{"id":759,"count":278,"description":"","link":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/","name":"Competencias profesionales","slug":"para-profesionales","taxonomy":"category","parent":8517,"meta":[],"acf":{"subtitulo":"","estilo_titulo":"","articulos_fijos":[{"ID":53160,"post_author":"255","post_date":"2022-12-07 09:52:54","post_date_gmt":"2022-12-07 08:52:54","post_content":"<!-- wp:paragraph -->\n<p>Cuando los responsables de <a href=\"https:\/\/www.emagister.com\/cursos-recursos-humanos-tematica-585.htm\"><strong>recursos humanos<\/strong><\/a> de una empresa eligen un determinado candidato, se fijan, m\u00e1s all\u00e1 de la experiencia, en sus <strong>competencias profesionales<\/strong>. Las competencias profesionales son aquellas habilidades que una persona debe adquirir para <strong>avanzar con \u00e9xito<\/strong> en un puesto de trabajo. Aunque algunas tienen componentes innatos, otras pueden trabajarse mediante cursos &nbsp;o <strong>formaciones de crecimiento personal<\/strong>.&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Para empezar hay que distinguir entre diversos tipos de competencias: estas aptitudes pueden ser <strong>b\u00e1sicas<\/strong>, <strong>t\u00e9cnicas<\/strong> o <strong>transversales<\/strong>. En este post, nos centraremos en las competencias profesionales b\u00e1sicas, es decir, aquellas que permiten el acceso a alguna formaci\u00f3n o trabajo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Son ejemplos de este tipo de conocimientos el<strong> uso de las TIC<\/strong>, el <strong>dominio de la lengua materna<\/strong> o las nociones de un<a href=\"https:\/\/www.emagister.com\/cursos-idiomas-tematica-460.htm\"> <strong>idioma extranjero<\/strong><\/a>. Si quieres conocer qu\u00e9 capacidades son esenciales en el mercado laboral de hoy, sigue leyendo y ponte manos a la obra. Y, sobre todo, no te olvides de consultar los cursos disponibles en Emagister para mejorar tu perfil.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:shortcode -->\n[my_courses q='' type='' segment='' category='' method='' size='' page='' sort='' show_more_link='' custom_class='' av_uid='av-20hlc8']\n<!-- \/wp:shortcode -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-cuales-son-las-competencias-profesionales-mas-importantes\"><strong>\u00bfCuales son las competencias profesionales m\u00e1s importantes?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>Cristina Shima<\/strong> (@cshima), consultora de captaci\u00f3n de talentos y recolocaci\u00f3n, distingue entre 11 habilidades esenciales. Son las siguientes:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><li><a href=\"https:\/\/www.emagister.com\/cursos-gestion-del-cambio-kwes-417.htm\"><strong>Gesti\u00f3n del cambio. <\/strong><\/a>En un mundo globalizado, las empresas necesitan profesionales flexibles que sean capaces de adaptarse a los cambios.<\/li><li><strong>Identificaci\u00f3n con la compa\u00f1\u00eda. <\/strong>El compromiso con la empresa es un valor importante ante la avalancha de curr\u00edculums que llegan diariamente.<\/li><li><a href=\"https:\/\/www.emagister.com\/herramientas-digitales-productividad-personal-profesional-cursos-2826439.htm\"><strong>Productividad Personal. <\/strong><\/a>El trabajador debe ser capaz de organizarse, gestionar el tiempo y mejorar su rendimiento.<\/li><li><a href=\"https:\/\/www.emagister.com\/como-obtener-acreditacion-competencias-tic-cursos-2819736.htm\"><strong>Dominio de las TIC.<\/strong><\/a> Internet y las redes sociales est\u00e1n presentes en la mayor\u00eda de puestos de trabajo. \u00a1Domina las TIC!<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-relaciones-sociales-kwes-3772.htm\"><strong>Relaciones Sociales. <\/strong><\/a>El trabajador tiene que mostrar predisposici\u00f3n para mantener relaciones sanas con los clientes y compa\u00f1eros.<\/li><li><strong>Identificaci\u00f3n de oportunidades y resoluci\u00f3n de problemas. <\/strong>Es la capacidad de identificar un conflicto y de abordarlo con una buena respuesta.<\/li><li><a href=\"https:\/\/www.emagister.com\/master\/optimizacion-procesos-tps-1179930.htm\"><strong>Optimizaci\u00f3n de recursos y mejora de resultados. <\/strong><\/a>Hace referencia al esfuerzo por realizar bien el trabajo y por superar el rendimiento obtenido.<\/li><li><a href=\"https:\/\/www.emagister.com\/blog\/brainstorming-generar-ideas-originales-grupo\/\"><strong>Desarrollo de ideas. <\/strong><\/a>Nada mejor que un empleado creativo e innovador para ayudar a avanzar la compa\u00f1\u00eda. \u00a1Marca la diferencia!<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-asertividad-kwes-4372.htm\"><strong>Comunicaci\u00f3n eficaz. <\/strong><\/a>Dominar el lenguaje es esencial para transmitir sensaci\u00f3n de empat\u00eda y asertividad.<\/li><li><strong>Comunicaci\u00f3n y cooperaci\u00f3n. <\/strong>\u00bfCu\u00e1ntas veces te han hablado de la importancia de trabajar en grupo? Tenla presente en cualquier labor profesional.<\/li><li><strong>Multidisciplinariedad. <\/strong>Todas las disciplinas est\u00e1n en contacto, por lo que se valoran especialmente los perfiles polivalentes y con intereses diversos.<\/li><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","post_title":"Qu\u00e9 son las competencias profesionales b\u00e1sicas y c\u00f3mo formarse para adquirirlas","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"que-son-las-competencias-profesionales-basicas-y-como-formarse-para-adqurirlas","to_ping":"","pinged":"","post_modified":"2022-12-07 09:52:55","post_modified_gmt":"2022-12-07 08:52:55","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=53160","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":19569,"post_author":"138","post_date":"2022-12-07 09:55:54","post_date_gmt":"2022-12-07 08:55:54","post_content":"<!-- wp:paragraph -->\n<p>Una de las competencias m\u00e1s solicitadas a nivel curricular para desempe\u00f1ar gran parte de los trabajos en la actualidad es el <strong><a href=\"https:\/\/www.emagister.com\/cursos-trabajo-equipo-kwes-5841.htm\">trabajo en equipo<\/a><\/strong>. Este t\u00e9rmino es algo confuso frente al otro t\u00e9rmino de trabajo en grupo que parece similar, pero que tiene una\u00a0filosof\u00eda totalmente diferente. Te explicamos las diferencias.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En t\u00e9rminos generales podemos afirmar que:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Trabajo en grupo<\/strong><em>:<\/em> es la realizaci\u00f3n de un trabajo mediante la suma de peque\u00f1as partes del mismo realizadas individualmente por una persona.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Trabajo en equipo<em>:<\/em> <\/strong>es la realizaci\u00f3n de todas y cada una de las partes de un trabajo por todas y cada una de las personas que est\u00e1n implicadas en \u00e9l mediante la colaboraci\u00f3n y el acuerdo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es por ello que el <strong>trabajo en equipo<\/strong> tiene unas caracter\u00edsticas diferenciales que le dan valor a esta competencia: la uni\u00f3n de forma armoniosa las actividades realizadas as\u00ed como las funciones de cada una de las personas del equipo de forma integral y mediante el acuerdo mutuo y la planificaci\u00f3n, desarrollo y resoluci\u00f3n de una trabajo conjunto con un objetivo com\u00fan perseguido en todo momento por el integrantes del grupo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s, el <strong>trabajo en equipo<\/strong> presenta algunas ventajas respecto al trabajo en grupo y al trabajo realizado de forma individual:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Calidad: cuando existen varias personas realizando un mismo trabajo, estas dan al equipo sus conocimientos y experiencias que acaban sumando para generar m\u00e1s contenido y sobre todo mejor contenido.<\/li><li>Valor: los trabajos realizados en equipo poseen m\u00e1s validez que los individuales puesto que el resultado final ha sido acordado y consensuado por todos los miembros.<\/li><li>Responsabilidad: cada uno de los miembros que forma parte del equipo tiene responsabilidad absoluta sobre el resultado final del trabajo. Es por ello que cada persona se siente responsable y motivada para que se realice lo mejor posible.<\/li><li>Sinergia grupal: cuando un grupo de personas lleva alg\u00fan tiempo realizando varios trabajos en equipo la calidad, el rendimiento y el resultado de los mismo es muy superior a la de un trabajo en grupo gracias a los conocidos como procesos de facilitaci\u00f3n social por las din\u00e1micas del equipo.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Pero no todo son ventajas y el<strong> trabajo en equipo<\/strong> en algunas ocasiones tambi\u00e9n presenta desventajas respecto a otro tipo de trabajos, como son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Tiempo: habitualmente el consenso y los acuerdos grupales necesitan de tiempo adicional.<\/li><li>Responsabilidad: los logros y los fracasos de un equipo est\u00e1n muy difuminados en el conjunto del equipo y en algunas ocasiones esto puede llevar a que haya miembros del equipo que no trabajen igual que el resto.<\/li><li>Conformismo: cuando se realizan trabajos en equipo pueden aparecer discusiones y algunos conflictos que a la larga pueden desencadenar actitudes pasivas y poco cr\u00edticas en algunos miembros que desean evitar estos problemas, pero finalizar el trabajo.<\/li><li>Liderazgo: el papel del l\u00edder en algunas ocasiones puede ser comprometido y generar algunos problemas que acaben atrasando el trabajo.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Del <strong>trabajo en equipo<\/strong> surgen varias competencias que hacen que cada uno de los miembros realice mejor su papel, como son:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Flexibilidad<strong>:<\/strong> es necesario no ser r\u00edgido en las opiniones e ideas que se expresen y aceptar las cr\u00edticas siempre y cuando estas sean constructivas y en busca de la mejora del resultado final.<\/li><li>Capacidad resolutiva: para facilitar los acuerdos finales en cada una de las fases en el trabajo en equipo.<\/li><li>Habilidades comunicativas: cualidad para saber expresar las ideas propuestas y dar a entender lo mejor\u00a0posible cu\u00e1les son los objetivos de cada idea y opini\u00f3n.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Es por ello que es necesario trabajar estas competencias que puedan ofrecer en nuestros puestos de trabajo la capacidad del <strong>trabajo en equipo<\/strong>.<\/p>\n<!-- \/wp:paragraph -->","post_title":"Competencias para el buen trabajo en equipo","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"competencias-para-el-buen-trabajo-en-equipo","to_ping":"","pinged":"","post_modified":"2022-12-07 09:56:10","post_modified_gmt":"2022-12-07 08:56:10","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=19569","menu_order":531,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":83253,"post_author":"282","post_date":"2019-03-29 11:40:59","post_date_gmt":"2019-03-29 10:40:59","post_content":"<p style=\"text-align: justify;\">\u00bfNo sabes como definir a una persona? \u00bfTe has preguntado cuales son esas competencias caracter\u00edsticas que engloban esa idea? Hoy te explicaremos algunas claves actitudinales para aplicar en tu entorno laboral.<!--more--><\/p>\n\n<h3 style=\"text-align: justify;\">\u00bfQu\u00e9 son las competencias?<\/h3>\n<p style=\"text-align: justify;\">En primer lugar, podemos entender a <strong>las competencias<\/strong> como las disposiciones motivacionales de las personas para plantearse metas y producir de forma persistente y esforzada la actividad necesaria para lograrlas. En este sentido, las competencias son esas&nbsp;capacidades que utilizamos para identificar los problemas o riesgos potenciales y desarrollar soluciones viables.<\/p>\n<p style=\"text-align: justify;\">Las competencias tambi\u00e9n se ven reflejadas en el repertorio conductual de las personas que poseen mayores habilidades o destrezas espec\u00edficas, verbales, motoras o de soluci\u00f3n de problemas.&nbsp;La competencia puede entenderse en t\u00e9rminos de rasgos de personalidad, ya que representan patrones organizados de funcionamiento psicosocial, es decir, de funcionamiento cognitivo, emocional y comportamental.&nbsp;De este modo, para lograr que alguien alcance las competencias y destrezas que se necesitan no basta con sugerir consejos, todo depender\u00e1 de la madurez de esa persona, de su formaci\u00f3n integral y la autonom\u00eda que posea para desarrollar satisfactoriamente estos.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, si consideramos que la vida de las personas transcurre entre tres \u00e1mbitos principales; las relaciones personales (familiares y de pareja), el trabajo y el ocio, y si asumimos que, inevitablemente, todas ellas tienen aspectos positivos y negativos, podremos asimilar m\u00e1s f\u00e1cilmente la idea descrita de competencia a cualquiera de estos tres campos centrales.<\/p>\n<p style=\"text-align: justify;\">Aunque todos tenemos capacidades, es necesario determinar cuales nos prestan valor como como profesionales, cu\u00e1les nos ayudan a conocernos mejor y cu\u00e1les nos ayudan a destacar, ampliando as\u00ed nuestros horizontes profesionales.<img class=\"alignright wp-image-82033 \" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/03\/codex-1-300x200.png\" alt=\"\" width=\"260\" height=\"173\"><\/p>\n<p style=\"text-align: justify;\">En definitiva, la idoneidad de un candidato en el \u00e1mbito laboral se define no solo por los conocimientos que tenga este, sino por la&nbsp;<strong>aptitud&nbsp;<\/strong>que posea.<\/p>\n\n<h3 style=\"text-align: justify;\">\u00bfA qu\u00e9 nos referimos exactamente por aptitud?<\/h3>\n<p style=\"text-align: justify;\">La aptitud, en este caso, viene marcada por las competencias, y su definici\u00f3n depende enteramente de ellas. Debemos entender que las competencias se dividen distintos grupos: b\u00e1sicas, t\u00e9cnicas y profesionales o transversales.<\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li style=\"text-align: justify;\"><strong>Competencias b\u00e1sicas.&nbsp;<\/strong>Son aquellas que te permiten ser apto para un puesto determinado, ya sea porque las has obtenidos en tus estudios, o bien, porque dominas una cualidad espec\u00edfica necesaria, como un idioma.<\/li>\n \t<li style=\"text-align: justify;\"><strong>Competencias t\u00e9cnicas.&nbsp;<\/strong>Son los conocimientos&nbsp;adquiridos despu\u00e9s de haber realizado una formaci\u00f3n espec\u00edfica, asociadas con la experiencia y la puesta en pr\u00e1ctica de esos conocimientos.<\/li>\n \t<li style=\"text-align: justify;\"><strong>Competencias profesionales\/transversales.&nbsp;<\/strong>Son aquellas habilidades y aptitudes que ayudan a desarrollar un trabajo de forma exitosa. Sirven para cualquier profesi\u00f3n y se desarrollan de forma personal, es decir que no se aprenden, sino que se ejercitan y se adquieren. Son las m\u00e1s valoradas en el entorno laboral y pueden categorizarse en 10 esferas:\n<ul>\n \t<li>&nbsp;<strong>Proactividad<\/strong>. Mide tu capacidad para tomar decisiones y mostrar iniciativa, sin que nadie est\u00e9 encima de ti. Implica poder asumir responsabilidades con autonom\u00eda y compromiso.<\/li>\n \t<li><strong>Trabajo en equipo<\/strong>. Algo esencial en todo trabajo. Es necesario para mantener una buena organizaci\u00f3n y generar un buen clima laboral.<\/li>\n \t<li><strong>Adaptaci\u00f3n. <\/strong>Mide tu capacidad de&nbsp;tolerancia a los cambios y la rapidez con la que logras adaptar a ellos.<\/li>\n \t<li><strong>Motivaci\u00f3n.&nbsp;<\/strong>La cualidad m\u00e1s buscada. Implica entusiasmo y ganas de aprender y superarse. Dice mucho sobre la personalidad del candidato.<\/li>\n \t<li><strong>Lealtad.<\/strong>&nbsp;El compromiso que asumes con la cultura de empresa y los objetivos. Esto facilitar\u00e1 el escalar puestos.<\/li>\n \t<li><strong>Resultados. <\/strong>No pienses m\u00e1s all\u00e1 de tus horizontes,&nbsp;esfu\u00e9rzate por conseguir resultados reales y concretos en tu \u00e1rea. Las metas son lo principal.<\/li>\n \t<li><strong>Creatividad.&nbsp;<\/strong>Una competencia muy solicitada. Las personas creativas son esenciales en cualquier puesto de trabajo, ya que ofrece&nbsp;soluciones alternativas, salt\u00e1ndose los est\u00e1ndares y dando ideas innovadoras. Es saber el lado oculto de las cosas.<\/li>\n \t<li><strong>Capacidad de di\u00e1logo.&nbsp;<\/strong>Esta actitud te acercar\u00e1 a una posici\u00f3n de liderazgo, deber\u00e1s ser&nbsp;capaz de enfrentarte a situaciones tensas con car\u00e1cter y siendo resolutivo.<\/li>\n \t<li><strong>Comunicaci\u00f3n.&nbsp;<\/strong>Una comunicaci\u00f3n fluida es imprescindible, supone la base de cualquier negociaci\u00f3n o reuni\u00f3n.<\/li>\n \t<li><strong>Ser organizado, respetuoso y puntual.<\/strong> Tres&nbsp;caracter\u00edsticas que se fusionan en una \u00fanica idea y que da cuenta de muchos aspectos que se consideran b\u00e1sicos en un puesto de trabajo. Tienen que ver con la personalidad del candidato.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Fuente: Centro de Formaci\u00f3n Codex<\/p>","post_title":"\u00bfCu\u00e1les son las actitudes y competencias clave en el entorno laboral?","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"cuales-son-las-actitudes-y-competencias-clave-en-el-entorno-laboral","to_ping":"","pinged":"","post_modified":"2021-05-03 12:57:29","post_modified_gmt":"2021-05-03 10:57:29","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=83253","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":30584,"post_author":"160","post_date":"2022-12-07 10:30:07","post_date_gmt":"2022-12-07 09:30:07","post_content":"<!-- wp:paragraph -->\n<p>Las <strong>competencias profesionales<\/strong> son todas aquellas capacidades de que disponemos para poner en pr\u00e1ctica nuestros conocimientos, habilidades y valores en el entorno laboral. Ahora que los procesos de selecci\u00f3n son cada vez m\u00e1s completos y especificados, las competencias profesionales son unas cualidades que precisamente en los \u00faltimos a\u00f1os han cobrado una especial importancia en los procesos de selecci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>As\u00ed pues, la formaci\u00f3n en competencias es un factor clave para el desarrollo integral de los estudiantes. En el <strong>World Economic Forum<\/strong>, por ejemplo, las competencias fueron identificadas como necesarias para una formaci\u00f3n completa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El desarrollo de \u00e9stas es una parte fundamental del modelo educativo de iFP, caracterizado tambi\u00e9n por su <strong>vinculaci\u00f3n con el mundo empresarial<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los programas que conforman los cursos de <a href=\"https:\/\/www.emagister.com\/ifp-innovacion-formacion-profesional-grupo-planeta-cursos-145826-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\">iFP<\/a> est\u00e1n basados en la idea que con los cambios tecnol\u00f3gicos y sociales de los \u00faltimos tiempos no se pueden seguir ense\u00f1ando los mismos conceptos de la misma manera. <strong>Ya no es suficiente acumular conocimiento<\/strong>. Hoy es m\u00e1s importante que nunca ofrecer metodolog\u00edas para disponer de los mejores recursos en los contenidos necesarios para cada momento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>De esta manera, las competencias profesionales son indispensables en cualquier sector empresarial y son un aspecto decisivo en la preparaci\u00f3n de los alumnos para el mundo profesional. Con el&nbsp;<strong>modelo educativo de iFP<\/strong> combinan casos reales de empresas, formaci\u00f3n de profesores, pr\u00e1ctica en el aula, contenidos en el campus virtual, y dinamizaci\u00f3n y seguimiento. Toda esta metodolog\u00eda se divide&nbsp;en tres ejes b\u00e1sicos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En primer lugar, resulta b\u00e1sico el <strong>dominio ling\u00fc\u00edstico<\/strong>. El ingl\u00e9s sigue siendo el idioma m\u00e1s solicitado y es exigido en nueve de cada diez ofertas donde reclaman una segunda lengua. Adem\u00e1s, es importante se\u00f1alar que el ingl\u00e9s es vital para aplicar a altos cargos, as\u00ed como a puestos en niveles medios. De acuerdo con el VI Informe Adecco e Infoempleo sobre Empleabilidad e Idiomas publicado a finales del a\u00f1o 2015, el 32,8% de las ofertas de empleo que se publican en nuestro pa\u00eds especifica la necesidad de conocer, como m\u00ednimo, una lengua extranjera, que acostumbra a ser el ingl\u00e9s. En <a href=\"https:\/\/www.emagister.com\/ifp-innovacion-formacion-profesional-grupo-planeta-cursos-145826-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\">iFP<\/a> son muy conscientes de la importancia del ingl\u00e9s, y por esto el centro complementa su formaci\u00f3n con un curso online de m\u00e1s de 1.000 horas y 26 sesiones presenciales de refuerzo al a\u00f1o.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En segundo lugar, en el mundo actual, es m\u00e1s necesario que nunca un buen <strong>dominio de la inform\u00e1tica y las nuevas tecnolog\u00edas<\/strong>. En iFP trabajan para mejorar las competencias digitales de sus&nbsp;alumnos y su&nbsp;oferta formativa incluye la opci\u00f3n de examinarse para la certificaci\u00f3n MOS. La <strong>certificaci\u00f3n Microsoft Office Specialist<\/strong> es una titulaci\u00f3n que reconoce las habilidades en las aplicaciones de Microsoft Office (Word, Excel, PowerPoint, Access y Outlook). El MOS permite obtener tres grados de habilidad en relaci\u00f3n al paquete Office: certificaci\u00f3n b\u00e1sica, certificaci\u00f3n experto y certificaci\u00f3n maestro, de menor a mayor grado de conocimiento respectivamente. Este t\u00edtulo permite construir un perfil laboral m\u00e1s completo.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En tercer lugar, desarrollan 1 competencia profesional por mes, completando las <strong>10 competencias<\/strong> a lo largo de los 3 primeros semestres del ciclo formativo. Han identificado diez competencias clave para el mercado laboral de acuerdo a los criterios de la UE y el MECD: trabajo en equipo; comunicaci\u00f3n; gesti\u00f3n del tiempo; iniciativa y creatividad; decisiones efectivas; inteligencia emocional; negociaci\u00f3n; escucha y empat\u00eda; networking y marca personal.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"right\",\"id\":24232,\"linkDestination\":\"custom\"} -->\n<figure class=\"wp-block-image alignright\"><a href=\"https:\/\/www.emagister.com\/ifp-innovacion-formacion-profesional-grupo-planeta-cursos-145826-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ifp_planeta_vertical.png\" alt=\"ifp_planeta_vertical\" class=\"wp-image-24232\"\/><\/a><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>La primera sesi\u00f3n de competencias fue sobre el <strong>trabajo en equipo<\/strong>. Dicho en otras palabras, la disposici\u00f3n y habilidad para colaborar de manera coordinada en la tarea realizada conjuntamente por un equipo de personas para conseguir el objetivo propuesto. Esta habilidad es muy importante porque un grupo unido y que sepa trabajar en equipo generar\u00e1 un rendimiento positivo para la empresa. El trabajar en equipo resulta provechoso no solo para una persona sino para todo el equipo involucrado. Cuando se trabaja en equipo, los esfuerzos de los miembros se potencian, disminuyendo el tiempo de acci\u00f3n y aumentando la eficacia de los resultados.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En s\u00edntesis, con el trabajo en equipo se fomenta la creatividad y la innovaci\u00f3n, porque cuando todos los miembros saben qu\u00e9 hacer y conocen su impacto en la empresa, se producen nuevas ideas e innovaciones que permiten el crecimiento.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4 id=\"h-fuente-blog-ifp-grupo-planeta\">Fuente: Blog iFP - Grupo Planeta<\/h4>\n<!-- \/wp:heading -->","post_title":"Competencias profesionales, vitales en los procesos de selecci\u00f3n","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"competencias-profesionales-vitales-los-procesos-seleccion","to_ping":"","pinged":"","post_modified":"2022-12-07 10:30:08","post_modified_gmt":"2022-12-07 09:30:08","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=30584","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"1","filter":"raw"},{"ID":48050,"post_author":"255","post_date":"2022-12-07 10:27:12","post_date_gmt":"2022-12-07 09:27:12","post_content":"<!-- wp:paragraph -->\n<p>La<strong> tecnolog\u00eda<\/strong> domina muchos \u00e1mbitos de nuestra vida. Y el trabajo no es una excepci\u00f3n. A d\u00eda de hoy, varias empresas se dedican a la fabricaci\u00f3n, venta y creaci\u00f3n de nuevas tecnolog\u00edas en el<a href=\"https:\/\/www.emagister.com\/cursos-informatica-tematica-2.htm\"><strong> sector IT<\/strong> <\/a>(Information Technologies). Por lo tanto, trabajan con un sistema operativo propio y con equipos espec\u00edficos. Pero la cosa no se acaba aqu\u00ed. Estas empresas creadoras venden sus servicios a otras entidades para contribuir a su desarrollo. En consecuencia, los empleados que entran en contacto con estas tecnolog\u00edas deben tener conocimientos especializados para llevar a cabo sus tareas. \u00bfQu\u00e9 papel juega una <strong>certificado IT<\/strong> en todo esto? \u00bfPara qu\u00e9 nos puede servir? Te lo contamos en este post.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Las certificaciones IT <strong>avalan el conocimiento<\/strong> que tiene un individuo para manejar una determinada tecnolog\u00eda. No se trata de un \u00fanico documento, sino que hay diferentes modalidades en funci\u00f3n de la habilidad que se acredite. Hay que tener en cuenta que los profesionales de la tecnolog\u00eda reciben una formaci\u00f3n gen\u00e9rica <a href=\"https:\/\/www.emagister.com\/universidades\/carreras-universitarias-informatica-tematica-2.htm\">durante la carrera <\/a>universitaria. Sin embargo, la pr\u00e1ctica profesional les suele plantear nuevos retos. Como sabes, el mundo de la tecnolog\u00eda es muy din\u00e1mico y los cambios se producen a gran velocidad. En este sentido, los expertos del sector consideran que los certificados IT mejoran el perfil profesional porque aportan<strong> prestigio, oportunidades y seguridad. <\/strong>Adem\u00e1s, se trata de un campo en crecimiento, por lo que es una&nbsp;<a href=\"https:\/\/www.emagister.com\/blog\/profesiones\/informatica-telecomunicacion\/\">garant\u00eda de trabajo <\/a>casi segura.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-que-tipos-de-certificado-it-existen\"><strong>\u00bfQu\u00e9 tipos de certificado IT existen?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Como ya hemos dicho, hay diversas empresas que ofrecen certificaciones en alta tecnolog\u00eda. Estas son algunas de las m\u00e1s destacadas:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><a href=\"https:\/\/www.emagister.com.co\/cursos-cisco-tematica-78.htm\"><strong>Cisco.<\/strong> <\/a>Esta empresa con sede en California trabaja en \u00e1mbitos muy diversos: conexi\u00f3n de redes inform\u00e1ticas, dispositivos de seguridad, productos de telefon\u00eda IP, software de gesti\u00f3n de red, etc.<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-certificaciones-microsoft-kwes-995.htm\"><strong>Microsoft.<\/strong>\u00a0<\/a>Un gigante. Es una multinacional con sede en Washington, dedicada al hardware y el software.<\/li><li><strong><a href=\"https:\/\/www.emagister.com\/certificado-sun-tps-1551996.htm\">Sun. <\/a><\/strong>Sun fue una empresa inform\u00e1tica que se dedicaba a vender estaciones de trabajo, software, servidores y otros servicios. Oracle Corporation la adquiri\u00f3 en 2010.<\/li><li><strong><a href=\"https:\/\/www.emagister.com\/cursos-sap-kwes-785.htm\">SAP.<\/a><\/strong>\u00a0SAP es una multinacional alemana que trabaja en el dise\u00f1o de productos inform\u00e1ticos. Su especialidad es la gesti\u00f3n empresarial, tanto en organizaciones privadas como en organismos p\u00fablicos.<\/li><li><strong>Adobe. <\/strong>Se trata de una empresa de software con sede en California. Destaca por sus programas de edici\u00f3n de v\u00eddeos, im\u00e1genes y p\u00e1ginas web como <a href=\"https:\/\/www.emagister.com\/cursos-photoshop-tematica-141.htm\">Photoshop<\/a>, <a href=\"https:\/\/www.emagister.com\/cursos-adobe-premiere-kwes-2994.htm\">Adobe Premiere<\/a>, <a href=\"https:\/\/www.emagister.com\/cursos-indesign-kwes-30375.htm\">InDesign<\/a>, <a href=\"https:\/\/www.emagister.com\/cursos-illustrator-kwes-459.htm\">Illustrator <\/a>y <a href=\"https:\/\/www.emagister.com\/cursos-dreamweaver-tematica-258.htm\">Dreamweaver<\/a>.<\/li><li><strong>Google. <\/strong>Otro gigante del mundo de las tecnolog\u00edas. Est\u00e1 especializado en servicios de Internet, software y dispositivos electr\u00f3nicos.<\/li><li><strong><a href=\"https:\/\/www.emagister.com\/cursos-red-hat-kwes-3539.htm\">Red Hat. <\/a><\/strong>Es la compa\u00f1\u00eda responsable de la creaci\u00f3n y \u00a0el mantenimiento del sistema operativo GNU\/Linux. Trabaja para la implantaci\u00f3n del software libre.<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-itil-kwes-1000001183.htm\"><strong>ITIL. <\/strong><\/a>Esta sigla en ingl\u00e9s responde a la expresi\u00f3n<em>\u00a0Biblioteca de Infraestructura de Tecnolog\u00edas de Informaci\u00f3n<\/em>. Se aplica a un conjunto de buenas pr\u00e1cticas utilizadas en la gesti\u00f3n de servicios IT.<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-scrum-kwes-1000006292.htm\"><strong>Scrum.<\/strong> <\/a>Es un proceso de metodolog\u00eda \u00e1gil que se usa para minimizar los riesgos durante la realizaci\u00f3n de un proyecto. Trabaja de manera colaborativa.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>\u00bfY t\u00fa? \u00bfTodav\u00eda no has encontrado el certificado que necesitas? Inf\u00f3rmate sobre<a href=\"https:\/\/www.emagister.com\/cursos-informatica-tematica-2.htm\"> la oferta disponible<\/a> y ponte manos a la obra. \u00a1Marcar\u00e1s la diferencia!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fuente:<\/strong><a href=\"https:\/\/www.emagister.com\/capacity-cursos-77287-centrodetalles.htm\"><strong> Capacity Information Technology Academy<\/strong><\/a><\/p>\n<!-- \/wp:paragraph -->","post_title":"\u00bfQu\u00e9 es un certificado IT? \u00bfCu\u00e1les puedo obtener?","post_excerpt":"Las certificaciones IT avalan el conocimiento que tiene un individuo para manejar una determinada tecnolog\u00eda. \u00bfCu\u00e1les son las m\u00e1s importantes? \u00bfPara qu\u00e9 nos pueden servir?","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"que-es-un-certificado-it-cuales-puedo-obtener","to_ping":"","pinged":"","post_modified":"2022-12-07 10:27:41","post_modified_gmt":"2022-12-07 09:27:41","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=48050","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":52565,"post_author":"255","post_date":"2022-12-07 10:33:04","post_date_gmt":"2022-12-07 09:33:04","post_content":"<!-- wp:paragraph -->\n<p>La <strong>formaci\u00f3n<\/strong> que los profesionales de Recursos Humanos buscan en un <a href=\"https:\/\/www.emagister.com\/blog\/empleo\/cv\/\"><strong>curr\u00edculum vitae<\/strong> <\/a>no se limita a un ciclo de FP o a una carrera universitaria. A d\u00eda de hoy, son cada vez m\u00e1s importantes las <strong>certificaciones profesionales<\/strong>, unos documentos que acreditan determinadas habilidades para trabajar en un sector concreto. La certificaci\u00f3n profesional puede prevenir de \u00e1mbitos muy diversos, desde la direcci\u00f3n de proyectos hasta la gesti\u00f3n de aplicaciones de Google. Sea como sea, estos avales son el complemento perfecto a nuestra experiencia profesional y laboral. De hecho, se trata de credenciales muy buscadas que otorgan un valor a\u00f1adido a los candidatos y demuestran a la empresa que esa persona est\u00e1 al d\u00eda.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si te planteas obtener una certificaci\u00f3n profesional, ten en cuenta que hay academias especializadas en este tipo de cursos.&nbsp; Es el caso de centros como <a href=\"https:\/\/www.emagister.com\/ceolevel-cursos-123311-centrodetalles.htm\"><strong>Ceolevel<\/strong><\/a>, que combina la modalidad <strong>presencial<\/strong> con las formaciones <strong>online<\/strong>. \u00bfQuieres mejorar tu empleabilidad sin tener que estudiar durante mucho tiempo? \u00bfTe gustar\u00eda acceder a puestos de m\u00e1s responsabilidad en el trabajo? Pues inf\u00f3rmate y empieza a formarte para obtener tu certificado. Puede ser la manera de avanzar hacia una nueva etapa profesional. \u00a1T\u00fa decides!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-los-5-beneficios-que-aporta-una-certificacion-profesional\"><strong>Los 5 beneficios que aporta una certificaci\u00f3n profesional<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><li><strong>La diferenciaci\u00f3n.<\/strong> El hecho de obtener una certificaci\u00f3n muy demandada y de prestigio internacional permite que marquemos la diferencia respecto a otros perfiles. As\u00ed pues, tendremos mayor visibilidad en los procesos de selecci\u00f3n de Recursos Humanos. \u00a1No te olvides de incluir las certificaciones en tu curr\u00edculum!<\/li><li><strong>Las herramientas.<\/strong> Los cursos ofrecen un set de recursos, nuevos o m\u00e1s tradicionales,&nbsp; que podr\u00e1s poner en pr\u00e1ctica en tu d\u00eda a d\u00eda. Esto incluye tanto los elementos t\u00e9cnicos como los te\u00f3ricos. En resumen, es una buena manera de reciclarse sin pasar por una formaci\u00f3n larga.<\/li><li><strong>La posibilidad de mejorar.<\/strong> Si ya tienes trabajo, los certificados te dar\u00e1n opci\u00f3n a escalar posiciones dentro de la empresa. Y, si no tienes, podr\u00e1s acceder a empleos mejor valorados.<\/li><li><strong>El progreso.<\/strong> De cara a tus superiores y compa\u00f1eros, estos cursos demuestran que tienes ganas de aprender, innovar y avanzar. A todas las empresas les gusta tener profesionales din\u00e1micos con ganas de estar al d\u00eda.<\/li><li><strong>La evaluaci\u00f3n.<\/strong> Tus conocimientos te permitir\u00e1n evaluar mejor las capacidades del equipo y tomar medidas para potenciarlas.<\/li><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-cuales-son-las-certificaciones-con-mas-demanda-actualmente\"><strong>\u00bfCu\u00e1les son las certificaciones con m\u00e1s demanda actualmente?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Los sectores emergentes, especialmente el mundo de la tecnolog\u00eda, generan nuevas figuras en el \u00e1mbito empresarial. En consecuencia, est\u00e1 claro que estos perfiles deben formarse con los certificados correspondientes. A d\u00eda de hoy, estas son algunas de las acreditaciones m\u00e1s demandas:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><a href=\"https:\/\/www.emagister.com\/cursos-pmp-kwes-36266.htm\"><strong>PMP.<\/strong><\/a> La certificaci\u00f3n en Project Management Profesional es la que tiene m\u00e1s demanda actualmente. Sirve para acreditar conocimientos en gesti\u00f3n de proyectos, por lo que la persona que lo obtenga podr\u00e1 trabajar como director de un proyecto. Este t\u00edtulo cultiva capacidades como el liderazgo o el trabajo en equipo.<\/li><li><a href=\"https:\/\/www.emagister.com\/i\/cursos-sap-kwes-785.htm\"><strong>SAP.&nbsp; <\/strong><\/a>El SAP es uno de los principales softwares que utilizan las empresas espa\u00f1olas para organizar y gestionar sus recursos. Se alimenta de los datos que se cargan y procesan dentro de un entorno. Posteriormente, el sistema se encarga de producir con esos datos informaci\u00f3n \u00fatil para la toma de decisiones.<\/li><li><a href=\"https:\/\/www.emagister.com\/cursos-six-sigma-kwes-6713.htm\"><strong>Six Sigma.<\/strong><\/a> Se trata de una metodolog\u00eda de mejora de procesos centrada en la reducci\u00f3n de la variabilidad. En concreto, busca reducir o eliminar los defectos y fallos en la entrega de un producto o servicio al cliente. En este \u00e1mbito, se entienden los defectos como cualquier evento en el que un servicio no logra cumplir los requisitos.<\/li><li><strong><a href=\"https:\/\/www.emagister.com\/i\/cursos-google-kwes-10000007769.htm\">Google<\/a><\/strong>. La certificaciones demuestran un nivel avanzado en el uso de determinados productos de Google. Eso s\u00ed, hay que distinguir entre diversas certificaciones seg\u00fan el producto. Las m\u00e1s conocidas son las de <strong><a href=\"https:\/\/www.emagister.com\/cursos-google-analytics-kwes-1000006225.htm\">Google Analytics<\/a>, <a href=\"https:\/\/www.emagister.com\/i\/cursos-adwords-kwes-1000000704.htm\">Google AdWords<\/a>,<a href=\"https:\/\/www.emagister.com\/i\/cursos-google-cloud-kwes-42272020040449535065545267101833.htm\"> Google Cloud<\/a><\/strong> y Sitios web para m\u00f3viles.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p><strong>Fuente: Ceolevel<\/strong><\/p>\n<!-- \/wp:paragraph -->","post_title":"\u00bfPara qu\u00e9 sirve una certificaci\u00f3n profesional en PMP, SAP, Google o Six Sigma?","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"certificacion-profesional-pmp-sap-google-sigma","to_ping":"","pinged":"","post_modified":"2022-12-07 10:33:05","post_modified_gmt":"2022-12-07 09:33:05","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=52565","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"2","filter":"raw"}],"descripcion_lo_ultimo":"","sidebar":"","enlaces":false,"mostrar_faldon":"1","texto_faldon":"Encuentra en Emagister tu curso ideal","link_faldon":"https:\/\/www.emagister.com","link_texto_faldon":"Buscar cursos","hreflang":[{"url":""}],"fecha":"no"},"z_taxonomy_image_url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/2-encontrar-empleo.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Competencias profesionales - Blog Emagister<\/title>\n<meta name=\"description\" content=\"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competencias profesionales archivos\" \/>\n<meta property=\"og:description\" content=\"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/formacion-continua\\\/para-profesionales\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/formacion-continua\\\/para-profesionales\\\/\",\"name\":\"Competencias profesionales - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"description\":\"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/formacion-continua\\\/para-profesionales\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/formacion-continua\\\/para-profesionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n continua\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/formacion-continua\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Competencias profesionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Competencias profesionales - Blog Emagister","description":"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/","og_locale":"es_ES","og_type":"article","og_title":"Competencias profesionales archivos","og_description":"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.","og_url":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/","og_site_name":"Blog Emagister","twitter_card":"summary_large_image","twitter_site":"@emagister","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/","url":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/","name":"Competencias profesionales - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"description":"Descubre cu\u00e1les son las competencias profesionales b\u00e1sicas y c\u00f3mo adquirirlas a trav\u00e9s de la formaci\u00f3n continua y certificaciones profesionales.","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/formacion-continua\/para-profesionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n continua","item":"https:\/\/www.emagister.com\/blog\/formacion-continua\/"},{"@type":"ListItem","position":3,"name":"Competencias profesionales"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories\/759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories\/8517"}],"wp:post_type":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts?categories=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}