{"id":8405,"count":28,"description":"","link":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/","name":"Oposiciones Educaci\u00f3n","slug":"maestros-profesores-educacion","taxonomy":"category","parent":8333,"meta":[],"acf":{"subtitulo":"","estilo_titulo":"","articulos_fijos":[{"ID":28003,"post_author":"160","post_date":"2022-11-07 12:53:58","post_date_gmt":"2022-11-07 11:53:58","post_content":"<!-- wp:paragraph -->\n<p>Los <strong>centros de preparaci\u00f3n de oposiciones<\/strong> comienzan estos d\u00edas su formaci\u00f3n de cara al examen de maestros y profesores del a\u00f1o que viene. Normalmente, la <strong>convocatoria<\/strong> se publica en el mes de <strong>abril<\/strong> y el <strong>examen<\/strong> se lleva a cabo la <strong>segunda quincena del mes de junio<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p> Si el opositor aprueba todas las pruebas, comenzar\u00e1 a trabajar en septiembre como funcionario.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Los <a href=\"https:\/\/www.emagister.com\/masterd-oposiciones-cursos-535-centrodetalles.htm\" target=\"_blank\" rel=\"noreferrer noopener\">ex\u00e1menes de las oposiciones de educaci\u00f3n<\/a> son convocados por concurso-oposici\u00f3n<\/strong>, lo que significa que no solo contar\u00e1 el examen, sino que tambi\u00e9n se valorar\u00e1n los m\u00e9ritos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Estos ex\u00e1menes constan de <strong>dos partes, ambas de car\u00e1cter eliminatorio<\/strong>. El <strong>primer examen<\/strong> consta de un caso pr\u00e1ctico, que el opositor, seg\u00fan la especialidad, deber\u00e1 resolver, y de un tema a desarrollar. Los maestros cuentan con <strong>25 temas<\/strong> en su temario, mientras que los profesores cuentan con <strong>70 temas<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La&nbsp;<strong>segunda parte<\/strong> constar\u00e1 de la&nbsp;<strong>exposici\u00f3n y defensa oral de una programaci\u00f3n did\u00e1ctica<\/strong> y de una unidad did\u00e1ctica.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"right\",\"id\":23642,\"linkDestination\":\"custom\"} -->\n<figure class=\"wp-block-image alignright\"><a href=\"https:\/\/www.emagister.com\/masterd-oposiciones-cursos-535-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/03\/s1.png\" alt=\"MasterD\" class=\"wp-image-23642\"\/><\/a><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Despu\u00e9s de realizar los ex\u00e1menes y de haberlos aprobado, el opositor pasar\u00e1 a <strong>la fase de concurso donde<\/strong> <strong>se valorar\u00e1n m\u00e9ritos<\/strong> como la experiencia profesional, su formaci\u00f3n, sus titulaciones, etc. En septiembre y coincidiendo con el curso escolar, el opositor que haya conseguida una plaza <strong>comenzar\u00e1 a trabajar<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Antes de poder optar a una plaza como profesor o maestro, el opositor deber\u00e1 reunir los requisitos exigidos para cada una de las oposiciones. Para las <strong>plazas de infantil y primaria<\/strong> se debe ser <strong>maestro<\/strong> (graduado o diplomado en magisterio), en el caso de <strong>profesor de secundaria<\/strong> se debe ser <strong>licenciado o graduado y, adem\u00e1s, tener el&nbsp;m\u00e1ster&nbsp;de formaci\u00f3n del profesorado<\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Los centros especializados en las oposiciones de educaci\u00f3n ofrecen al alumno una <strong>metodolog\u00eda que se centra en todas las partes espec\u00edficas de la oposici\u00f3n<\/strong>, poniendo a disposici\u00f3n del alumno un itinerario did\u00e1ctico completo y organizado seg\u00fan las diferentes pruebas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4 id=\"h-fuente-blog-masterd\">Fuente: <strong>Blog MasterD<\/strong><\/h4>\n<!-- \/wp:heading -->","post_title":"Conseguir empleo de maestro y profesor","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"conseguir-empleo-maestro-profesor","to_ping":"","pinged":"","post_modified":"2022-11-07 12:54:00","post_modified_gmt":"2022-11-07 11:54:00","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=28003","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":36825,"post_author":"160","post_date":"2022-06-10 10:35:00","post_date_gmt":"2022-06-10 08:35:00","post_content":"<!-- wp:paragraph -->\n<p>\u00bfTe gustar\u00eda trabajar con ni\u00f1os?\u00a0\u00bfQuieres dedicarte profesionalmente a la infancia?\u00a0Si es as\u00ed, lo que t\u00fa <strong><a href=\"https:\/\/www.emagister.com\/i\/cursos-educacion-infantil-tematica-776.htm\">quieres ser es\u00a0educador\/a infantil<\/a><\/strong>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Para conseguirlo tendr\u00e1s que cursar el <strong>Ciclo Formativo de&nbsp;Grado Superior&nbsp;en Educaci\u00f3n Infantil<\/strong>. Podr\u00e1s realizarlo de forma&nbsp;presencial en un IES oficial o a distancia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si tu mejor opci\u00f3n es <strong>sac\u00e1rtelo a distancia, deber\u00e1s saber&nbsp; que el&nbsp; t\u00edtulo oficial lo podr\u00e1s obtener&nbsp;mediante la realizaci\u00f3n de pruebas libres&nbsp;convocadas por las diferentes administraciones educativas de las comunidades aut\u00f3nomas<\/strong>. Est\u00e1s pruebas o ex\u00e1menes se realizar\u00e1n en institutos p\u00fablicos de FP de cada una de las comunidades convocantes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-una-vez-obtenido-el-titulo-de-educador-infantil-que-puedes-hacer\">Una vez obtenido el t\u00edtulo de&nbsp;Educador infantil, \u00bfqu\u00e9 puedes hacer?.<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong>1. Trabajar.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dedicarte&nbsp;profesionalmente al sector de la educaci\u00f3n formal y no formal y en el sector de los servicios sociales de atenci\u00f3n a la infancia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>&nbsp;&nbsp;2. Seguir estudiando.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li><a href=\"https:\/\/www.emagister.com\/homologados-educacion-infantil-tps-562746.htm\"><strong>Cursos homologados de educaci\u00f3n infantil<\/strong><\/a><\/li><li style=\"text-align: justify;\">Cursos de especializaci\u00f3n profesional, como por ejemplo, Experto en direcci\u00f3n y gesti\u00f3n de escuelas infantiles.<\/li><li style=\"text-align: justify;\">Realizar otro ciclo de Formaci\u00f3n Profesional de Grado Superior.<\/li><li style=\"text-align: justify;\">Ense\u00f1anzas Universitarias.<\/li><li style=\"text-align: justify;\"><strong>Aprobar una oposici\u00f3n de T\u00e9cnico educador de escuelas infantiles<\/strong>.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-salidas-profesionales-para-el-la-tecnico-educador-a-infantil\">Salidas profesionales para el\/la t\u00e9cnico educador\/a infantil<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>\u00bfCu\u00e1les son las salidas profesionales?.&nbsp;\u00bfEn qu\u00e9 sector de la educaci\u00f3n vamos a poder dedicarnos profesionalmente?\u2026Todo educador infantil podr\u00e1 dedicarse profesionalmente en el sector de la&nbsp;educaci\u00f3n formal y no formal y en el sector de los servicios sociales de atenci\u00f3n a la infancia. En concreto sus&nbsp;salidas profesionales ser\u00e1n:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Educador o educadora infantil en primer ciclo de educaci\u00f3n infantil.<\/li><li>Educador o educadora en instituciones y\/o en programas espec\u00edficos de trabajo con menores (0-6 a\u00f1os) en situaci\u00f3n de riesgo social, o en medios de apoyo familiar.<\/li><li>Educador o educadora en programas o actividades de ocio y tiempo libre infantil con menores de 0 a 6 a\u00f1os: ludotecas, casas de cultura, bibliotecas, centros educativos, centros de ocio, granjas escuela, etc.<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-estudiar-educacion-infantil\">Estudiar educaci\u00f3n infantil<\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Desde <strong>MasterD pueden asesorarte para que puedas alcanzar tu meta y conseguir un puesto de educador\/a infantil <\/strong>en guarder\u00edas p\u00fablicas y privadas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"right\",\"id\":23642,\"linkDestination\":\"custom\"} -->\n<div class=\"wp-block-image\"><figure class=\"alignright\"><a href=\"https:\/\/www.emagister.com\/masterd-oposiciones-cursos-535-centrodetalles.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><img src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/03\/s1.png\" alt=\"MasterD\" class=\"wp-image-23642\"\/><\/a><\/figure><\/div>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p><strong><\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":4} -->\n<h4 id=\"h-fuente-blog-masterd\">Fuente: Blog MasterD<\/h4>\n<!-- \/wp:heading -->","post_title":"Oposiciones T\u00e9cnico Educaci\u00f3n Infantil: Pruebas y requisitos","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"oposiciones-tecnico-educacion-infantil-pruebas-requisitos","to_ping":"","pinged":"","post_modified":"2022-06-14 17:48:23","post_modified_gmt":"2022-06-14 15:48:23","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=36825","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"16","filter":"raw"},{"ID":76684,"post_author":"255","post_date":"2022-11-02 16:57:32","post_date_gmt":"2022-11-02 15:57:32","post_content":"<!-- wp:paragraph -->\n<p>El<a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/\" target=\"_blank\" rel=\"noopener\"><strong> proceso de oposici\u00f3n<\/strong><\/a> y las pruebas que hay que superar para <a href=\"https:\/\/www.emagister.com\/master-oficial\/master-oficial-ensenanza-secundaria-tematica-783.htm\" target=\"_blank\" rel=\"noopener\"><strong>ser maestro o profesor<\/strong><\/a> en Espa\u00f1a pueden ser un poco complicados. Por eso, en Emagister te lo queremos facilitar y te lo explicamos <a href=\"https:\/\/www.emagister.com\/blog\/oposiciones\/\" target=\"_blank\" rel=\"noopener\"><strong>punto por punto<\/strong><\/a>. Lo primero que debes hacer es esperar a que salga la <strong>oferta de empleo p\u00fablico <\/strong>de profesores, que se suele publicar cada a\u00f1o. En esta oferta se detallan <a href=\"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/\" target=\"_blank\" rel=\"noopener\"><strong>las plazas de ESO y FP<\/strong><\/a> y las materias correspondientes. Seguidamente, cada comunidad aut\u00f3noma publica la <strong>convocatoria<\/strong> con el temario de las pruebas, las puntuaciones, los requisitos para participar. El temario, por otra parte, var\u00eda tambi\u00e9n seg\u00fan la comunidad. En la convocatoria tambi\u00e9n se especifica el <strong>plazo de inscripci\u00f3n<\/strong>; una vez finalizado, al cabo de unos d\u00edas o semanas sale el <strong>listado provisional de admitidos<\/strong>, contra el cual se puede alegar. A continuaci\u00f3n, se determina el <strong>lugar y hora de la prueba<\/strong>, a partir de la cual se definen las <strong>listas provisionales y las definitivas <\/strong>de calificaciones. La oposici\u00f3n finaliza con la publicaci\u00f3n en el BOE de los aprobados y su nombramiento como funcionarios.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Por otra parte, no en todas las comunidades la <strong>fase de oposici\u00f3n<\/strong> es igual. En todos los casos, sin embargo, consta de dos pruebas eliminatorias: la primera consiste en desarrollar uno o m\u00e1s temas, mientras que en la segunda hay que presentar y exponer una programaci\u00f3n y una unidad did\u00e1cticas ante un tribunal. Finalmente, en la <strong>fase de concurso<\/strong> se valoran los m\u00e9ritos tanto acad\u00e9micos como profesionales del aspirante. Por ejemplo, los que se presenten a una especialidad de ingl\u00e9s tendr\u00e1n que hacer un examen para demostrar sus capacidades. \u00bfTe parece demasiado complicado todo este proceso de oposiciones para maestro o profesor? En Emagister te lo ponemos f\u00e1cil <a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/oposiciones-educacion-cultura-tematica-6.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>con nuestros cursos<\/strong><\/a>. \u00a1Atr\u00e9vete!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 id=\"h-que-necesitas-saber-para-presentarte-a-unas-oposiciones\"><strong>\u00bfQu\u00e9 necesitas saber para presentarte a unas oposiciones?<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol><li><strong>Planifica el tiempo.<\/strong> Aunque parezca que hay que estudiar un temario interminable o que las fases de la oposici\u00f3n no se acaban nunca, el \u00e9xito reside en la planificaci\u00f3n del tiempo para estudiar y presentar las tareas que te encomienden. Una buena planificaci\u00f3n es la base para un excelente.<\/li><li><strong>La motivaci\u00f3n, un elemento clave.<\/strong> A pesar de que te planifiques bien, puede pasar que no encuentres motivos para estudiar un temario que te parece poco \u00fatil o que no te llama la atenci\u00f3n. Sin embargo, est\u00e1 demostrado que <a href=\"https:\/\/www.emagister.com\/blog\/que-frases-no-debes-decirle-a-un-opositor\/\" target=\"_blank\" rel=\"noopener\">cuanto m\u00e1s te impliques<\/a> en el proceso de estudio, m\u00e1s disfrutar\u00e1s y mejores resultados obtendr\u00e1s.<\/li><li><strong>Oposiciones, \u00bfmisi\u00f3n imposible?<\/strong> Las oposiciones suelen requerir muchos a\u00f1os de estudio, pero no siempre dan los frutos esperados. Es m\u00e1s, a menudo no sirven para cubrir muchas de las plazas ofertadas. \u00bfConviene optar por un sistema m\u00e1s flexible que no potencie la competitividad? \u00a1El dilema est\u00e1 servido!<\/li><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Fuente: Educaci\u00f3n 3.0<\/strong><\/p>\n<!-- \/wp:paragraph -->","post_title":"\u00bfQu\u00e9 tengo que saber para preparar las oposiciones de Educaci\u00f3n?","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"que-tengo-que-saber-para-preparar-las-oposiciones-de-educacion","to_ping":"","pinged":"","post_modified":"2022-11-02 16:57:34","post_modified_gmt":"2022-11-02 15:57:34","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=76684","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":36526,"post_author":"239","post_date":"2023-01-17 12:14:10","post_date_gmt":"2023-01-17 11:14:10","post_content":"<!-- wp:paragraph -->\n<p>Para ser <strong>profesor o profesora de Formaci\u00f3n Profesional<\/strong>, adem\u00e1s de tener una serie de conocimientos y competencias, es necesaria una gran <strong>vocaci\u00f3n<\/strong>, ya que puede llegar a ser una profesi\u00f3n <strong>tan gratificante como exigente<\/strong>. Quiz\u00e1 no fuese la primera opci\u00f3n laboral que escogiste cuando acabaste tu formaci\u00f3n, pero tanto si lo ten\u00edas claro desde el principio como si no, hay una serie de requisitos que debes conocer.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Si quieres ser profesor en un <strong>centro privado o concertado<\/strong>, la mejor opci\u00f3n es hacerles llegar tu <strong><em>curr\u00edculum<\/em><\/strong> para cuando tengan una plaza disponible, y el proceso de selecci\u00f3n depender\u00e1 de cada centro. Para entrar en un <strong>centro p\u00fablico<\/strong> es necesario superar unas <a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>oposiciones<\/strong><\/a><strong> <\/strong>o entrar en las bolsas de interinos de las comunidades aut\u00f3nomas.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Pero tanto si optas por la educaci\u00f3n p\u00fablica como por la privada, tienes que saber que hay una serie de <strong>requisitos y titulaciones indispensables<\/strong> para las dos opciones:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 id=\"h-requisitos-para-ser-profesor-tecnico-de-fp\"><strong>Requisitos para ser profesor t\u00e9cnico de FP<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:list -->\n<ul><li>Ser mayor de edad y ciudadano de la Uni\u00f3n Europea.<\/li><li>No contar con un expediente disciplinario previo que inhabilite el desempe\u00f1o en el cargo.<\/li><li>No poseer limitaci\u00f3n f\u00edsica o ps\u00edquica alguna, que impida el adecuado desempe\u00f1o de las tareas de docente.<\/li><li>Dependiendo de la Comunidad Aut\u00f3noma de inter\u00e9s, se debe autentificar el dominio de la lengua co-oficial establecida en la misma.<\/li><li>Contar con una <strong>Carrera universitaria<\/strong> (grado, licenciatura, ingenier\u00eda\u2026) que tenga relaci\u00f3n con la especialidad que elijas para impartir clase <strong>o ciclo formativo de grado superior<\/strong> que tenga relaci\u00f3n con la especialidad.<\/li><li>Para los titulados universitarios: estar en posesi\u00f3n del t\u00edtulo de <a href=\"https:\/\/www.emagister.com\/blog\/10-opciones-para-cursar-el-master-de-formacion-del-profesorado\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>M\u00e1ster de Formaci\u00f3n del Profesorado<\/strong><\/a>. Esto es obligatorio para impartir clase en cualquier tipo de centro, tanto p\u00fablico como privado.<\/li><li>Para los titulados en FP superior: estar en posesi\u00f3n del <a href=\"https:\/\/www.emagister.com\/i\/certificado-formacion-pedagogica-didactica-profesorado-tecnico-fp.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>CAP de FP (Certificado Oficial de Formaci\u00f3n Pedag\u00f3gica y Did\u00e1ctica para Profesorado de Formaci\u00f3n Profesional sin carrera)<\/strong><\/a><strong>.\u00a0<\/strong><\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Vale recalcar que cada Comunidad Aut\u00f3noma puede requerir requisitos adicionales o <strong>requisitos propios<\/strong>, como por ejemplo la exigencia de alguna titulaci\u00f3n necesaria, la exigencia de una experiencia profesional relacionada con la materia a impartir o tener experiencia como docente en centros p\u00fablicos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Hay profesionales que no poseen una titulaci\u00f3n universitaria, y por tanto no pueden cursar el M\u00e1ster de Formaci\u00f3n del Profesorado. Si este es tu caso, necesitas llevar a cabo una formaci\u00f3n pedag\u00f3gica y did\u00e1ctica que pueda ser equivalente y que te habilite para el ejercicio de la docencia.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Las personas que aprobaron el antiguo <strong>CAP (Certificado de Aptitud Pedag\u00f3gica)<\/strong> antes de 2009 est\u00e1n exentos de cursar este m\u00e1ster para acceder a este tipo de oposiciones.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tambi\u00e9n hay que saber que para las personas con un certificado de discapacidad de m\u00e1s del 33%, algunas comunidades aut\u00f3nomas <strong>reservan una serie de plazas<\/strong>, que oscilan entre el 5% y el 7%.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2><strong>Oposiciones a Profesor de FP<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Como el resto de las oposiciones, para los cargos de profesores o maestros, cada a\u00f1o se publican las convocatorias en el <strong>Bolet\u00edn Oficial de la Provincia (BOP)<\/strong>, en las gacetas municipales y tablones de anuncios de los ayuntamientos, y en el <strong>Bolet\u00edn Oficial del Estado<\/strong> (<strong>BOE<\/strong>).<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Todos los a\u00f1os, las convocatorias son llevadas a cabo entre enero y abril, mientras que las oposiciones se efect\u00faan a partir de finales de junio.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Recomendamos consultar con cada comunidad aut\u00f3noma el contenido de las pruebas de oposici\u00f3n, as\u00ed como los temarios. Para prepararlas, puedes encontrar diversas opciones en el <a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>buscador de oposiciones<\/strong><\/a><strong> <\/strong>de <strong>Emagister <\/strong>o consultar el <a href=\"https:\/\/www.emagister.com\/rankings\/ranking-escuelas-academias-para-oposiciones-mejor-valoracion-rankt-20.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ranking de academias de preparaci\u00f3n de oposiciones mejor valoradas.<\/strong><\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2 id=\"h-plazas\"><strong>Plazas<\/strong><\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Aunque la informaci\u00f3n oficial de las plazas para las oposiciones del 2023 no est\u00e1 confirmada en su totalidad, el sitio web especialista en oposiciones <strong>Magister.com<\/strong> ha publicado un listado con las previsiones de plazas por cada Comunidad Aut\u00f3noma:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><li>Madrid: 3.700 plazas<\/li><li>Andaluc\u00eda: 3.800 plazas<\/li><li>Arag\u00f3n: 1021 plazas<\/li><li>Asturias: 780 plazas<\/li><li>Baleares: 1080 plazas<\/li><li>Canarias: 1210 plazas<\/li><li>Cantabria: 595 plazas<\/li><li>Castilla de la Mancha: 1157<\/li><li>Castilla y Le\u00f3n: 1050 plazas<\/li><li>Catalu\u00f1a: 5005 plazas<\/li><li>Extremadura: 720 plazas<\/li><li>Galicia: 3000 plazas<\/li><li>La Rioja: 338 plazas<\/li><li>MEC: Ceuta-Melilla: 200 plazas<\/li><li>Murcia: 1300 plazas<\/li><li>Navarra: 883 plazas<\/li><li>Pa\u00eds Vasco: 1900 plazas<\/li><li>C. Valenciana: m\u00e1s de 2500 plazas<\/li><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3><strong>Bolsa de interinos<\/strong><\/h3>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p>Cada comunidad aut\u00f3noma tiene una <strong>bolsa de profesores interinos<\/strong>, que puede ser otra manera de acceder al empleo p\u00fablico de manera temporal o mientras no se convocan nuevas oposiciones. Para acceder a estas, es necesario aprobar una prueba espec\u00edfica de car\u00e1cter te\u00f3rico y pr\u00e1ctico. En algunos casos se puede evitar dicha prueba acreditando una cierta experiencia previa.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00bfY t\u00fa? \u00bfHas realizado alguno de estos cursos? <strong>No olvides compartir tu opini\u00f3n con los dem\u00e1s estudiantes en Emagister<\/strong> (tanto si los has realizado a trav\u00e9s de nuestra plataforma como si no), y as\u00ed estar\u00e1s ayudando a que otras personas elijan su mejor formaci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->","post_title":"Qu\u00e9 necesitas para ser profesor de FP","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"necesitas-profesor-fp","to_ping":"","pinged":"","post_modified":"2023-01-17 12:14:12","post_modified_gmt":"2023-01-17 11:14:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=36526","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"865","filter":"raw"},{"ID":16446,"post_author":"124","post_date":"2022-10-29 09:45:00","post_date_gmt":"2022-10-29 07:45:00","post_content":"<!-- wp:paragraph -->\n<p>La actual crisis econ\u00f3mica ha tenido una gran repercusi\u00f3n en el conjunto de la sociedad espa\u00f1ola, independientemente de la clase social, la edad o el sexo. &nbsp;Cada vez m\u00e1s los j\u00f3venes temen el futuro. Tras varias d\u00e9cadas de bonanza econ\u00f3mica saben que la edad adulta no vendr\u00e1 acompa\u00f1ada de la seguridad con la que ellos, en la mayor parte de los casos, se han criado. El mercado laboral es mucho m\u00e1s variable, los trabajadores est\u00e1n sometidos a unas exigencias mayores, y la formaci\u00f3n continua y adaptaci\u00f3n constante son dos requisitos indispensables en cualquier trabajo, independientemente del sector.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Conscientes de esta gran dificultad, se ha tratado, desde diferentes \u00e1mbitos sociales, fomentar el esp\u00edritu emprendedor de todos los ciudadanos, especialmente de los j\u00f3venes. Pero, \u00bfcu\u00e1l ha sido el resultado? \u00bfSe est\u00e1 realmente inculcando estos valores? Los \u00faltimos estudios demuestran precisamente lo contrario: m\u00e1s de la mitad de los j\u00f3venes quiere ser funcionario en Espa\u00f1a. &nbsp;\u00bfQu\u00e9 hay de cierto en esto?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>La salida de la docencia<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>A pesar de los esfuerzos constantes de diferentes administraciones p\u00fablicas en fomentar el emprendurismo, y del progresivo descenso de las convocatorias de <a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/\">oposiciones<\/a>, \u00a0lo cierto es que el funcionariado, y concretamente, las condiciones de los empleados p\u00fablicos, siguen siendo muy atractivos para los m\u00e1s j\u00f3venes. Muchos piensan que es de las pocas salidas que disponen para poder garantizar un futuro sin sobresaltos econ\u00f3micos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un ejemplo de ello es, sin ir m\u00e1s lejos, la amplia demanda, independientemente de la regi\u00f3n, del <a href=\"https:\/\/www.emagister.com\/master-oficial\/master-oficial-ensenanza-secundaria-tematica-783.htm\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1ster de Formaci\u00f3n de Profesorado<\/a>, recordemos, obligatorio para todo titulado universitario que quiere ejercer la docencia en un <a href=\"https:\/\/www.emagister.com\/cursos-homologados-oposiciones-secundaria-tps-1353078.htm\" target=\"_blank\" rel=\"noreferrer noopener\">centro p\u00fablico de educaci\u00f3n secundaria.<\/a><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Seg\u00fan zonas, Andaluc\u00eda tuvo este pasado mes de septiembre 2.665 matriculados, regi\u00f3n seguida por la Comunidad Valenciana, con 2.346, ambas, con cifras muy superiores a las registradas en Madrid, con 1.890, o Catalu\u00f1a, 1.007, donde hay un censo de estudiantes mayor. La alta demanda ha provocado que en las aulas se encuentren personas con perfiles de lo m\u00e1s variopinto, con una experiencia profesional y acad\u00e9mica diferente, edad, o incluso aspiraciones.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La pregunta en este caso podr\u00eda ser: \u00bfes la <a href=\"https:\/\/www.emagister.com\/oposiciones-convocatorias\/oposiciones-educacion-cultura-tematica-6.htm\" target=\"_blank\" rel=\"noreferrer noopener\">docencia <\/a>una verdadera vocaci\u00f3n para estos profesionales o \u00fanicamente una salida posible para encontrar la estabilidad econ\u00f3mica? \u00bfSi no se hace por vocaci\u00f3n, es una apuesta segura?<\/p>\n<!-- \/wp:paragraph -->","post_title":"M\u00e1ster de secundaria, \u00bfvocaci\u00f3n o \u00faltimo recurso?","post_excerpt":"","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"master-profesor-secundaria-vocacion-o-ultimo-recurso","to_ping":"","pinged":"","post_modified":"2022-11-07 13:17:43","post_modified_gmt":"2022-11-07 12:17:43","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.emagister.com\/blog\/?p=16446","menu_order":936,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw"}],"descripcion_lo_ultimo":"","sidebar":"","enlaces":false,"mostrar_faldon":"-1","texto_faldon":"Prepara tus oposiciones de Educaci\u00f3n","link_faldon":"https:\/\/www.emagister.com\/oposiciones-convocatorias\/oposiciones-educacion-cultura-tematica-6.htm","link_texto_faldon":"Buscar cursos","hreflang":[{"url":""}],"fecha":"no"},"z_taxonomy_image_url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/11\/educacion-3.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Oposiciones Educaci\u00f3n - Blog Emagister<\/title>\n<meta name=\"description\" content=\"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones Educaci\u00f3n archivos\" \/>\n<meta property=\"og:description\" content=\"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/oposiciones\\\/maestros-profesores-educacion\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/oposiciones\\\/maestros-profesores-educacion\\\/\",\"name\":\"Oposiciones Educaci\u00f3n - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"description\":\"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/oposiciones\\\/maestros-profesores-educacion\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/oposiciones\\\/maestros-profesores-educacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparar oposiciones\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/oposiciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oposiciones Educaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oposiciones Educaci\u00f3n - Blog Emagister","description":"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones Educaci\u00f3n archivos","og_description":"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.","og_url":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/","og_site_name":"Blog Emagister","twitter_card":"summary_large_image","twitter_site":"@emagister","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/","url":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/","name":"Oposiciones Educaci\u00f3n - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"description":"Convocatorias, consejos y toda la informaci\u00f3n necesaria para preparar las oposiciones a maestro de educaci\u00f3n infantil, primaria y profesor de secundaria, FP o universidad. Encuentra en la Gu\u00eda Emagister todas las opciones para preparar tus oposiciones de educaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/oposiciones\/maestros-profesores-educacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Preparar oposiciones","item":"https:\/\/www.emagister.com\/blog\/oposiciones\/"},{"@type":"ListItem","position":3,"name":"Oposiciones Educaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories\/8405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories\/8333"}],"wp:post_type":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts?categories=8405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}