{"id":107237,"date":"2020-09-18T10:09:18","date_gmt":"2020-09-18T08:09:18","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=107237"},"modified":"2021-04-27T09:52:06","modified_gmt":"2021-04-27T07:52:06","slug":"las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/","title":{"rendered":"Las consecuencias del apego evitativo en la infancia y la adultez"},"content":{"rendered":"<p>A medida que crecemos, los v\u00ednculos emocionales que se generaron en la infancia se van desarrollando hasta el punto de marcar nuestra personalidad y la forma de relacionarnos con otras personas.<\/p>\n<p>En ese sentido, es importante establecer diferencias entre quienes tuvieron el respaldo de un apego seguro y quienes experimentaron un apego evitativo. Para conocer las diferencias y otras cuestiones vinculadas con las emociones de los ni\u00f1os y su impacto en la adultez, se recomienda el siguiente art\u00edculo y, en caso de querer profundizar de manera te\u00f3rica y profesional en la educaci\u00f3n infantil, se sugiere cursar la capacitaci\u00f3n como Experto\/a en Crianza y en Desarrollo Emocional.<!--more--><\/p>\n<h2><strong>El apego: \u00bfc\u00f3mo se crea?<\/strong><\/h2>\n<p>Filogen\u00e9ticamente, <strong>los seres humanos estamos orientados a la creaci\u00f3n de v\u00ednculos emocionales<\/strong>. Los primeros se producen con los responsables de nuestro crecimiento, padres y cuidadores, y con aquellas personas que nos transmiten sensaci\u00f3n de seguridad.<\/p>\n<p>Se estima que hay tres patrones de apego:<\/p>\n<ul>\n<li>Seguro (lo generan aproximadamente un 60% de los ni\u00f1os)<\/li>\n<li>Ambivalente o resistente (cerca de un 12% de los peque\u00f1os)<\/li>\n<li>Evitativo o rechazante (un 20%)<\/li>\n<\/ul>\n<p>Seg\u00fan distintas investigaciones, <strong>estos apegos se mantienen estables durante el crecimiento y el desarrollo de la personalidad<\/strong>; en ocasiones, es posible que se puedan modificar pero no es tan frecuente. Por tanto, hay que tenerlos en cuenta ya que influyen en la educaci\u00f3n y se manifiestan en circunstancias espec\u00edficas, como la muerte de una figura cercana.<\/p>\n<p><strong>Apego evitativo en ni\u00f1os: manifestaciones<\/strong><\/p>\n<p>\u00bfEn qu\u00e9 consiste el apego evitativo? \u00bfC\u00f3mo se reconoce? Se manifiesta <strong>cuando la persona huye de forma habitual de sus emociones<\/strong>. Esto guarda relaci\u00f3n con los primeros a\u00f1os, en la infancia, ya que posiblemente el responsable, entendido como figura paterna u otras cercanas, no cumpli\u00f3 con las necesidades afectivas del ni\u00f1o.<\/p>\n<p>Por tanto, <strong>el apego evitativo se refiere a padres y madres que no lograron aportar al ni\u00f1o el cari\u00f1o y acompa\u00f1amiento necesario<\/strong>. En estos casos, antes que la maldad o alg\u00fan otro sentimiento negativo, se trata de incapacidad o negligencia. Por tanto, esto tambi\u00e9n es un factor a tener en cuenta durante la crianza. No solo se trata de alimentar y vestir, <strong>sino tambi\u00e9n de acercar al ni\u00f1o a sus emociones y prestarle atenci\u00f3n cuando las manifiesta.<\/strong><\/p>\n<p>\u00bfEsto puede afectar su vida adulta? S\u00ed. \u00bfLas consecuencias? <strong>Se desarrollan personas con falsa seguridad, mostr\u00e1ndose autosuficientes, ocultando vulnerabilidades y diversas carencias<\/strong>. Aunque puedan transmitir emociones positivas, en muchos casos est\u00e1n d\u00e1ndole la espalda a sus emociones, alej\u00e1ndose de lo que realmente sienten.<\/p>\n<p>Estas personas suelen transmitir independencia y autonom\u00eda. Sin embargo, <strong>no les resulta c\u00f3modo afrontar sus emociones, en especial cuando experimentan miedos<\/strong>. Por tanto, no pueden encausar de la mejor manera sus sentimientos. Por eso importante estar atento a su manifestaci\u00f3n y abordarla de la mejor manera posible.<\/p>\n<h3><strong>La principal caracter\u00edstica: bloqueo emocional<\/strong><\/h3>\n<p>Por lo general, <strong>estas personas suelen tener una percepci\u00f3n elevada sobre s\u00ed mismas;<\/strong>\u00a0autoestima alta, capacidad y acci\u00f3n con base en esto. En oposici\u00f3n, menosprecian a otras personas o las ven de manera negativa. Esa experiencia durante la infancia los lleva a percibir a otros como inseguros o poco fiables.<\/p>\n<p>Ac\u00e1 tambi\u00e9n se puede tratar de apego rechazante. <strong>Este incentiva que las personas puedan desenvolverse de forma segura en distintos escenarios racionales, marcados por objetivos, estudios o trabajo.<\/strong> Por el contrario, cuando se trata de relaciones \u00edntimas, manifiestan complicaciones. Es en el campo emocional donde se sienten bloqueados, desconectados y ajenos. Esto es, en buena medida, porque no logran lidiar con sus emociones.<\/p>\n<p>Hay algunos patrones de comportamiento que se pueden reconocer en estas personas:<\/p>\n<ol>\n<li>Suelen marcar distancia para prevenir el rechazo. Es una especie de protecci\u00f3n emocional.<\/li>\n<li>Se incomodan en escenarios de relaciones emocionales. Las pueden buscar y querer, pero su temor los lleva a quedarse bloqueados en muchos casos.<\/li>\n<\/ol>\n<h4><strong>Apego rechazante: \u00bfpor qu\u00e9 se produce?<\/strong><\/h4>\n<p>Estas condiciones por lo general est\u00e1n asociadas con la infancia, el momento en el que los padres deben prestar atenci\u00f3n a las emociones que manifieste el hijo. <strong>De esa manera ser\u00e1 posible ayudarlo a gestionarlas para que, m\u00e1s adelante, no sean un inconveniente o condicionen su personalidad.<\/strong><\/p>\n<p>Por lo general, los responsables del peque\u00f1o se desinteresan o desprenden de \u00e9l en algunos escenarios. Entonces, a modo de respuesta, el ni\u00f1o reacciona emocionalmente. Por tanto, cuando lo dejan solo o no le prestan atenci\u00f3n, se las apa\u00f1a sin alterarse.<\/p>\n<p>Sin embargo, <strong>est\u00e1 cient\u00edficamente comprobado que la frecuencia card\u00edaca de los peque\u00f1os se eleva en estos casos.<\/strong>\u00a0Esto se interpreta como incomodidad y sufrimiento, aunque sea disimulado, ya que reprime e inhibe sus reacciones externas, algo que influir\u00e1 en sus crecimiento personal.<\/p>\n<h5><strong>Dificultad para expresar emociones en la infancia y la adultez<\/strong><\/h5>\n<p>Cuando un beb\u00e9 es desatendido por el responsable reprime la expresi\u00f3n de sus emociones. Aunque puedan aparentar todo lo contrario, transmitiendo seguridad, autosuficiencia, y otras conductas, no es realmente as\u00ed. <strong>Pueden relacionarse f\u00e1cilmente con desconocidos pero, al momento de profundizar y lograr relaciones m\u00e1s estables, se complica.<\/strong><\/p>\n<p>Es por eso que se convierten en adultos que ocultan sus emociones, que no saben manifestarlas. <strong>Esto los penaliza, los bloquea y afecta sus v\u00ednculos personales.<\/strong> Para ello, lo m\u00e1s recomendable es asistir a terapia y trabajar en la readaptaci\u00f3n. As\u00ed, de manera progresiva, se pueden llenar esos vac\u00edos.<a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-94750 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<p>La manera m\u00e1s clara de reconocer a este tipo de personas es cuando se les pregunta c\u00f3mo est\u00e1n y no alcanzan a profundizar sobre sus emociones, ni reconocer cu\u00e1l es su estado emocional en el momento.<\/p>\n<h6><strong>Las diferencias entre el apego seguro y el evitativo<\/strong><\/h6>\n<p>En oposici\u00f3n, el apego seguro contribuye a que los ni\u00f1os crezcan con confianza y tranquilidad. Esto se produce porque los padres o responsables estuvieron cercanos y generaron un clima grato para ambos. Eso facilita su equilibrio emocional y abre posibilidades de exploraci\u00f3n para el chico.<\/p>\n<p>Ocurre todo lo contrario cuando el apego es evitativo, ya que el peque\u00f1o tiende a cerrarse a modo de respuesta ante el desprecio y las decepciones que teme experimentar. <strong>Se suelen desconectar de sus emociones.<\/strong><\/p>\n<p>Al ser conductas distintas el tipo de relaciones emocionales que sostienen tambi\u00e9n var\u00eda de forma significativa. <strong>En unas abundar\u00e1 la confianza, la seguridad y la empat\u00eda, mientras que en otras no, dando paso a la distancia, la desconfianza, miedo a la intimidad y otras tendencias que afectan su conducta.<\/strong><\/p>\n<p>Como se muestra, es importante manifestar cercan\u00eda y aprecio durante los primeros a\u00f1os de vida de un ni\u00f1o. De esa manera no solo se construye mejores momentos en esa instancia, tambi\u00e9n se le ayuda para que, cuando crezcan, tenga mejores respuestas emocionales ante sus necesidades. Por otro lado, entre adultos, se recomienda empat\u00eda y comprensi\u00f3n en estos casos.<\/p>\n<p><span style=\"font-weight: 400;\">\u00bfQuieres descubrir<\/span> <a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\"><b>toda la oferta formativa<\/b><\/a><span style=\"font-weight: 400;\"> de <strong>FormaInfancia European School<\/strong>? Ponte en <\/span><a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\"><b>contacto<\/b><\/a> <span style=\"font-weight: 400;\">con <strong>Emagister<\/strong> y te ayudaremos a encontrar el curso perfecto para ti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si eres ya un estudiante de este centro y deseas contarnos tu experiencia?, \u00a1deja tu opini\u00f3n gracias a este <\/span><a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\"><b>formulario<\/b><\/a><span style=\"font-weight: 400;\"> y ayuda otros estudiantes como t\u00fa a escoger mejor!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que crecemos, los v\u00ednculos emocionales que se generaron en la infancia se van desarrollando hasta el punto de &#8230; <a title=\"Las consecuencias del apego evitativo en la infancia y la adultez\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/\" aria-label=\"M\u00e1s en Las consecuencias del apego evitativo en la infancia y la adultez\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":16745,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[3265,5851,5852,10950,11164],"class_list":["post-107237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-centros-de-formacion","tag-5851","tag-formainfancia-european-school","tag-ij_sector_center_99997192958079401036578245562647_67","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de FORMAINFANCIA EUROPEAN SCHOOL","link_faldon":"https:\/\/www.emagister.com\/formainfancia-european-school-cursos-176986-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las consecuencias del apego evitativo en la infancia y la adultez - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las consecuencias del apego evitativo en la infancia y la adultez\" \/>\n<meta property=\"og:description\" content=\"A medida que crecemos, los v\u00ednculos emocionales que se generaron en la infancia se van desarrollando hasta el punto de ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-18T08:09:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T07:52:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1073\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Las consecuencias del apego evitativo en la infancia y la adultez\",\"datePublished\":\"2020-09-18T08:09:18+00:00\",\"dateModified\":\"2021-04-27T07:52:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/\"},\"wordCount\":1237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Ni\u00f1o_Blog.jpg\",\"keywords\":[\"Centros de formaci\u00f3n\",\"99997192958079401036578245562647\",\"FORMAINFANCIA EUROPEAN SCHOOL\",\"ij_sector_center_99997192958079401036578245562647_67\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/\",\"name\":\"Las consecuencias del apego evitativo en la infancia y la adultez - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Ni\u00f1o_Blog.jpg\",\"datePublished\":\"2020-09-18T08:09:18+00:00\",\"dateModified\":\"2021-04-27T07:52:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Ni\u00f1o_Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Ni\u00f1o_Blog.jpg\",\"width\":1073,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las consecuencias del apego evitativo en la infancia y la adultez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las consecuencias del apego evitativo en la infancia y la adultez - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/","og_locale":"es_ES","og_type":"article","og_title":"Las consecuencias del apego evitativo en la infancia y la adultez","og_description":"A medida que crecemos, los v\u00ednculos emocionales que se generaron en la infancia se van desarrollando hasta el punto de ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-09-18T08:09:18+00:00","article_modified_time":"2021-04-27T07:52:06+00:00","og_image":[{"width":1073,"height":715,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Las consecuencias del apego evitativo en la infancia y la adultez","datePublished":"2020-09-18T08:09:18+00:00","dateModified":"2021-04-27T07:52:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/"},"wordCount":1237,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg","keywords":["Centros de formaci\u00f3n","99997192958079401036578245562647","FORMAINFANCIA EUROPEAN SCHOOL","ij_sector_center_99997192958079401036578245562647_67","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/","url":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/","name":"Las consecuencias del apego evitativo en la infancia y la adultez - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg","datePublished":"2020-09-18T08:09:18+00:00","dateModified":"2021-04-27T07:52:06+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/11\/Ni\u00f1o_Blog.jpg","width":1073,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/las-consecuencias-del-apego-evitativo-en-la-infancia-y-la-adultez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Las consecuencias del apego evitativo en la infancia y la adultez"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/107237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=107237"}],"version-history":[{"count":5,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/107237\/revisions"}],"predecessor-version":[{"id":107265,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/107237\/revisions\/107265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/16745"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=107237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=107237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=107237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}