{"id":108268,"date":"2020-10-13T09:45:04","date_gmt":"2020-10-13T07:45:04","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=108268"},"modified":"2021-04-27T10:30:36","modified_gmt":"2021-04-27T08:30:36","slug":"sindrome-de-savant-que-es-el-sindrome-del-sabio","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/","title":{"rendered":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?"},"content":{"rendered":"<p>El s\u00edndrome del sabio es una cualidad mental poco com\u00fan y que, por tanto, se presenta solo en algunas personas. <strong>Se trata de individuos que tienen capacidades especiales para el dibujo, las ciencias, el deporte y otros campos.<\/strong><!--more--><\/p>\n<p>Sin embargo, el s\u00edndrome de Savant es a\u00fan m\u00e1s particular. Este art\u00edculo explora sus caracter\u00edsticas, su origen y explicaci\u00f3n, as\u00ed como distintas estrategias para detectarlo. Adem\u00e1s, en caso de que la persona quiera profundizar sobre este y otros s\u00edndromes que pueden manifestarse en las personas, se le invita a cursar el M\u00e1ster en Atenci\u00f3n Temprana para sumar herramientas y conocimientos dentro del campo de la Psicopedagog\u00eda.<\/p>\n<h2>S\u00edndrome de Savant: <span style=\"font-size: 24px;\">\u00bfQu\u00e9<\/span>\u00a0es?<\/h2>\n<p>Este s\u00edndrome <strong>se manifiesta en personas que pueden llegar a alcanzar competencias mentales fuera de lo com\u00fan<\/strong>; por ejemplo, logran desarrollar una memoria fotogr\u00e1fica notable. Sin embargo, esta no es la \u00fanica cualidad que se desarrolla o se manifiesta a partir de est\u00e9 s\u00edndrome.<\/p>\n<p>Su origen <strong>se remonta a 1789, cuando Benjamin Rush lo describi\u00f3<\/strong>. Fue el primero y se apoy\u00f3 en el caso de un esclavo africano que pod\u00eda calcular con precisi\u00f3n la edad de las personas, al instante. Ese fue el primer indicador que tom\u00f3 dentro de una larga investigaci\u00f3n que comenz\u00f3 con el objetivo de buscar el porqu\u00e9 a esas manifestaciones.<\/p>\n<p>Con el paso del tiempo, el s\u00edndrome tambi\u00e9n fue tratado por <strong>Darold Treffert<\/strong>, psiquiatra retirado y quien, en la actualidad, a\u00fan dirige investigaciones y desarrolla estudios sobre este s\u00edndrome, al que tambi\u00e9n se le define como s\u00edndrome del sapiente.<\/p>\n<p>Entre los aspectos que se han podido caracterizar es que <strong>suele afectar a m\u00e1s hombres que a mujeres<\/strong>; en promedio, entre cuatro y seis veces m\u00e1s. Este tipo de personas son definidas como extraordinarias a partir de las habilidades mentales que desarrollan.<\/p>\n<p>Algunos de los casos m\u00e1s famosos que se han asociados con este s\u00edndrome son <strong>Kim Peek<\/strong>, protagonista de <strong>The Good Doctor<\/strong>; <strong>Derek Paravicini<\/strong>, m\u00fasico; el pintor <strong>Stephen Wiltshire<\/strong> y <strong>Orlando Serrel<\/strong>. Otros nombres clave en la historia de la humanidad, como <strong>Miguel \u00c1ngel<\/strong>, <strong>Beethoven<\/strong>, <strong>Mozart<\/strong> o <strong>Nikolas Tesla<\/strong> tambi\u00e9n han sido asociados con este s\u00edndrome por sus extraordinarias habilidades mentales desarrolladas en diversos campos.<\/p>\n<h4><strong>S\u00edndrome de Savant: cuatro modelos<\/strong><\/h4>\n<p>Esta tipolog\u00eda fue desarrollada por el doctor <strong>Darold Teffert<\/strong>. Es \u00e9l quien los ubica en cuatro grupos distintos.<\/p>\n<ol>\n<li><strong>C\u00e1lculo de fechas<\/strong><\/li>\n<\/ol>\n<p>Las personas con este s\u00edndrome pueden memorizar calendarios completos.<\/p>\n<ol start=\"2\">\n<li><strong>C\u00e1lculo matem\u00e1tico<\/strong><\/li>\n<\/ol>\n<p>Los n\u00fameros se les dan con facilidad, resolviendo operaciones sin mayor tipo de complicaci\u00f3n y con grado de acierto total.<\/p>\n<ol start=\"3\">\n<li><strong>Creaci\u00f3n art\u00edstica<\/strong><\/li>\n<\/ol>\n<p>La m\u00fasica, la escultura y la pintura son campos en los que se desenvuelven con comodidad y personalidad.<\/p>\n<ol start=\"4\">\n<li><strong>Capacidades mec\u00e1nicas y espaciales<\/strong><\/li>\n<\/ol>\n<p>Las personas con el s\u00edndrome de Savant pueden construir maquetas y medir distancias con facilidad. Dentro de este s\u00edndrome hay al menos tres variantes m\u00e1s:<\/p>\n<ul>\n<li><strong>Savant prodigiosos<\/strong>: por lo general refiere a ni\u00f1os prodigio, con un conocimiento intelectual muy superior a otros. En la actualidad se estima que hay al menos 35 chicos con este s\u00edndrome.<\/li>\n<li><strong>Savant con talento<\/strong>: son personas que despuntan por habilidades espec\u00edficas y que, en otros campos, no demuestran tantas fortalezas.<\/li>\n<li><strong>Savant de minucias<\/strong>: disponen de habilidades concretas.<\/li>\n<\/ul>\n<h5><strong>\u00bfQui\u00e9nes desarrollan el S\u00edndrome del Sabio?<\/strong><\/h5>\n<p>No est\u00e1 claro, <strong>no hay una teor\u00eda que lo explique u ofrezca alguna relaci\u00f3n con su desarrollo<\/strong>. Estas personas pueden haber experimentado alguna lesi\u00f3n cerebral o tienen el hemisferio derecho m\u00e1s desarrollado en relaci\u00f3n con otras personas.<\/p>\n<p>Es particularidad <strong>hace que sus conexiones neurol\u00f3gicas y otros procesos sean mejores en ellos<\/strong>. Sin embargo, no es un campo en el que se tengan demasiadas certezas para poder establecer conclusiones.<\/p>\n<h6><strong>\u00bfC\u00f3mo se reconoce un ni\u00f1o prodigio?<\/strong><\/h6>\n<p>Es necesario tener claro algo: <strong>un ni\u00f1o prodigio no necesariamente experimenta el s\u00edndrome de Savant<\/strong>. Sin embargo, la mejor manera de reconocerlo, es apoy\u00e1ndose en la ayuda de un psic\u00f3logo.<\/p>\n<p>Los ni\u00f1os prodigio, en algunos casos, se pueden reconocer durante los primeros a\u00f1os. Hay una serie de caracter\u00edsticas que los describen:<\/p>\n<ul>\n<li>La curiosidad. Suelen interesarse por distintas cuestiones y mostrar deseos de aprender.<\/li>\n<li>Pueden experimentar dificultades de aprendizaje, hiperactividad o d\u00e9ficit de atenci\u00f3n. Sin embargo, cuentan con una memoria potencial valiosa.<\/li>\n<li>Suelen dormir menos que otros bebes, necesitan est\u00edmulos de forma constante y mantienen una mirada atenta a cuanto ocurre.<\/li>\n<li>Dan sus primeros pasos antes de cumplir el primer a\u00f1o de edad.<\/li>\n<li>A medida que crecen, pueden ser desobedientes. Sin embargo, desarrollan h\u00e1bitos como la lectura desde temprano y pueden recordar lugares en los que solo estuvieron durante un momento.<\/li>\n<li>Pueden desarrollar un intenso sentido de la justicia y hasta hipersensibilidad sensorial.<\/li>\n<\/ul>\n<p>Aunque estas caracter\u00edsticas suelen ser frecuentes, <strong>no quiere decir que todas se manifiestan en el ni\u00f1o<\/strong>. Sin embargo, sirven de gu\u00eda. En caso de que se desee profundizar m\u00e1s sobre ella, en <strong>Espa\u00f1a<\/strong> se puede consultar a la <strong>Asociaci\u00f3n Espa\u00f1ola para Superdotados y con Talento.<a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-94750 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/strong><\/p>\n<p>Las habilidades que desarrolla un ni\u00f1o Savant suelen requerirle muy poco esfuerzo y pr\u00e1ctica. Se les dan de forma natural. Por eso, en cuestiones de n\u00fameros, pueden resolver problemas matem\u00e1ticos con sencillez; dibujar de buena manera o recordar detalles con bastante precisi\u00f3n.<\/p>\n<p>En cualquiera de los casos (y habilidades), <strong>lo m\u00e1s recomendable es que el ni\u00f1o sea visto por un psic\u00f3logo que aclare el panorama y, a su vez, ofrezca orientaci\u00f3n para fomentar esas conductas y que el ni\u00f1o pueda desarrollarlas de la mejor manera posible.<\/strong><\/p>\n<h6><strong>S\u00edndrome de Savant y s\u00edndrome de Asperger, \u00bfhay relaci\u00f3n?<\/strong><\/h6>\n<p>Es muy com\u00fan que las personas asocien el s\u00edndrome de Savant con el s\u00edndrome de Asperger. Sin embargo, establecer estas relaciones no es lo m\u00e1s conveniente. <strong>Son cuestiones distintas m\u00e1s all\u00e1 de los paralelismos que se puedan establecer.<\/strong> Por tanto, no todo ni\u00f1o con s\u00edndrome de Asperger es considerado un Savant.<\/p>\n<p>En promedio, se estima que el 10% de los ni\u00f1os con autismo cuentan con habilidades Savant. Por otro lado, se calcula que 1 de cada 2 Savant manifiestan alguna caracter\u00edsticas vinculada con el autismo.<\/p>\n<p>Ante las dudas, lo m\u00e1s recomendable es consultar con un especialista en el \u00e1rea, un psic\u00f3logo que pueda ayudar a aclarar inquietudes y canalizar de mejor manera esas habilidades que poco a poco vaya manifestando el peque\u00f1o.<\/p>\n<p><span style=\"font-weight: 400;\">\u00bfQuieres descubrir<\/span> <a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\"><b>toda la oferta formativa<\/b><\/a><span style=\"font-weight: 400;\"> de <strong>FormaInfancia European School<\/strong>? Ponte en <\/span><a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\"><b>contacto<\/b><\/a> <span style=\"font-weight: 400;\">con <strong>Emagister<\/strong> y te ayudaremos a encontrar el curso perfecto para ti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si eres ya un estudiante de este centro y deseas contarnos tu experiencia, \u00a1deja tu opini\u00f3n gracias a este <\/span><a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\"><b>formulario<\/b><\/a><span style=\"font-weight: 400;\"> y ayuda otros estudiantes como t\u00fa a escoger mejor!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00edndrome del sabio es una cualidad mental poco com\u00fan y que, por tanto, se presenta solo en algunas personas. &#8230; <a title=\"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/\" aria-label=\"M\u00e1s en S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":100277,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[3265,5851,5852,10141,11164],"class_list":["post-108268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-centros-de-formacion","tag-5851","tag-formainfancia-european-school","tag-noticiaselpais","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de FORMAINFANCIA EUROPEAN SCHOOL","link_faldon":"https:\/\/www.emagister.com\/formainfancia-european-school-cursos-176986-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio? - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?\" \/>\n<meta property=\"og:description\" content=\"El s\u00edndrome del sabio es una cualidad mental poco com\u00fan y que, por tanto, se presenta solo en algunas personas. ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-13T07:45:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:30:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1197\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?\",\"datePublished\":\"2020-10-13T07:45:04+00:00\",\"dateModified\":\"2021-04-27T08:30:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/\"},\"wordCount\":1182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/autoestima-1-e1582282071532.jpg\",\"keywords\":[\"Centros de formaci\u00f3n\",\"99997192958079401036578245562647\",\"FORMAINFANCIA EUROPEAN SCHOOL\",\"noticiasElPais\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/\",\"name\":\"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/autoestima-1-e1582282071532.jpg\",\"datePublished\":\"2020-10-13T07:45:04+00:00\",\"dateModified\":\"2021-04-27T08:30:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/autoestima-1-e1582282071532.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/autoestima-1-e1582282071532.jpg\",\"width\":1197,\"height\":666,\"caption\":\"grupo crece\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/sindrome-de-savant-que-es-el-sindrome-del-sabio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio? - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?","og_description":"El s\u00edndrome del sabio es una cualidad mental poco com\u00fan y que, por tanto, se presenta solo en algunas personas. ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-10-13T07:45:04+00:00","article_modified_time":"2021-04-27T08:30:36+00:00","og_image":[{"width":1197,"height":666,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?","datePublished":"2020-10-13T07:45:04+00:00","dateModified":"2021-04-27T08:30:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/"},"wordCount":1182,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg","keywords":["Centros de formaci\u00f3n","99997192958079401036578245562647","FORMAINFANCIA EUROPEAN SCHOOL","noticiasElPais","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/","url":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/","name":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg","datePublished":"2020-10-13T07:45:04+00:00","dateModified":"2021-04-27T08:30:36+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/02\/autoestima-1-e1582282071532.jpg","width":1197,"height":666,"caption":"grupo crece"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/sindrome-de-savant-que-es-el-sindrome-del-sabio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"S\u00edndrome de Savant: \u00bfqu\u00e9 es el s\u00edndrome del sabio?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=108268"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108268\/revisions"}],"predecessor-version":[{"id":108360,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108268\/revisions\/108360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/100277"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=108268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=108268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=108268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}