{"id":108341,"date":"2020-10-13T09:31:24","date_gmt":"2020-10-13T07:31:24","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=108341"},"modified":"2021-04-27T10:53:12","modified_gmt":"2021-04-27T08:53:12","slug":"trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/","title":{"rendered":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos"},"content":{"rendered":"<p>Sin duda, la nataci\u00f3n es una de las actividades y deportes preferidos en la actualidad. Adem\u00e1s de ser un pasatiempo divertido, es un excelente deporte para practicar de forma profesional. As\u00ed que, si deseas empezar a ejercitarte, uno de los factores clave para desarrollar esta actividad adecuadamente es <strong>controlar la respiraci\u00f3n al nadar<\/strong>, pues una vez logres dominar por completo tu forma de respirar, podr\u00e1s ejecutar distintas t\u00e9cnicas de nado mientras ajustas tu respiraci\u00f3n a cada movimiento.<!--more--><\/p>\n<p>Por ello, en este art\u00edculo te contamos cu\u00e1les son los mejores ejercicios de entrenamiento para que aprendas a <strong>controlar tu respiraci\u00f3n al nadar <\/strong>y puedas practicar nataci\u00f3n como todo un experto. O si prefieres especializarte profesionalmente en este campo, la <strong>Escuela Europea del Deporte<\/strong> tiene para ti este nuevo y completo<strong> Curso Entrenador Superior de Nataci\u00f3n<\/strong>, una formaci\u00f3n de vanguardia que te permitir\u00e1 adquirir nuevos conocimientos y habilidades para que te puedas desempe\u00f1ar en esta \u00e1rea.<\/p>\n<h2><strong>T\u00e9cnicas b\u00e1sicas de respiraci\u00f3n<\/strong><\/h2>\n<p>A medida que vayas practicando ciertos ejercicios, aprender\u00e1s a respirar m\u00e1s r\u00e1pido, m\u00e1s profundo y de una manera \u00f3ptima, y as\u00ed mejorar\u00e1s tu t\u00e9cnica al nadar y tu rendimiento ser\u00e1 notablemente superior.<\/p>\n<p>Antes que nada, es importante que tengas en cuenta que, mientras est\u00e9s en el agua, la respiraci\u00f3n siempre se debe hacer a trav\u00e9s de la boca. Al exhalar profundamente, sacar\u00e1s todo el aire de los pulmones y, por ende, la inhalaci\u00f3n ser\u00e1 mejor\u2026 No olvides que el tiempo de exhalaci\u00f3n es aproximadamente dos o tres veces mayor que el de inhalaci\u00f3n.<\/p>\n<p>A continuaci\u00f3n, te indicamos algunos ejercicios pr\u00e1cticos para que puedas controlar y optimizar tu respiraci\u00f3n en el agua (es importante resaltar que cualquier tipo de ejercicio que practiques debe ser bajo la estricta supervisi\u00f3n de un entrenador):<\/p>\n<ul>\n<li><strong>Aguantar la respiraci\u00f3n<\/strong><\/li>\n<\/ul>\n<p>Lo primero que debes hacer antes de aprender a respirar al nadar es practicar tu aguante bajo el agua. Inicia poco a poco conteniendo tu respiraci\u00f3n y sumergi\u00e9ndote en la piscina; permanece all\u00ed durante unos cuantos segundos, y luego sal del agua. Practica este ejercicio alrededor de cinco veces en cada entrenamiento y ver\u00e1s como vas mejorando tu aguante gradualmente.<\/p>\n<ul>\n<li><strong>Inhalaci\u00f3n y exhalaci\u00f3n<\/strong><\/li>\n<\/ul>\n<p>Realiza este ejercicio mientras te sostienes en la orilla de la piscina. Comienza por sumergir tu cuerpo hasta que tus hombros queden justo a la altura del agua. Luego, debes inhalar profundamente por la boca y sumergir tu cabeza en el agua; inmediatamente, saca suavemente el aire de los pulmones por la nariz y retoma la posici\u00f3n inicial. Puedes hacer 10 repeticiones de este ejercicio.<a href=\"https:\/\/www.emagister.com\/cursos-escuela-europea-del-deporte-cen-1136987.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-96121 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/07\/escuela-europea-del-deporte.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/07\/escuela-europea-del-deporte.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/07\/escuela-europea-del-deporte-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<p>As\u00ed mismo, para aprender a respirar por la nariz y por la boca al mismo tiempo, solo debes repetir los pasos del ejercicio anterior, hacer una pausa para respirar tranquilamente y continuar 10 veces.<\/p>\n<ul>\n<li><strong>Respiraci\u00f3n para nado estilo crol<\/strong><\/li>\n<\/ul>\n<p>Si quieres nadar al estilo crol, es importante que sepas que justo cuando haces la rotaci\u00f3n es el momento preciso en el que debes inspirar. Una forma en la que lo puedes hacer de manera adecuada es manteniendo tu oreja contra el brazo extendido mientras rotas tu cuerpo de manera natural. Nunca debes hacer la inspiraci\u00f3n hacia el frente, solo hacia los lados, lo que tambi\u00e9n te ayudar\u00e1 a mantener una buena velocidad y coordinaci\u00f3n mientras nadas.<\/p>\n<p>Para este ejercicio la clave est\u00e1 en inhalar por la boca mientras giras la cabeza lateralmente, y la mitad de tu cara se encuentra bajo el agua. Luego, vuelve a sumergir toda la cara en el agua.<\/p>\n<p>Al retomar la posici\u00f3n de base (cuando toda la cabeza se encuentra sumergida en el agua), saca todo el aire por la nariz, por la boca o por ambos lados. No olvides mantener tu mirada siempre hacia el fondo de la piscina para que tu cuerpo permanezca alineado.<\/p>\n<p>As\u00ed que, si hasta ahora vas a comenzar a practicar nataci\u00f3n, es necesario que realices estos ejercicios b\u00e1sicos constantemente para que aprendas a controlar tu respiraci\u00f3n al nadar\u2026 y \u00a1no esperes m\u00e1s! Es hora de dar el primer paso para convertirte en todo un profesional en nataci\u00f3n.<\/p>\n<p>Si quieres conocer <a href=\"https:\/\/www.emagister.com\/cursos-escuela-europea-del-deporte-cen-1136987.htm\" target=\"_blank\" rel=\"noopener\"><strong>toda la oferta formativa<\/strong><\/a> que la<strong> Escuela Europea del Deporte<\/strong> tiene disponible para ti, no dudes en <a href=\"https:\/\/www.emagister.com\/contact\/center\" target=\"_blank\" rel=\"noopener\"><strong>contactar<\/strong><\/a> a uno de los profesionales de <strong>Emagister<\/strong> que con gusto te ayudar\u00e1 a encontrar el curso ideal.<\/p>\n<p>Si ya formas parte del grupo de estudiantes de este centro, comparte tu experiencia con otros alumnos en este <strong><a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\">formulario<\/a>,<\/strong> y ay\u00fadalos a tomar su decisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin duda, la nataci\u00f3n es una de las actividades y deportes preferidos en la actualidad. Adem\u00e1s de ser un pasatiempo &#8230; <a title=\"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/\" aria-label=\"M\u00e1s en Trucos para aprender a respirar adecuadamente al nadar en distintos estilos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":104680,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[11198,3265,9723,9785,11164],"class_list":["post-108341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-ij_sector_center_99997192958079401036578245616828_143","tag-centros-de-formacion","tag-9723","tag-escuela-europea-del-deporte","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de la Escuela Europea del Deporte","link_faldon":"https:\/\/www.emagister.com\/escuela-europea-del-deporte-cursos-1136987-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trucos para aprender a respirar adecuadamente al nadar en distintos estilos - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos\" \/>\n<meta property=\"og:description\" content=\"Sin duda, la nataci\u00f3n es una de las actividades y deportes preferidos en la actualidad. Adem\u00e1s de ser un pasatiempo ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-13T07:31:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:53:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos\",\"datePublished\":\"2020-10-13T07:31:24+00:00\",\"dateModified\":\"2021-04-27T08:53:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/\"},\"wordCount\":792,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/632017-PO9D5U-404.jpg\",\"keywords\":[\"ij_sector_center_99997192958079401036578245616828_143\",\"Centros de formaci\u00f3n\",\"99997192958079401036578245616828\",\"Escuela Europea del Deporte\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/\",\"name\":\"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/632017-PO9D5U-404.jpg\",\"datePublished\":\"2020-10-13T07:31:24+00:00\",\"dateModified\":\"2021-04-27T08:53:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/632017-PO9D5U-404.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/632017-PO9D5U-404.jpg\",\"width\":1920,\"height\":1247},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/","og_locale":"es_ES","og_type":"article","og_title":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos","og_description":"Sin duda, la nataci\u00f3n es una de las actividades y deportes preferidos en la actualidad. Adem\u00e1s de ser un pasatiempo ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-10-13T07:31:24+00:00","article_modified_time":"2021-04-27T08:53:12+00:00","og_image":[{"width":1920,"height":1247,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos","datePublished":"2020-10-13T07:31:24+00:00","dateModified":"2021-04-27T08:53:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/"},"wordCount":792,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg","keywords":["ij_sector_center_99997192958079401036578245616828_143","Centros de formaci\u00f3n","99997192958079401036578245616828","Escuela Europea del Deporte","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/","url":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/","name":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg","datePublished":"2020-10-13T07:31:24+00:00","dateModified":"2021-04-27T08:53:12+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/06\/632017-PO9D5U-404.jpg","width":1920,"height":1247},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/trucos-para-aprender-a-respirar-adecuadamente-al-nadar-en-distintos-estilos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Trucos para aprender a respirar adecuadamente al nadar en distintos estilos"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=108341"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108341\/revisions"}],"predecessor-version":[{"id":108357,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108341\/revisions\/108357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/104680"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=108341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=108341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=108341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}