{"id":108910,"date":"2020-10-27T09:27:13","date_gmt":"2020-10-27T08:27:13","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=108910"},"modified":"2021-04-27T10:56:25","modified_gmt":"2021-04-27T08:56:25","slug":"eros-y-psique-detalles-de-la-obra","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/","title":{"rendered":"Eros y Psique: detalles de la obra"},"content":{"rendered":"<p>Si eres una persona que le gustan las obras de arte y eres un observador(a) innato, te invitamos a leer este post con atenci\u00f3n. A continuaci\u00f3n, encontrar\u00e1s una breve explicaci\u00f3n de una de las obras m\u00e1s importantes de Antonio Canova \u2013 Eros y Psique.<!--more--><\/p>\n<h2>Descripci\u00f3n<\/h2>\n<p>Esta famosa obra est\u00e1 hecha de m\u00e1rmol blanco pulido y refinado con piedra volc\u00e1nica, con una mezcla de calcio con \u00e1cido. Esta combinaci\u00f3n de materiales era muy famosa en aquella \u00e9poca porque hac\u00eda lucir cada pieza reluciente y pulcra. Originalmente, se encontraba en los jardines de Lord Cawdor, en Roma. Actualmente se puede visitar en el Museo del Louvre, en Par\u00eds.<\/p>\n<p>Pero ahora, centr\u00e9monos en el mensaje, la escultura representa el momento justo en que Psique est\u00e1 a punto de ser besada por Eros. Ella aparece desnuda, ligeramente tapada con una tela, en posici\u00f3n yacente. Mientras que Eros se le aproxima suavemente con las alas desplegadas y la abraza sensualmente. Podemos decir que esta escultura refleja el poder del amor.<\/p>\n<h3>Composici\u00f3n<\/h3>\n<p>La proporci\u00f3n de la escultura est\u00e1 marcada por los c\u00e1nones cl\u00e1sicos. Cada cuerpo tiene una estructura cl\u00e1sica (piramidal), pero las alas de Eros, se entrelazan con su pierna y el cuerpo de Psique y componen una estructura de aspa. Por otro lado, las dos bocas \u2013 que no llegan a juntarse- est\u00e1n en medio; los brazos de Psique sirven para enmarcar las caras de los personajes que van a darse un beso.<\/p>\n<h4>Estilo Neocl\u00e1sico<\/h4>\n<p>Esta obra pertenece al estilo del neoclasicismo, en el cual predomina el uso de blanco en la mayor\u00eda de las esculturas. Tambi\u00e9n destaca porque se eliminaba cualquier referencia a la emoci\u00f3n, la pasi\u00f3n o el sentimiento. Las figuras ten\u00edan una contenci\u00f3n expresiva, aunque no es del todo cierto en el caso de Canova, ya que esta escultura es claramente pasional.<\/p>\n<h5>Estilo de autor<\/h5>\n<p>Antonio Canova no solo fue escultor, tambi\u00e9n fue un pintor italiano reconocido. En cuanto a su estilo, usaba l\u00edneas puras para dar claridad compositiva. Se dice que sent\u00eda un profundo inter\u00e9s por la figura humana y usaba materiales como el m\u00e1rmol blanco con un pulido extremo.<a href=\"https:\/\/www.emagister.com\/escuela-turismo-gastronomia-pirineos-cursos-1146151-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-93530 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/ESCUELA-DE-TURISMO-GASTRONOM\u00cdA-DE-LOS-PIRINEOS.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/ESCUELA-DE-TURISMO-GASTRONOM\u00cdA-DE-LOS-PIRINEOS.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/ESCUELA-DE-TURISMO-GASTRONOM\u00cdA-DE-LOS-PIRINEOS-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<p>Todas sus esculturas se caracterizan por tener un toque de sensualidad y un componente emotivo, a la vez que no se limitan a la visi\u00f3n frontal, sino que destaca el inter\u00e9s del espectador desde diferentes puntos de vista.<\/p>\n<h6>Interpretaci\u00f3n<\/h6>\n<p>El arte se puede interpretar de muchas formas pero, para un buen n\u00famero de personas y cr\u00edticos de arte, la obra Eros y Psique representa el grupo del amor que hace renacer a Psique, dormida para siempre. Se trata casi de un himno de amor que hace recordar la mitolog\u00eda griega y su historia que se enfoca en el alma inmortal del mito plat\u00f3nico. Para querer una persona por completo el d\u00eda y la noche, debe de haber un equilibrio entre la atracci\u00f3n f\u00edsica y la espiritual. Aunque sea la mente quien elabore nuestros valores est\u00e9ticos.<\/p>\n<p>Seg\u00fan Plat\u00f3n, el amor es una forma de elevaci\u00f3n, de purificaci\u00f3n del alma. Considera el amor f\u00edsico como el primer momento, pero el momento trascendente es cuando se da la compenetraci\u00f3n espiritual, cuando los amantes logran fusionar sus almas de una forma m\u00e1s intelectual.<\/p>\n<p>Si te pareci\u00f3 interesante esta publicaci\u00f3n y quieres descubrir <a href=\"https:\/\/www.emagister.com\/escuela-turismo-gastronomia-pirineos-cursos-1146151-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\">toda la oferta formativa<\/a> de la\u00a0<span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;ESCUELA DE TURISMO &amp; GASTRONOM\u00cdA DE LOS PIRINEOS&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14722,&quot;4&quot;:[null,2,13624051],&quot;10&quot;:2,&quot;11&quot;:3,&quot;14&quot;:[null,2,0],&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">ESCUELA DE TURISMO &amp; GASTRONOM\u00cdA DE LOS PIRINEOS<\/span><strong>, <\/strong>ponte en <a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\">contacto<\/a> con <strong>Emagister<\/strong> y te ayudaremos a encontrar el curso perfecto para ti.<\/p>\n<p>Si eres ya un estudiante de este centro y deseas contarnos tu experiencia \u00a1deja tu opini\u00f3n en este <a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\">formulario<\/a> y ayuda otros estudiantes como t\u00fa a escoger mejor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si eres una persona que le gustan las obras de arte y eres un observador(a) innato, te invitamos a leer &#8230; <a title=\"Eros y Psique: detalles de la obra\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/\" aria-label=\"M\u00e1s en Eros y Psique: detalles de la obra\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":103222,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[3265,10142,10511,10512,11164],"class_list":["post-108910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-centros-de-formacion","tag-noticiaslavanguardia","tag-10511","tag-escuela-de-turismo-gastronomia-de-los-pirineos","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de la ESCUELA DE TURISMO & GASTRONOM\u00cdA DE LOS PIRINEOS","link_faldon":"https:\/\/www.emagister.com\/escuela-turismo-gastronomia-pirineos-cursos-1146151-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eros y Psique: detalles de la obra - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eros y Psique: detalles de la obra\" \/>\n<meta property=\"og:description\" content=\"Si eres una persona que le gustan las obras de arte y eres un observador(a) innato, te invitamos a leer ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-27T08:27:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Eros y Psique: detalles de la obra\",\"datePublished\":\"2020-10-27T08:27:13+00:00\",\"dateModified\":\"2021-04-27T08:56:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1mio_1-small.jpg\",\"keywords\":[\"Centros de formaci\u00f3n\",\"noticiasLaVanguardia\",\"99997192958079401036578245625992\",\"ESCUELA DE TURISMO &amp; GASTRONOM\u00cdA DE LOS PIRINEOS\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/\",\"name\":\"Eros y Psique: detalles de la obra - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1mio_1-small.jpg\",\"datePublished\":\"2020-10-27T08:27:13+00:00\",\"dateModified\":\"2021-04-27T08:56:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1mio_1-small.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/1mio_1-small.jpg\",\"width\":1200,\"height\":674,\"caption\":\"optimizaci\u00f3n del tiempo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/eros-y-psique-detalles-de-la-obra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eros y Psique: detalles de la obra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eros y Psique: detalles de la obra - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/","og_locale":"es_ES","og_type":"article","og_title":"Eros y Psique: detalles de la obra","og_description":"Si eres una persona que le gustan las obras de arte y eres un observador(a) innato, te invitamos a leer ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-10-27T08:27:13+00:00","article_modified_time":"2021-04-27T08:56:25+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Eros y Psique: detalles de la obra","datePublished":"2020-10-27T08:27:13+00:00","dateModified":"2021-04-27T08:56:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg","keywords":["Centros de formaci\u00f3n","noticiasLaVanguardia","99997192958079401036578245625992","ESCUELA DE TURISMO &amp; GASTRONOM\u00cdA DE LOS PIRINEOS","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/","url":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/","name":"Eros y Psique: detalles de la obra - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg","datePublished":"2020-10-27T08:27:13+00:00","dateModified":"2021-04-27T08:56:25+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/04\/1mio_1-small.jpg","width":1200,"height":674,"caption":"optimizaci\u00f3n del tiempo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/eros-y-psique-detalles-de-la-obra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Eros y Psique: detalles de la obra"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=108910"}],"version-history":[{"count":5,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108910\/revisions"}],"predecessor-version":[{"id":109164,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/108910\/revisions\/109164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/103222"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=108910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=108910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=108910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}