{"id":109108,"date":"2020-10-29T09:05:31","date_gmt":"2020-10-29T08:05:31","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=109108"},"modified":"2021-04-27T10:25:06","modified_gmt":"2021-04-27T08:25:06","slug":"pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/","title":{"rendered":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional"},"content":{"rendered":"<p>El concepto de \u201ceducaci\u00f3n alternativa\u201d no tiene todav\u00eda una definici\u00f3n conceptual precisa y definitiva, pero se conoce como un proceso pr\u00e1ctico de acompa\u00f1amiento durante el periodo estudiantil con diferentes componentes como la implementaci\u00f3n de metodolog\u00edas din\u00e1micas y la construcci\u00f3n de nuevas oportunidades de formaci\u00f3n en lo t\u00e9cnico-vocacional y en lo l\u00fadico-art\u00edstico-cultural.<!--more--><\/p>\n<p>Aunque la educaci\u00f3n alternativa como las metodolog\u00edas Waldorf, Montessori, Kumon, Doman\u2026 existen en Espa\u00f1a desde hace d\u00e9cadas, poco partido se ha sacado de estas innovadoras y poco convencionales metodolog\u00edas de ense\u00f1anza.<\/p>\n<p>Se conocen como una alternativa a los colegios convencionales; sin embargo, a nivel educativo algunos intentan integrarlo a los sistemas de aprendizaje en los coles \u201cnormales\u201d o como actividades extraescolares.<\/p>\n<h2>Ense\u00f1anza tradicional vs. alternativa<\/h2>\n<p>En la ense\u00f1anza tradicional todo se realiza bajo un modelo conductual, es decir que existe un maestro o docente que entrega contenido y hay un estudiante que tiene que recibirlo. Sin embargo, este tipo de metodolog\u00edas de ense\u00f1anza se han quedado un poco obsoletas y no se adec\u00faan a las nuevas necesidades de los ni\u00f1os o estudiantes.<\/p>\n<p>Los ni\u00f1os en la actualidad crecen en un entorno sobre-estimulado gracias a las tecnolog\u00edas de la informaci\u00f3n, por lo que necesitan metodolog\u00edas diferentes que los ayuden a formarse a este nuevo ritmo de una manera mucho m\u00e1s independiente que en el pasado.<\/p>\n<p>Aprender descubriendo de la mano de herramientas como la tecnolog\u00eda deber\u00eda ser el hoy de la pedagog\u00eda. Pero a pesar de que las metodolog\u00edas de ense\u00f1anza alternativa existen hace varias d\u00e9cadas, poco se ha hecho para llegar a instaurarlas en la actualidad o sacarles alg\u00fan provecho.<\/p>\n<p>Una ense\u00f1anza alternativa parte de la motivaci\u00f3n del mismo estudiante para que quiera seguir adquiriendo conocimientos. Lo que la diferencia de la tradicional, es que se basa en estimular los sentidos visuales, auditivos, y cinest\u00e9sicos, para que el ni\u00f1o descubra progresivamente los distintos canales que le ayudan a captar el entorno y aprender de una manera pr\u00e1ctica sobre este.<\/p>\n<p>En general, los m\u00e9todos de educaci\u00f3n alternativa se basan en la premisa de ofrecer al alumno las herramientas que le permitan convertirse en autodidacta, aunque siempre bajo la direcci\u00f3n de maestros especializados.<\/p>\n<h3>M\u00e9todos de educaci\u00f3n alternativa en Espa\u00f1a<\/h3>\n<p>Existen diferentes m\u00e9todos de ense\u00f1anza alternativa como la Kumon, Montessori, Waldorf, Doman\u2026 que, a diferencia del sistema educativo convencional, proporcionan a los ni\u00f1os herramientas para ser m\u00e1s autodidactas tanto a nivel educativo como a nivel interpersonal. A continuaci\u00f3n una breve explicaci\u00f3n de cada una de estas metodolog\u00edas:<\/p>\n<p>M\u00e9todo Waldorf: La pedagog\u00eda Waldorf, iniciada por el fil\u00f3sofo alem\u00e1n Rudolf Steiner, busca el desarrollo de cada ni\u00f1o en un ambiente libre y cooperativo, sin ex\u00e1menes y con un fuerte apoyo en el arte y los trabajos manuales.<\/p>\n<p>Este m\u00e9todo divide el desarrollo en 3 etapas diferentes:<\/p>\n<ul>\n<li><strong><em>En la primera infancia<\/em><\/strong> el ni\u00f1o imita lo que le rodea y, por lo tanto, sus padres y educadores tienen la responsabilidad de crear un entorno que ofrezca al ni\u00f1o suficientes oportunidades para la imitaci\u00f3n y para que pueda jugar de forma creativa, ya que el m\u00e9todo entiende que las actividades l\u00fadicas constituyen una herramienta indispensable para aprender a dominar el movimiento corporal.<\/li>\n<li><strong><em>En la escuela primaria<\/em><\/strong>, el ni\u00f1o aprende a trav\u00e9s de la imaginaci\u00f3n, lo que el m\u00e9todo Waldorf denomina educar la inteligencia sensible del ni\u00f1o.<\/li>\n<li><strong><em>Durante la adolescencia<\/em><\/strong>, el alumno estudia todas las materias b\u00e1sicas, lo que le permitir\u00e1 descubrir aquellas para las que est\u00e1 m\u00e1s dotado o que suscitan su mayor inter\u00e9s y, de este modo, estar\u00e1 listo para elegir su vocaci\u00f3n.<\/li>\n<\/ul>\n<p>M\u00e9todo Montessori: Propugna la creaci\u00f3n de un entorno estimulante para que cada ni\u00f1o desarrolle su propio m\u00e9todo de aprendizaje siguiendo su curiosidad innata. En sus aulas, los ni\u00f1os se dividen por tramos de edad.<\/p>\n<p>Seg\u00fan la doctora y profesora italiana Mar\u00eda Montessori, el objetivo de la educaci\u00f3n es que los ni\u00f1os adquieran la m\u00e1xima independencia f\u00edsica y ps\u00edquica, y que aprendan a pensar por s\u00ed mismos.<\/p>\n<p>Ella se dedic\u00f3 a observar a los ni\u00f1os peque\u00f1os y lleg\u00f3 a la conclusi\u00f3n de que los adultos estaban equivocados al juzgarlos desde su propia experiencia, llena de prejuicios, que les imped\u00eda apreciar la curiosidad innata de los ni\u00f1os y su ilimitada capacidad para absorber conocimiento. Por eso, la doctora Montessori bas\u00f3 su m\u00e9todo educativo en facilitar a los ni\u00f1os un entorno y unos materiales que les sirviesen para avanzar en el conocimiento por s\u00ed mismos, dejando al profesor como un gu\u00eda.<\/p>\n<p>M\u00e9todo Kumon: Es un sistema de aprendizaje japon\u00e9s basado en dos programas: uno de matem\u00e1ticas y otro de lectura. Su principal objetivo es desarrollar el potencial de aprendizaje de los ni\u00f1os: motivar al alumno, mejorar su rendimiento acad\u00e9mico y aportarle autoconfianza.<\/p>\n<p>El papel de los padres es controlar que sus hijos realicen las tareas todos los d\u00edas, y corregir los ejercicios (con una plantilla que les facilitar\u00e1n en el centro) para que aprendan de sus propios errores, y, por supuesto, felicitarles por su esfuerzo y sus logros, motiv\u00e1ndoles para que contin\u00faen.<a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-94750 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/m-10-1-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<p>M\u00e9todo Doman: Se basa en desarrollar al m\u00e1ximo las \u00e1reas sensoriales del ni\u00f1o mediante la estimulaci\u00f3n para que los peque\u00f1os sean m\u00e1s inteligentes. Los programas m\u00e1s populares en las escuelas infantiles son los de los Bits de inteligencia, lectura y matem\u00e1ticas.<\/p>\n<p>B\u00e1sicamente se trata de mostrar al ni\u00f1o series de cinco tarjetas con palabras, escritas con letras grandes y que correspondan a una misma categor\u00eda (por ejemplo: partes del cuerpo humano, colores, animales\u2026), de forma r\u00e1pida, tres veces al d\u00eda y a manera de juego para que el ni\u00f1o se involucre m\u00e1s f\u00e1cilmente.<\/p>\n<p>M\u00e9todo Freinet: La pedagog\u00eda Freinet considera al ni\u00f1o como una persona completa, con sus gustos, sus ritmos, su forma particular de inteligencia. Ante todo, C\u00e9lestin Freinet cree que al ni\u00f1o le gusta hacer cosas, buscar respuestas a sus preguntas, descubrir y comprender por s\u00ed mismo, moverse, en lugar de permanecer sentado en su silla durante largas e interminables hora.<\/p>\n<p>Para profundizar en estos m\u00e9todos de aprendizaje, el M\u00e1ster en Pedagog\u00eda Montessori, brindar\u00e1 a todos los interesados los conocimientos especializados en la ense\u00f1anza alternativa de hoy y c\u00f3mo aplicarla de la mejor manera para obtener el mejor potencial de los estudiantes.<\/p>\n<p>Si te pareci\u00f3 interesante esta publicaci\u00f3n y quieres descubrir <a href=\"https:\/\/www.emagister.com\/cursos-formainfancia-european-school-cen-176986.htm\" target=\"_blank\" rel=\"noopener\">toda la oferta formativa<\/a> de\u00a0<strong>FORMAINFANCIA EUROPEAN SCHOOL, <\/strong>ponte en <a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\">contacto<\/a> con <strong>Emagister<\/strong> y te ayudaremos a encontrar el curso perfecto para ti.<\/p>\n<p>Si eres ya un estudiante de este centro y deseas contarnos tu experiencia \u00a1deja tu opini\u00f3n en este <a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\">formulario<\/a> y ayuda otros estudiantes como t\u00fa a escoger mejor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concepto de \u201ceducaci\u00f3n alternativa\u201d no tiene todav\u00eda una definici\u00f3n conceptual precisa y definitiva, pero se conoce como un proceso &#8230; <a title=\"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/\" aria-label=\"M\u00e1s en Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":108687,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[3265,5851,5852,10141,11164],"class_list":["post-109108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-centros-de-formacion","tag-5851","tag-formainfancia-european-school","tag-noticiaselpais","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de FORMAINFANCIA EUROPEAN SCHOOL","link_faldon":"https:\/\/www.emagister.com\/formainfancia-european-school-cursos-176986-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional\" \/>\n<meta property=\"og:description\" content=\"El concepto de \u201ceducaci\u00f3n alternativa\u201d no tiene todav\u00eda una definici\u00f3n conceptual precisa y definitiva, pero se conoce como un proceso ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-29T08:05:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:25:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional\",\"datePublished\":\"2020-10-29T08:05:31+00:00\",\"dateModified\":\"2021-04-27T08:25:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/\"},\"wordCount\":1211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/language-text-bubble.jpg\",\"keywords\":[\"Centros de formaci\u00f3n\",\"99997192958079401036578245562647\",\"FORMAINFANCIA EUROPEAN SCHOOL\",\"noticiasElPais\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/\",\"name\":\"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/language-text-bubble.jpg\",\"datePublished\":\"2020-10-29T08:05:31+00:00\",\"dateModified\":\"2021-04-27T08:25:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/language-text-bubble.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/language-text-bubble.jpg\",\"width\":1920,\"height\":1171,\"caption\":\"Speech Bubble Icons\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/","og_locale":"es_ES","og_type":"article","og_title":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional","og_description":"El concepto de \u201ceducaci\u00f3n alternativa\u201d no tiene todav\u00eda una definici\u00f3n conceptual precisa y definitiva, pero se conoce como un proceso ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-10-29T08:05:31+00:00","article_modified_time":"2021-04-27T08:25:06+00:00","og_image":[{"width":1920,"height":1171,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional","datePublished":"2020-10-29T08:05:31+00:00","dateModified":"2021-04-27T08:25:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/"},"wordCount":1211,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg","keywords":["Centros de formaci\u00f3n","99997192958079401036578245562647","FORMAINFANCIA EUROPEAN SCHOOL","noticiasElPais","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/","url":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/","name":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg","datePublished":"2020-10-29T08:05:31+00:00","dateModified":"2021-04-27T08:25:06+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/10\/language-text-bubble.jpg","width":1920,"height":1171,"caption":"Speech Bubble Icons"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/pedagogia-alternativa-un-modelo-educativo-fuera-de-lo-convencional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Pedagog\u00eda alternativa, un modelo educativo fuera de lo convencional"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=109108"}],"version-history":[{"count":5,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109108\/revisions"}],"predecessor-version":[{"id":109124,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109108\/revisions\/109124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/108687"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=109108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=109108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=109108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}