{"id":109517,"date":"2020-11-19T09:14:16","date_gmt":"2020-11-19T08:14:16","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=109517"},"modified":"2021-04-27T10:55:35","modified_gmt":"2021-04-27T08:55:35","slug":"todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/","title":{"rendered":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico"},"content":{"rendered":"<p>Para empezar a entenderlo, es necesario definirlo. El an\u00e1lisis grafol\u00f3gico es una ciencia dedicada a estudiar la personalidad, el temperamento y el car\u00e1cter de las personas a trav\u00e9s de su caligraf\u00eda, tomando en cuenta elementos como el espacio, el movimiento y la forma de las letras. Los profesionales de la grafolog\u00eda son fundamentales en la rama jur\u00eddica y por la naturaleza de su profesi\u00f3n, son met\u00f3dicos y muy rigurosos con su trabajo, pero tambi\u00e9n requieren de una formaci\u00f3n especializada para poder desarrollar sus habilidades. Antes de seguir hablando del tema, te recomendamos echar un vistazo al doble m\u00e1ster en Documentoscopia y Grafolog\u00eda que ofrece la Escuela des Arts.<!--more--><\/p>\n<h2><strong>Las bases de la grafolog\u00eda <\/strong><\/h2>\n<p>Los humanos escribimos de la misma manera en que subimos las escaleras: de forma autom\u00e1tica. Cuando tomamos el l\u00e1piz en la mano y lo enfrentamos al papel, plasmamos en \u00e9l una serie de gestos interiores que contiene informaci\u00f3n valiosa sobre el funcionamiento de nuestro cerebro, que es el que da la orden de escribir que luego los m\u00fasculos ejecutan. Nuestra escritura refleja detalles de nuestro inconsciente y de nuestra forma de ser.<\/p>\n<p>En ese sentido, el an\u00e1lisis grafol\u00f3gico de la escritura es un procedimiento mediante el cual, un graf\u00f3logo experto se dedica a estudiar un manuscrito hecho con anterioridad o pedido especialmente para estudiar la graf\u00eda de la persona (este es un recurso com\u00fan en casos de fraude fiscal, estafas y afines).<\/p>\n<h3><strong>\u00bfQu\u00e9 analiza un graf\u00f3logo? <\/strong><\/h3>\n<p>El acercamiento del graf\u00f3logo es hol\u00edstico, por decirlo de alguna manera. Le interesa analizar la inclinaci\u00f3n de las letras, la direcci\u00f3n, la presi\u00f3n del bol\u00edgrafo o el l\u00e1piz contra el papel, la velocidad de la escritura, el orden y la continuidad de las palabras. M\u00e1s all\u00e1 de lo que se ha escrito, se analizan posibles temblores a la hora de marcar el trazo, la elevaci\u00f3n de las may\u00fasculas y las min\u00fasculas, la forma de cada letra, las fracturas de las palabras, los retoques y las terminaciones.<\/p>\n<h4><strong>\u00bfPara qu\u00e9 es \u00fatil un estudio grafol\u00f3gico? <\/strong><\/h4>\n<p>Los estudios grafol\u00f3gicos son necesarios para conocer detalles ocultos sobre la personalidad y el car\u00e1cter de quien escribe. Con su aplicaci\u00f3n, se puede llegar a algunas conclusiones interesantes:<\/p>\n<ul>\n<li>El orden con el que se disponen las palabras en el papel refleja si la persona tiene o no un equilibrio interno, su capacidad de estar en el mundo y de transitar por \u00e9l.<\/li>\n<li>La forma de las letras y las vocales refleja el nivel cultural y el comportamiento social.<\/li>\n<li>El tama\u00f1o de las letras habla del nivel de autoestima, inteligencia y concentraci\u00f3n que se tiene.<\/li>\n<li>La presi\u00f3n que ejerza sobre el papel refleja la energ\u00eda vital y la fuerza con la que siente.<\/li>\n<li>La direcci\u00f3n de las palabras refleja el estado de \u00e1nimo, la voluntad, el sentido del humor y la visi\u00f3n de mundo que se tiene.<\/li>\n<li>La inclinaci\u00f3n es uno de los factores m\u00e1s relevadores de la graf\u00eda, pues dice mucho sobre las relaciones con las dem\u00e1s personas, los afectos y las pasiones.<\/li>\n<li>La velocidad con la que se escribe refleja la agilidad mental.<\/li>\n<li>La continuidad de las palabras dice mucho sobre los v\u00ednculos que creamos con otras personas, el sentido l\u00f3gico y la intuici\u00f3n.<strong><br \/>\n<\/strong><\/li>\n<\/ul>\n<h5><strong>\u00bfQu\u00e9 usos tiene la grafolog\u00eda? <\/strong><\/h5>\n<p>Aunque se pueda pensar lo contrario, analizar la manera de escribir de las personas no es una ciencia exacta como las matem\u00e1ticas, ni funciona con f\u00f3rmulas infalibles. Por el contrario, se trata de una herramienta que bien usada puede brindarnos informaci\u00f3n extra muy valiosa imposible de conseguir de alguna otra manera. Muchos profesionales de los recursos humanos conf\u00edan en la grafolog\u00eda para cubrir vacantes con los mejores candidatos posibles. Son igualmente \u00fatiles en estudios forenses, en el \u00e1mbito docente, en el \u00e1rea de la salud y hasta en estudios sobre compatibilidad entre parejas.<\/p>\n<p>Existen dos direcciones de aplicaci\u00f3n: la grafoterapia, que busca ayuda en tratamientos y sanaci\u00f3n de personas con diferentes problemas, y la grafopatolog\u00eda, que ayuda en los procesos de diagn\u00f3stico.<\/p>\n<h6><strong>Interpretaciones grafol\u00f3gicas m\u00e1s frecuentes <\/strong><\/h6>\n<p>La grafolog\u00eda es un m\u00e9todo de an\u00e1lisis y estudio que requiere de la aplicaci\u00f3n de m\u00e9todos rigurosos. Un experto graf\u00f3logo es un observador innato, capaz de reconocer detalles que pasan desapercibidos ante el ojo humano, para luego relacionarlos de manera global y extraer hip\u00f3tesis y posibles conclusiones. \u00a0Algunos de los aspectos que m\u00e1s informaci\u00f3n les proporciona en un an\u00e1lisis de grafolog\u00eda son:<\/p>\n<p><strong>M\u00e1rgenes<\/strong><\/p>\n<p>No respetar los m\u00e1rgenes del espacio de escritura est\u00e1 asociado a personalidades introvertidas, mientras que los m\u00e1rgenes anchos relejan todo lo contrario.<\/p>\n<p><strong>Forma de las l\u00edneas de escritura <\/strong><\/p>\n<p>Las formas que adquieren las l\u00edneas al escribir dan mucha informaci\u00f3n sobre los estados de \u00e1nimo de la persona que escribe. Si las palabras suben hacia el cielo, se intuye una personalidad positiva y optimista detr\u00e1s, mientras que si las palabras tienden a ir hacia abajo se entiende que el estado de \u00e1nimo est\u00e1 deca\u00eddo, la persona est\u00e1 cansada, triste o descontenta. En el caso de graf\u00edas ondulantes, se interpreta inquietud e inestabilidad en la persona que escribe.<\/p>\n<p><strong>Letra grande vs. Letra peque\u00f1a <\/strong><\/p>\n<p>Las letras que miden menos de 1,5 mm indican introversi\u00f3n y pensamientos profundos. Las letras de m\u00e1s de 2, 5 mm reflejan una persona sociable con una visi\u00f3n amplia del mundo.<a href=\"https:\/\/www.emagister.com\/cursos-escuela-des-arts-cen-190328.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-96494 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/europea-des-arts.jpeg\" alt=\"\" width=\"220\" height=\"146\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/europea-des-arts.jpeg 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/europea-des-arts-80x53.jpeg 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/p>\n<p><strong>Intensidad <\/strong><\/p>\n<p>La presi\u00f3n con la que se escribe es uno de los elementos clave en un an\u00e1lisis grafol\u00f3gico, pues indica el nivel de energ\u00eda que tiene la persona, si es sensible o decidida, si es valiente o si esconde miedo.<\/p>\n<p><strong>Espacio entre palabras<\/strong><\/p>\n<p>Aunque parezca muy literal, el espacio que dejamos entre palabras refleja la distancia que solemos poner entre las personas y nosotros.<\/p>\n<p><strong>Inclinaci\u00f3n de las palabras <\/strong><\/p>\n<p>Una graf\u00eda inclinada hacia la derecha indica que la persona es sociable y tiene buenos dotes comunicativos, mientras que, si va inclinada hacia la izquierda, se trata de una persona a la que le cuesta decir lo que siente cuando lo siente.<\/p>\n<p>Como hemos podido ver, el an\u00e1lisis grafol\u00f3gico es una herramienta fascinante que nos permite conocernos y conocer m\u00e1s a profundidad a personas de todo tipo, pues nos da acceso a informaci\u00f3n reveladora que de otra manera ser\u00eda imposible de conseguir.<\/p>\n<p>\u00bfQuieres descubrir <a href=\"https:\/\/www.emagister.com\/cursos-escuela-des-arts-cen-190328.htm\" target=\"_blank\" rel=\"noopener\"><strong>toda la oferta formativa<\/strong><\/a> de la <strong>Escuela Des Arts<\/strong> para ampliar tus conocimientos y mejorar tu perfil profesional? Ponte en <a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\"><strong>contacto<\/strong> <\/a>con <strong>Emagister<\/strong> y te ayudaremos a encontrar el curso perfecto para ti.<\/p>\n<p>Si ya eres o has sido alumno de este centro y quieres contarnos tu experiencia, \u00a1queremos leerte! Deja tu opini\u00f3n gracias a este <a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\"><strong>formulario<\/strong><\/a> y ayuda otros estudiantes como t\u00fa a escoger mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para empezar a entenderlo, es necesario definirlo. El an\u00e1lisis grafol\u00f3gico es una ciencia dedicada a estudiar la personalidad, el temperamento &#8230; <a title=\"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/\" aria-label=\"M\u00e1s en Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":100662,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[3265,6420,6421,10864,11164],"class_list":["post-109517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-centros-de-formacion","tag-6420","tag-escuela-des-arts","tag-ij_sector_center_99997192958079401036578245575985_16","tag-noticias-centros-de-formacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de la Escuela Des Arts","link_faldon":"https:\/\/www.emagister.com\/escuela-des-arts-cursos-190328-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico\" \/>\n<meta property=\"og:description\" content=\"Para empezar a entenderlo, es necesario definirlo. El an\u00e1lisis grafol\u00f3gico es una ciencia dedicada a estudiar la personalidad, el temperamento ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T08:14:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1918\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico\",\"datePublished\":\"2020-11-19T08:14:16+00:00\",\"dateModified\":\"2021-04-27T08:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/\"},\"wordCount\":1189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Formaci\u00f3n-Profesional-2.jpg\",\"keywords\":[\"Centros de formaci\u00f3n\",\"99997192958079401036578245575985\",\"Escuela Des Arts\",\"ij_sector_center_99997192958079401036578245575985_16\",\"noticias centros de formaci\u00f3n\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/\",\"name\":\"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Formaci\u00f3n-Profesional-2.jpg\",\"datePublished\":\"2020-11-19T08:14:16+00:00\",\"dateModified\":\"2021-04-27T08:55:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Formaci\u00f3n-Profesional-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Formaci\u00f3n-Profesional-2.jpg\",\"width\":1918,\"height\":1280,\"caption\":\"Three happy students dressed casual using tablet for school project and sitting at desk in library.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/","og_locale":"es_ES","og_type":"article","og_title":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico","og_description":"Para empezar a entenderlo, es necesario definirlo. El an\u00e1lisis grafol\u00f3gico es una ciencia dedicada a estudiar la personalidad, el temperamento ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-11-19T08:14:16+00:00","article_modified_time":"2021-04-27T08:55:35+00:00","og_image":[{"width":1918,"height":1280,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico","datePublished":"2020-11-19T08:14:16+00:00","dateModified":"2021-04-27T08:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/"},"wordCount":1189,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg","keywords":["Centros de formaci\u00f3n","99997192958079401036578245575985","Escuela Des Arts","ij_sector_center_99997192958079401036578245575985_16","noticias centros de formaci\u00f3n"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/","url":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/","name":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg","datePublished":"2020-11-19T08:14:16+00:00","dateModified":"2021-04-27T08:55:35+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/03\/Formaci\u00f3n-Profesional-2.jpg","width":1918,"height":1280,"caption":"Three happy students dressed casual using tablet for school project and sitting at desk in library."},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/todo-lo-que-necesitas-saber-sobre-el-analisis-grafologico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Todo lo que necesitas saber sobre el an\u00e1lisis grafol\u00f3gico"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=109517"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109517\/revisions"}],"predecessor-version":[{"id":109749,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/109517\/revisions\/109749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/100662"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=109517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=109517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=109517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}