{"id":111809,"date":"2021-01-25T10:41:56","date_gmt":"2021-01-25T09:41:56","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=111809"},"modified":"2021-04-27T10:23:59","modified_gmt":"2021-04-27T08:23:59","slug":"el-calculo-del-gravamen-que-es-y-como-hacerlo","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/","title":{"rendered":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las personas que hacen vida econ\u00f3mica en cualquier pa\u00eds deben tributar en el Estado en el que se encuentran. Dentro de las distintas tasas imponibles, se encuentra el gravamen. Esta, a su vez, tiene distintos tipos. En el siguiente art\u00edculo se profundiza sobre ella, con el objetivo de simplificar su comprensi\u00f3n y funcionamiento.<\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p class=\"wp-block-paragraph\"><strong>Gravamen: en qu\u00e9 consiste<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el concepto de la Real Academia Espa\u00f1ola, <strong>el gravamen es una carga impuesta sobre un inmueble o sobre un caudal.<\/strong> Por tanto, este impuesto se aplica a un inmueble o bien, dependiendo del uso que se haga de este. La definici\u00f3n puede variar seg\u00fan su aplicaci\u00f3n, ya que tambi\u00e9n es utilizada en materia civil, mercantil y fiscal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este caso, se vincula con el valor impositivo. El gravamen es una cifra o porcentaje que sirve para marcar el valor del impuesto que se debe abonar al Estado. En Espa\u00f1a, por lo general, se manejan dos grandes clasificaciones de gravamen. La primera establece un 30% sobre el Impuesto de Sociedades. La segunda incluye una serie de grav\u00e1menes especiales, que se abordan m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo calcular el gravamen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para saber cu\u00e1l es la cuota \u00edntegra, es necesario aplicar el gravamen sobre la base imponible. <strong>Este monto marca la capacidad econ\u00f3mica del contribuyente y puede estar especificada por cantidades dinerarias o no dinerarias<\/strong>. Si existe alguna reducci\u00f3n, se calcular\u00e1 a partir de la base liquidable. \u00bfCu\u00e1l es la base liquidable? La que resta de las reducciones sobre la base imponible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tipos de gravamen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clasificaci\u00f3n del gravamen est\u00e1 sujeta a la base imponible. A continuaci\u00f3n se profundiza sobre el gravamen general y los grav\u00e1menes especiales.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.emagister.com\/fintech-business-medical-school-cursos-1148684-centrodetalles.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"147\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/fintech-school.jpg\" alt=\"\" class=\"wp-image-93561\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/fintech-school.jpg 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/fintech-school-80x53.jpg 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gravamen general<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consiste en el impuesto sobre la Renta de las Personas F\u00edsicas (IRPF). <strong>Est\u00e1 regulado como Impuesto de Sociedades. Consiste en un 30% y se aplica en per\u00edodos impositivos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Grav\u00e1menes especiales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos est\u00e1n sujetos al tipo de sociedad, persona o bien al que se le aplicar\u00e1 el porcentaje. Pueden ser de:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>35%, en casos en los que las entidades est\u00e9n vinculadas a hidrocarburos<\/li><li>25% en el caso de las uniones, federaciones y confederaciones de cooperativas.<\/li><li>20% si se trata de sociedades cooperativas y que cuenten con protecci\u00f3n fiscal.<\/li><li>10% e incluso el 1% en el caso del fondo de regulaci\u00f3n, con car\u00e1cter p\u00fablico del mercado hipotecario.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Formas de aplicaci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se har\u00e1 de manera fija o porcentual, dependiendo del tipo de gravamen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El gravamen espec\u00edfico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se aplicar\u00e1 de acuerdo con bases imponibles no monetarias. Se impondr\u00e1 para seg\u00fan la cantidad de dinero por unidad de base imponible. Por tanto, <strong>este tipo de gravamen se base en una cuant\u00eda fija o variable gradual<\/strong>. Se marca seg\u00fan la cantidad y se adec\u00faa seg\u00fan una escala de valores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al\u00edcuotas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se aplica sobre una base dineraria. Las al\u00edcuotas tambi\u00e9n pueden ser definidas como porcentuales y est\u00e1n divididas en tres grupos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Porcentual: el IVA, cuando el porcentaje es fijo o \u00fanico.<\/li><li>Progresivo: el IRPF, se adapta seg\u00fan la funci\u00f3n de la base imponible.<\/li><li>Represivo: en el caso de que disminuyen al aumentar la base imponible.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQuieres descubrir <a href=\"https:\/\/www.emagister.com\/fintech-business-medical-school-cursos-1148684-centrodetalles.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>toda la oferta formativa<\/strong><\/a> de <strong>Fintech School<\/strong>? Ponte en <a rel=\"noreferrer noopener\" href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\"><strong>contacto<\/strong><\/a><strong> <\/strong>con <strong>Emagister <\/strong>y te ayudaremos a encontrar el curso perfecto para ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si eres ya un estudiante de este centro y deseas contarnos tu experiencia, \u00a1deja tu opini\u00f3n gracias a este <a rel=\"noreferrer noopener\" href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\"><strong>formulario<\/strong><\/a> y ayuda otros estudiantes como t\u00fa a escoger mejor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las personas que hacen vida econ\u00f3mica en cualquier pa\u00eds deben tributar en el Estado en el que se encuentran. Dentro &#8230; <a title=\"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/\" aria-label=\"M\u00e1s en El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":111919,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[2832,3265,10141,10507,10508],"class_list":["post-111809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-noticiaselpais","tag-10507","tag-fintech-school","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de Fintech School","link_faldon":"https:\/\/www.emagister.com\/fintech-business-medical-school-cursos-1148684-centrodetalles.htm","link_texto_faldon":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo\" \/>\n<meta property=\"og:description\" content=\"Las personas que hacen vida econ\u00f3mica en cualquier pa\u00eds deben tributar en el Estado en el que se encuentran. Dentro ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-25T09:41:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:23:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo\",\"datePublished\":\"2021-01-25T09:41:56+00:00\",\"dateModified\":\"2021-04-27T08:23:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/GettyImages-1182777182.jpg\",\"keywords\":[\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"noticiasElPais\",\"99997192958079401036578245628525\",\"Fintech School\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/\",\"name\":\"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/GettyImages-1182777182.jpg\",\"datePublished\":\"2021-01-25T09:41:56+00:00\",\"dateModified\":\"2021-04-27T08:23:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/GettyImages-1182777182.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/GettyImages-1182777182.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Business document report on paper and tablet with sales data and financial business growth graph on table background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/el-calculo-del-gravamen-que-es-y-como-hacerlo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/","og_locale":"es_ES","og_type":"article","og_title":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo","og_description":"Las personas que hacen vida econ\u00f3mica en cualquier pa\u00eds deben tributar en el Estado en el que se encuentran. Dentro ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2021-01-25T09:41:56+00:00","article_modified_time":"2021-04-27T08:23:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo","datePublished":"2021-01-25T09:41:56+00:00","dateModified":"2021-04-27T08:23:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg","keywords":["Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","noticiasElPais","99997192958079401036578245628525","Fintech School"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/","url":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/","name":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg","datePublished":"2021-01-25T09:41:56+00:00","dateModified":"2021-04-27T08:23:59+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/01\/GettyImages-1182777182.jpg","width":1920,"height":1280,"caption":"Business document report on paper and tablet with sales data and financial business growth graph on table background."},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/el-calculo-del-gravamen-que-es-y-como-hacerlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"El c\u00e1lculo del gravamen: qu\u00e9 es y c\u00f3mo hacerlo"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/111809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=111809"}],"version-history":[{"count":6,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/111809\/revisions"}],"predecessor-version":[{"id":111924,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/111809\/revisions\/111924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/111919"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=111809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=111809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=111809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}