{"id":112316,"date":"2021-02-04T09:56:32","date_gmt":"2021-02-04T08:56:32","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=112316"},"modified":"2021-04-27T10:17:15","modified_gmt":"2021-04-27T08:17:15","slug":"efectos-especiales-que-son-y-como-funcionan","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/","title":{"rendered":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el mundo profesional del arte digital existen millones de posibilidades para lograr un objetivo espec\u00edfico. Todo esto est\u00e1 relacionado con los efectos especiales y la magia que producen. El conocimiento adecuado junto con las herramientas apropiadas son los factores clave para llevar a cabo un proyecto en el que los efectos especiales son los protagonistas; no obstante, estos puntos no sirven de nada si no existe el elemento m\u00e1s importante, la pasi\u00f3n, que va acompa\u00f1ada de la creatividad.<\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p class=\"wp-block-paragraph\">Si te interesa enfocar tu desarrollo profesional en este campo y te apasiona todo lo que tiene que ver con efectos especiales, en el art\u00edculo de hoy te contamos en detalle c\u00f3mo se realiza el proceso creativo de los efectos especiales y cu\u00e1les son sus principales caracter\u00edsticas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 son los efectos especiales?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los efectos especiales se refieren a las t\u00e9cnicas y elementos que se utilizan, espec\u00edficamente en el mundo del cine y la televisi\u00f3n, para crear objetos, escenarios, personajes, ambientes o realidades que no existen, pero que han sido ideadas con un fin especial para cada proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los ejemplos m\u00e1s apropiados sobre efectos especiales es en la pel\u00edcula de Jurassic Park. Este es un film en el que fue necesario recrear dinosaurios con una imagen muy cercana a la real. Otra de las pel\u00edculas m\u00e1s reconocidas por sus maravillosos efectos especiales es Avatar, una pieza que ha logrado crear un ambiente de Pandora\u2026 un mundo de total de fantas\u00eda creado gracias a los efectos especiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra de las sagas caracterizadas por sus efectos especiales es Star Wars, una serie de pel\u00edculas traen a la pantalla la creaci\u00f3n de un mundo totalmente diferente e irreal y c\u00f3mo ha evolucionado a trav\u00e9s de cada entrega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En general, los efectos especiales suelen aplicarse en la etapa de postproducci\u00f3n de la pel\u00edcula, es decir, despu\u00e9s del rodaje de la misma. En esta fase tambi\u00e9n se realizan las correcciones que se requieren (colores, iluminaci\u00f3n, sonido, etc.).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tipos de efectos especiales<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Existe un mill\u00f3n de efectos especiales, todo depende del objetivo que se quiera lograr. A continuaci\u00f3n, te contamos c\u00f3mo se clasifican los efectos especiales:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos \u00f3pticos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los efectos \u00f3pticos son los m\u00e1s conocidos y quiz\u00e1 los m\u00e1s antiguos. Como su nombre lo indica, se enfocan en la manipulaci\u00f3n de una imagen que ya ha sido tomada. Algunos de los m\u00e1s comunes son:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Stop-motion.<\/strong> Es una t\u00e9cnica que se basa en simular movimiento en un objeto est\u00e1tico. Adem\u00e1s, existe una variante, el <strong>Go-motion<\/strong>, y uno de los ejemplos en donde mejor se puede observar esta t\u00e9cnica es en la pel\u00edcula \u201cPesadilla antes de navidad\u201d.<\/li><li><strong>Retroproyecci\u00f3n.<\/strong> En este caso el efecto consiste en grabar al actor mientras que en el escenario se proyecta una imagen en una pantalla. Para tener una idea m\u00e1s clara, recordemos la escena de la avioneta en la pel\u00edcula \u201cCon la muerte en los talones\u201d.<\/li><li><strong>Rotoscopia<\/strong>. La idea de esta t\u00e9cnica es crear cada uno de los fotogramas de la animaci\u00f3n a partir de una imagen real, es decir, se realiza un calco para dar continuidad a la animaci\u00f3n. La pel\u00edcula de \u201cBlancanieves y los siete enanitos\u201d es un claro ejemplo de esta t\u00e9cnica.<\/li><li><strong>Matte Painting<\/strong>. Es una t\u00e9cnica en donde se realiza una pintura o decoraci\u00f3n sobre un vidrio dejando libre el espacio en donde debe ubicarse el actor. En las primeras pel\u00edculas de la saga de Star Wars se us\u00f3 mucho este m\u00e9todo.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos digitales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se refieren espec\u00edficamente a todos los efectos creados por ordenador, bien sean im\u00e1genes creadas desde cero o la modificaci\u00f3n de tomas reales. Entre los efectos digitales m\u00e1s conocidos tenemos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Morphing.<\/strong> Es una t\u00e9cnica por medio de la cual se realiza la transformaci\u00f3n de una imagen real a trav\u00e9s de la animaci\u00f3n por ordenador. Por ejemplo, en la pel\u00edcula de \u201cStar Trek VI\u201d hay una escena donde el rostro de una alien\u00edgena se transforma en el del capit\u00e1n Kirk.<\/li><li><strong>CGI \u2013<\/strong> <strong>Computer Generated Imagery<\/strong>. La creaci\u00f3n de im\u00e1genes por ordenador consiste en el desarrollo de im\u00e1genes desde cero, de manera que no se necesita ning\u00fan elemento fotogr\u00e1fico. En la pel\u00edcula de \u201cEl se\u00f1or de los anillos\u201d cuando se muestran las multitudes podemos apreciar este efecto.<\/li><li><strong>Motion Capture<\/strong>. El famoso MOCAP es un proceso de grabaci\u00f3n en el cual se captan los movimientos de las personas (o animales) para llevarlos a un personaje digital; de esta manera se logra que dicho personaje luzca m\u00e1s real. La representaci\u00f3n que mejor ejemplifica esta t\u00e9cnica la podemos ver en la pel\u00edcula \u201cTed\u201d, que utiliz\u00f3 esta tecnolog\u00eda para dar movimiento al osito protagonista.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos mec\u00e1nicos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los efectos mec\u00e1nicos son todos los procesos que se realizan mientras se est\u00e1 rodando la pel\u00edcula. Para ellos, es necesario el uso de maquetas mec\u00e1nicas o cualquier tipo de escenograf\u00eda que genere el ambiente esperado. En la pel\u00edcula \u201cGremlins\u201d los mu\u00f1ecos fueron creados a partir de marionetas con un sistema de cableado interno para darles la movilidad necesaria.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.emagister.com\/cursos-ifp-innovacion-formacion-profesional-grupo-planeta-cen-145826.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"147\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/iFP.png\" alt=\"\" class=\"wp-image-93723\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/iFP.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/10\/iFP-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos de sonido<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como su nombre lo indica, los efectos de sonido pretenden generar cierto impacto en la percepci\u00f3n auditiva de los espectadores. Aqu\u00ed, la idea es utilizar distintos sonidos pregrabados para aplicarlos a las escenas que lo requieran, aunque tambi\u00e9n estos sonidos pueden ser grabados en un estudio para imitar alg\u00fan sonido espec\u00edfico de ambiente. Por ejemplo, para la pel\u00edcula \u201cEl doctor Frankenstein\u201d se cre\u00f3 el sonido \u201cCastle Thunder\u201d, que fue utilizado m\u00e1s adelante en films como \u201cCazafantasmas\u201d o \u201cRegreso al futuro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Efectos de maquillaje<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El maquillaje es otro de los efectos que ofrece una infinidad de posibilidades. Aqu\u00ed se puede utilizar desde el maquillaje b\u00e1sico, hasta m\u00e1scaras e inclusive pr\u00f3tesis. La pel\u00edcula \u201cEl laberinto del fauno\u201d es una clara representaci\u00f3n de los efectos de maquillaje con pr\u00f3tesis.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Perfil del experto en efectos especiales<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a la alta demanda de profesionales en este campo, la labor del experto en efectos especiales exige una formaci\u00f3n s\u00f3lida, pr\u00e1ctica y de primer nivel. Por ello, <strong>IFP \u2013 Grupo Planeta<\/strong> pone a disposici\u00f3n de la comunidad el ciclo de <strong>Formaci\u00f3n Profesional de Grado Superior en Animaciones 3D, Juegos y Entornos Interactivos<\/strong>. Con este programa aprender\u00e1s acerca de todo el proceso de la creaci\u00f3n de efectos especiales, incluyendo la animaci\u00f3n en 2D y 3D; el dise\u00f1o, dibujo y modelaci\u00f3n de animaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>Grado Superior de Animaci\u00f3n 3D, Juegos y Entornos Interactivos<\/strong> se encuentra disponible en la modalidad presencial, tanto para las sede de Madrid como la de Barcelona. Cada una de las sedes de iFP cuenta con unas instalaciones totalmente adecuadas para el desarrollo del proceso de aprendizaje, adem\u00e1s de las mejores herramientas en el \u00e1rea para llevar a cabo formaci\u00f3n pr\u00e1ctica y totalmente actualizada. Entre los principales programas que se manejan en el aula tenemos, por ejemplo, Unity, 3DSMax, Substance, Zbrush y Autodesk MAYA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ciclos formativos de Grado Superior en Animaciones 3D, Juegos y Entornos Interactivos se encuentran disponibles ahora en las sedes de Madrid y Barcelona. Conoce todos los detalles aqu\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQuieres conocer <strong><a href=\"https:\/\/www.emagister.com\/cursos-ifp-innovacion-formacion-profesional-grupo-planeta-cen-145826.htm\" target=\"_blank\" rel=\"noreferrer noopener\">toda la oferta formativa<\/a><\/strong> de <strong>IFP \u2013 Grupo Planeta<\/strong>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si es as\u00ed, no dudes en <a href=\"https:\/\/www.emagister.com\/contact\/center\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>contactar<\/strong><\/a> a <strong>Emagister<\/strong> para que uno de nuestros profesionales te brinde toda la informaci\u00f3n que requieras. O si ya perteneces a la comunidad de estudiantes de este centro, comparte tu experiencia con nosotros en este <a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>formulario<\/strong><\/a> y deja que nuevos estudiantes conozcan tus opiniones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mundo profesional del arte digital existen millones de posibilidades para lograr un objetivo espec\u00edfico. Todo esto est\u00e1 relacionado &#8230; <a title=\"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/\" aria-label=\"M\u00e1s en Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":112321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[2832,3264,3265,6947,10142,10329,10348,12633,1273],"class_list":["post-112316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-noticias-de-centros-de-formacion","tag-3264","tag-centros-de-formacion","tag-efectos-especiales","tag-noticiaslavanguardia","tag-efectos-digitales","tag-efectos-de-cine","tag-ifp-grupo-planeta-2","tag-cine","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"mostrar_faldon":"-1","texto_faldon":"Descubre toda la oferta formativa de IFP \u2013 Grupo Planeta","link_faldon":"https:\/\/www.emagister.com\/ifp-innovacion-formacion-profesional-grupo-planeta-cursos-145826-centrodetalles.htm","link_texto_faldon":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan\" \/>\n<meta property=\"og:description\" content=\"En el mundo profesional del arte digital existen millones de posibilidades para lograr un objetivo espec\u00edfico. Todo esto est\u00e1 relacionado ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-04T08:56:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:17:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan\",\"datePublished\":\"2021-02-04T08:56:32+00:00\",\"dateModified\":\"2021-04-27T08:17:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/\"},\"wordCount\":1315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/GettyImages-1268544459.jpg\",\"keywords\":[\"Noticias de centros de formaci\u00f3n\",\"99997192958079401036578245531488\",\"Centros de formaci\u00f3n\",\"efectos especiales\",\"noticiasLaVanguardia\",\"efectos digitales\",\"efectos de cine\",\"IFP \u2013 Grupo Planeta\",\"cine\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/\",\"name\":\"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/GettyImages-1268544459.jpg\",\"datePublished\":\"2021-02-04T08:56:32+00:00\",\"dateModified\":\"2021-04-27T08:17:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/GettyImages-1268544459.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/GettyImages-1268544459.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Glowing neon Hockey coach icon isolated on blue background. Vector Illustration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/efectos-especiales-que-son-y-como-funcionan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/","og_locale":"es_ES","og_type":"article","og_title":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan","og_description":"En el mundo profesional del arte digital existen millones de posibilidades para lograr un objetivo espec\u00edfico. Todo esto est\u00e1 relacionado ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2021-02-04T08:56:32+00:00","article_modified_time":"2021-04-27T08:17:15+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan","datePublished":"2021-02-04T08:56:32+00:00","dateModified":"2021-04-27T08:17:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/"},"wordCount":1315,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg","keywords":["Noticias de centros de formaci\u00f3n","99997192958079401036578245531488","Centros de formaci\u00f3n","efectos especiales","noticiasLaVanguardia","efectos digitales","efectos de cine","IFP \u2013 Grupo Planeta","cine"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/","url":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/","name":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg","datePublished":"2021-02-04T08:56:32+00:00","dateModified":"2021-04-27T08:17:15+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/02\/GettyImages-1268544459.jpg","width":1280,"height":1280,"caption":"Glowing neon Hockey coach icon isolated on blue background. Vector Illustration"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/efectos-especiales-que-son-y-como-funcionan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Efectos especiales: qu\u00e9 son y c\u00f3mo funcionan"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/112316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=112316"}],"version-history":[{"count":6,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/112316\/revisions"}],"predecessor-version":[{"id":112326,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/112316\/revisions\/112326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/112321"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=112316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=112316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=112316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}