{"id":12413,"date":"2014-02-06T12:45:47","date_gmt":"2014-02-06T11:45:47","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=12413"},"modified":"2021-06-15T09:41:40","modified_gmt":"2021-06-15T07:41:40","slug":"todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/","title":{"rendered":"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC"},"content":{"rendered":"<p>La formaci\u00f3n online est\u00e1 en alza. En Emagister hemos comprobado que la formaci\u00f3n online aumenta un 21% cada a\u00f1o desde el 2010.<\/p>\n<p>A pesar de ello, todav\u00eda existen reticencias.&nbsp;Hemos ido a buscar a un experto para que despeje tus dudas. Carles Sigal\u00e9s es Vicerrector de Docencia y Aprendizaje de la UOC (Universitat Oberta de Catalunya),<\/p>\n<p><!--more--> con 50 mil estudiantes y 20 a\u00f1os de experiencia en formaci\u00f3n a distancia. Le hemos trasladado tus dudas.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12416\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/02\/vicerector-199x300.jpg\" alt=\"vicerector\" width=\"199\" height=\"300\"><\/p>\n<p><strong>\u00bfCree que todav\u00eda hay reticencias a la formaci\u00f3n online? \u00bfPor qu\u00e9?<\/strong><\/p>\n<p>S\u00ed, seguramente, por varias razones. Se mezclan tres cosas:<\/p>\n<ul>\n<li>La formaci\u00f3n online utiliza un&nbsp;medio, el de las TIC, que para una parte de la poblaci\u00f3n aun es un medio extra\u00f1o y existe una&nbsp;cierta reticencia. Es una cuesti\u00f3n generacional, las personas de m\u00e1s edad todav\u00eda se sienten&nbsp;poco c\u00f3modas y no le saben sacar todo el partido.<\/li>\n<li>Hay una parte del sistema universitario, personas que est\u00e1n en las direcciones y puestos de&nbsp;responsabilidad en universidades presenciales, que nunca han trabajado en un entorno online&nbsp;y desconf\u00edan que en este tipo de entorno de ense\u00f1anza se d\u00e9 el mismo grado de aprendizaje&nbsp;que en la ense\u00f1anza presencial.<\/li>\n<li>Tambi\u00e9n pueden haber intereses corporativos: es mejor&nbsp;que la ense\u00f1anza online no prospere porque si prospera pone en peligro otros entornos m\u00e1s&nbsp;tradicionales de ense\u00f1anza<\/li>\n<\/ul>\n<p>No toda la ense\u00f1anza online es de la misma calidad. Lo mismo que pasa con la presencial. En&nbsp;Internet todo es posible, adem\u00e1s de cursos online de calidad contrastada, se ofrecen cursos&nbsp;con muy poco acompa\u00f1amiento, utilizando contenidos de dudosa calidad que tambi\u00e9n quieren&nbsp;hacerse hueco en la oferta online.<\/p>\n<p><strong>\u00bfHa costado cambiar la mentalidad?<\/strong><\/p>\n<p>Yo creo que s\u00ed, por varias razones. Hay un cambio generacional. La generaci\u00f3n que ahora&nbsp;est\u00e1 llegando a la universidad es la primera generaci\u00f3n que ha vivido en Internet toda la vida.<\/p>\n<p>Cuando ellos nacieron Internet ya exist\u00eda. El problema para las generaciones anteriores ha sido&nbsp;la falta de dominio y conocimiento de los entornos virtuales. Para las generaciones futuras eso&nbsp;no ser\u00e1 un problema, ser\u00e1 su medio.<\/p>\n<p>Las reticencias, creo que van a caer en picado y veremos que lo m\u00e1s normal o habitual ser\u00e1&nbsp;que todas las ofertas educativas tengan una parte importante de desarrollo en Internet.<\/p>\n<p><strong>\u00bfDesaparecer\u00e1 la formaci\u00f3n presencial?<\/strong><\/p>\n<p>Yo no lo creo. Esto va a promover&nbsp;la desaparici\u00f3n de aquellas universidades presenciales que no cumplan con unos m\u00ednimos&nbsp;requisitos de calidad porque no podr\u00e1n competir con la formaci\u00f3n online.<\/p>\n<p><strong>El alumno que cursa esta formaci\u00f3n, \u00bfdebe tener unas caracter\u00edsticas particulares? (en&nbsp;cuanto a h\u00e1bitos de estudio, fuerza de voluntad, ser autodidacta\u2026)<\/strong><\/p>\n<p>Hay que distinguir entre:<\/p>\n<ul>\n<li>los alumnos j\u00f3venes que cada vez m\u00e1s utilizan Internet como forma&nbsp;complementaria a su formaci\u00f3n habitual; \u00e9stos tienen que hacer el mismo esfuerzo que&nbsp;hac\u00edan en el pasado.<\/li>\n<li>gente que intenta compaginar sus estudios con el trabajo,&nbsp;que le ocupa muchas horas, o con otras responsabilidades familiares, etc. Ah\u00ed esa fuerza de&nbsp;voluntad, perseverancia, capacidad de auto disciplinarse es muy importante. Lo es sobre&nbsp;todo porque compaginar estudios con una vida laboral intensa y una vida familiar llena de&nbsp;ocupaciones es muy dif\u00edcil.<\/li>\n<\/ul>\n<p>Por lo tanto, yo dir\u00eda que es m\u00e1s la situaci\u00f3n personal que cada&nbsp;estudiante tiene que no el hecho de ser una formaci\u00f3n online o presencial.<\/p>\n<p>Los estudiantes que tenemos en la UOC, la mayor\u00eda, son estudiantes que trabajan, por la edad&nbsp;que tienen suelen tener familia propia, hijos y responsabilidades. Por eso nuestros estudiantes&nbsp;son especialmente competentes en ese tipo de cuestiones, el entorno online les facilita&nbsp;muchas cosas.<\/p>\n<p><strong>\u00bfQu\u00e9 ventajas educativas tiene la formaci\u00f3n a distancia?<\/strong><\/p>\n<p>Los estudiantes de la formaci\u00f3n online tienen acceso a unos recursos de aprendizaje mucho&nbsp;m\u00e1s ricos que los que uno puede ver en un aula en una universidad presencial, donde aun&nbsp;hoy puede verse la pizarra, retroproyectores y mucho power point. La educaci\u00f3n online bien&nbsp;dise\u00f1ada permite simulaciones, utilizaci\u00f3n de medios audiovisuales, realidad aumentada\u2026.<\/p>\n<p>Una serie de recursos que bien utilizados ayudan a la comprensi\u00f3n de conceptos y adquisici\u00f3n&nbsp;de competencias tanto o m\u00e1s que la formaci\u00f3n presencial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12418\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/02\/uoc2-300x199.jpg\" alt=\"uoc2\" width=\"300\" height=\"199\"><\/p>\n<p><strong>\u00bfAlg\u00fan aspecto a mejorar?<\/strong><\/p>\n<p>Siempre hay aspectos a mejorar. Los sistemas de apoyo al aprendizaje basados en las TIC&nbsp;est\u00e1n en constante evoluci\u00f3n. Hay que estar al d\u00eda para poder elegir de forma cr\u00edtica los&nbsp;m\u00e9todos y la tecnolog\u00eda apropiada para mejorar todos los aspectos de apoyo al aprendizaje,&nbsp;en un entorno que debe tender a la m\u00e1xima flexibilidad y personalizaci\u00f3n. Hoy m\u00e1s que nunca&nbsp;hay mucho camino por recorrer.<\/p>\n<p><strong>\u00bfC\u00f3mo se sustituye la figura del tutor?&nbsp;<\/strong><\/p>\n<p>Hay ofertas online que cogen lo peor de la ense\u00f1anza presencial y lo trasladan al medio online.&nbsp;Entendiendo por ense\u00f1anza presencial una clase en que el profesor est\u00e1 una hora hablando y&nbsp;hay 150 personas escuchando, pero no hay posibilidad de interacci\u00f3n, de matiz, de pregunta&nbsp;(eso a veces sucede).&nbsp;Nosotros no entendemos as\u00ed la educaci\u00f3n presencial ni la online.<\/p>\n<ul>\n<li>Quien aprende debe mantenerse activo, interactuar, realizar preguntas, actividades,&nbsp;plantear problemas, resolver casos\u2026 y a partir de ah\u00ed el profesor m\u00e1s bien se convierte en un&nbsp;acompa\u00f1ante, en un ayudante, un gu\u00eda, no en alguien que est\u00e1 hablando largamente sobre&nbsp;un tema. Esta clase magistral puede cada vez m\u00e1s f\u00e1cilmente ser sustituida por un video, una&nbsp;lectura, etc.<\/li>\n<\/ul>\n<p>El valor a\u00f1adido del profesorado est\u00e1 en las ayudas que da al estudiante cuando \u00e9l le plantea&nbsp;las dudas que le sugiere el aprendizaje, m\u00e1s que en reproducir elementos que uno puede leer,&nbsp;ver o escuchar.<\/p>\n<p><strong>\u00bfQ\u00fae funciones debe tener el tutor?<\/strong><\/p>\n<p>La figura del tutor en la educaci\u00f3n virtual tiene dos funciones fundamentales:<\/p>\n<ul>\n<li>La primera es preparatoria, tiene que preparar todo el entorno que va a utilizar el alumnado&nbsp;en su proceso de aprendizaje: seleccionar materiales, realizar un plan docente, plantear&nbsp;una propuesta de evaluaci\u00f3n, de actividades de aprendizaje \u2026..y a partir de ah\u00ed, ayudar al&nbsp;estudiante en ese proceso.<\/li>\n<\/ul>\n<ul>\n<li>El tutor tiene que estar completamente implicado en el proceso de aprendizaje,&nbsp;no tiene sentido evaluar al final del curso, tiene que haber una evaluaci\u00f3n continuada&nbsp;que permita ese tipo de intervenciones. Eso se hace adapt\u00e1ndose a los medios que se&nbsp;utilicen en cada curso, pueden ser: ejercicios, resoluci\u00f3n de casos, problemas, peque\u00f1os&nbsp;ex\u00e1menes\u2026..toda la variedad que tambi\u00e9n existe en la presencial.<\/li>\n<\/ul>\n<p><strong>\u00bfEl nivel de exigencia es el mismo que en la formaci\u00f3n presencial?<\/strong><\/p>\n<p>El nivel de exigencia no lo determina el tipo de formaci\u00f3n, lo determina el nivel de exigencia&nbsp;que cada instituci\u00f3n plantea a la hora de aprobar una determinada asignatura, o un&nbsp;determinado curso.<\/p>\n<ul>\n<li>La tendencia intuitiva hace pensar que como uno no va a clase no tiene que esforzarse.&nbsp;Nada m\u00e1s lejos de la realidad. Los estudiantes le dir\u00e1n que no es m\u00e1s f\u00e1cil aprobar en una&nbsp;universidad online que presencial, que tienen que trabajar muchas horas y que deben de&nbsp;organizarse mejor.<\/li>\n<\/ul>\n<p>No hay&nbsp;ninguna raz\u00f3n por lo que un curso online tenga que ser m\u00e1s f\u00e1cil, lo que s\u00ed que hace es facilitar&nbsp;mucho m\u00e1s la vida de los estudiantes, porque les permite m\u00e1s flexibilidad, m\u00e1s variedad&nbsp;de medios, mayor interacci\u00f3n con compa\u00f1eros y profesores, y eso ayuda seguramente a&nbsp;conseguir esos aprendizajes.<\/p>\n<p><strong>\u00bfLos t\u00edtulos conseguidos tienen la misma validez?<\/strong><\/p>\n<p>Por supuesto. En Espa\u00f1a y en muchos otros pa\u00edses. En el caso de la UOC somos una&nbsp;universidad en toda regla, hacemos lo mismo que hacen las otras universidades: investigar,&nbsp;hacer docencia, utilizamos el mismo sistema de verificaci\u00f3n y acreditaci\u00f3n de t\u00edtulos, que se&nbsp;aplican en todas las universidades y somos evaluados por las mismas agencias de calidad.<\/p>\n<p>Cuando nosotros impartimos un t\u00edtulo oficial en Psicolog\u00eda o un M\u00e1ster en Fiscalidad, por&nbsp;ejemplo, ese t\u00edtulo tiene el mismo valor que si uno lo realizara en una universidad presencial&nbsp;de las m\u00e1s reconocidas que pueda haber. Es un t\u00edtulo oficial en toda regla.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12420\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/02\/uoc3-300x112.jpg\" alt=\"uoc3\" width=\"300\" height=\"112\"><\/p>\n<p><strong>\u00bfQu\u00e9 formaciones son las m\u00e1s solicitadas?<\/strong><\/p>\n<p>En ese sentido la UOC no se distingue mucho del resto de universidades espa\u00f1olas. Las&nbsp;titulaciones m\u00e1s populares son aquellas vinculadas al \u00e1rea de econom\u00eda y empresa, como&nbsp;el grado de ADE, o las titulaciones de psicolog\u00eda, derecho, ingenier\u00eda inform\u00e1tica y tambi\u00e9n&nbsp;hay porcentualmente muchos estudiantes que est\u00e1n cursando titulaciones de humanidades,&nbsp;ciencias de la informaci\u00f3n y la comunicaci\u00f3n, educaci\u00f3n, etc. Tambi\u00e9n estamos creciendo en&nbsp;ofertas de masteres y aqu\u00ed hay mucha m\u00e1s diversidad.<\/p>\n<p><strong>La Ley Wert est\u00e1 ahora mismo en el centro del debate, \u00bfafectar\u00e1 a las universidades?<br \/>\n<\/strong><\/p>\n<p>La ley Wert (La LOMCE) afecta principalmente al sistema educativo no universitario.&nbsp;Indirectamente puede afectar a la universidad con la supresi\u00f3n de las pruebas generales de&nbsp;acceso (la llamada selectividad). No creo que la LOMCE sea el instrumento adecuado para&nbsp;mejorar la calidad de la ense\u00f1anza pero no me voy a extender en ello.<\/p>\n<ul>\n<li>El ministerio que el sr.&nbsp;Wert preside est\u00e1 preparando una modificaci\u00f3n de la LOMLOU, la ley de universidades. Esa&nbsp;si va afectar a nuestro sistema universitario. No sabemos c\u00f3mo ser\u00e1 esta modificaci\u00f3n pero&nbsp;si no consigue cambiar la gobernanza de las universidades, desburocratizarlas, dotarlas de la&nbsp;autonom\u00eda de decisi\u00f3n y de la financiaci\u00f3n necesaria (muy lejos de lo que hoy existe) y si no&nbsp;nos acerca a Europa de un modo decidido, no servir\u00e1 para resolver los problemas que afectan&nbsp;a nuestro sistema universitario.<\/li>\n<\/ul>\n<p><strong>\u00bfPor d\u00f3nde pasa el futuro del sector de la formaci\u00f3n online?<\/strong><\/p>\n<p>Por una apuesta decidida por la calidad, por el m\u00e1ximo aprovechamiento de las posibilidades&nbsp;que ofrecen las tecnolog\u00edas disponibles, por el trabajo en red a escala internacional, por el&nbsp;fomento de la ocupabilidad y por una estrecha relaci\u00f3n con el mundo empresarial, por la&nbsp;flexibilidad y por la adaptaci\u00f3n a las necesidades de los estudiantes y de una sociedad en&nbsp;constante evoluci\u00f3n.<\/p>\n<p>Seguramente, la oferta en Espanya sea mucho m\u00e1s elevada que en algunos de los pa\u00edses vecinos, como Francia o Italia.&nbsp;Nuestra posici\u00f3n se acerca a los pa\u00edses con m\u00e1s tradici\u00f3n de educaci\u00f3n a distancia, como el&nbsp;Reino Unido que cuenta con la Open University, pero todav\u00eda est\u00e1 lejos de EEUU, donde la&nbsp;oferta de formaci\u00f3n online est\u00e1 mucho m\u00e1s implantada.<\/p>\n<p>En estos momentos, gracias a las TIC, la eclosi\u00f3n de la ense\u00f1anza online y m\u00e1s concretamente&nbsp;la aparici\u00f3n de los cursos masivos y abiertos (MOOC), han propiciado una oferta muy amplia&nbsp;que se dirige a sectores muy variados. La educaci\u00f3n a distancia est\u00e1 en un proceso de cambio y&nbsp;de plena evoluci\u00f3n&#8217;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La formaci\u00f3n online est\u00e1 en alza. En Emagister hemos comprobado que la formaci\u00f3n online aumenta un 21% cada a\u00f1o desde &#8230; <a title=\"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/\" aria-label=\"M\u00e1s en \u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":94,"featured_media":24058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8430,8484],"tags":[],"class_list":["post-12413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudiar-carrera-distancia","category-distancia","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resuelve tus dudas sobre educaci\u00f3n online con el vicerector de la UOC<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC\" \/>\n<meta property=\"og:description\" content=\"La formaci\u00f3n online est\u00e1 en alza. En Emagister hemos comprobado que la formaci\u00f3n online aumenta un 21% cada a\u00f1o desde ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sonia.ribo.9\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-06T11:45:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T07:41:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2122\" \/>\n\t<meta property=\"og:image:height\" content=\"1415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sonia Ribo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@soniaribo\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonia Ribo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/\"},\"author\":{\"name\":\"Sonia Ribo\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/b13231ce954d76e9ebc3b5771df738ae\"},\"headline\":\"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC\",\"datePublished\":\"2014-02-06T11:45:47+00:00\",\"dateModified\":\"2021-06-15T07:41:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/\"},\"wordCount\":1972,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ThinkstockPhotos-175206709.jpg\",\"articleSection\":[\"Estudiar una carrera a distancia\",\"Estudiar un master distancia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/\",\"name\":\"Resuelve tus dudas sobre educaci\u00f3n online con el vicerector de la UOC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ThinkstockPhotos-175206709.jpg\",\"datePublished\":\"2014-02-06T11:45:47+00:00\",\"dateModified\":\"2021-06-15T07:41:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ThinkstockPhotos-175206709.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/ThinkstockPhotos-175206709.jpg\",\"width\":2122,\"height\":1415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema educativo y titulaciones\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Masters y postgrados\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/masters\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Estudiar un master distancia\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/masters\\\/distancia\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/b13231ce954d76e9ebc3b5771df738ae\",\"name\":\"Sonia Ribo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g\",\"caption\":\"Sonia Ribo\"},\"description\":\"Soy periodista. He trabajado 12 a\u00f1os en la radio: en Radio Nacional y la Cadena SER. Ahora me dedico a la comunicaci\u00f3n digital y redacci\u00f3n de contenidos en Emagister. Presento un programa de radio de baloncesto de formaci\u00f3n en Badalona que se llama Fem B\u00e0squet.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sonia.ribo.9\",\"https:\\\/\\\/x.com\\\/soniaribo\"],\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/sonia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resuelve tus dudas sobre educaci\u00f3n online con el vicerector de la UOC","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC","og_description":"La formaci\u00f3n online est\u00e1 en alza. En Emagister hemos comprobado que la formaci\u00f3n online aumenta un 21% cada a\u00f1o desde ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_author":"https:\/\/www.facebook.com\/sonia.ribo.9","article_published_time":"2014-02-06T11:45:47+00:00","article_modified_time":"2021-06-15T07:41:40+00:00","og_image":[{"width":2122,"height":1415,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg","type":"image\/jpeg"}],"author":"Sonia Ribo","twitter_card":"summary_large_image","twitter_creator":"@soniaribo","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Sonia Ribo","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/"},"author":{"name":"Sonia Ribo","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/b13231ce954d76e9ebc3b5771df738ae"},"headline":"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC","datePublished":"2014-02-06T11:45:47+00:00","dateModified":"2021-06-15T07:41:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/"},"wordCount":1972,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg","articleSection":["Estudiar una carrera a distancia","Estudiar un master distancia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/","url":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/","name":"Resuelve tus dudas sobre educaci\u00f3n online con el vicerector de la UOC","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg","datePublished":"2014-02-06T11:45:47+00:00","dateModified":"2021-06-15T07:41:40+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2016\/04\/ThinkstockPhotos-175206709.jpg","width":2122,"height":1415},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/todavia-dudas-sobre-la-formacion-online-resuelve-tus-dudas-con-el-vicerector-de-la-uoc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sistema educativo y titulaciones","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/"},{"@type":"ListItem","position":3,"name":"Masters y postgrados","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/masters\/"},{"@type":"ListItem","position":4,"name":"Estudiar un master distancia","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/masters\/distancia\/"},{"@type":"ListItem","position":5,"name":"\u00bfTodav\u00eda dudas sobre la formaci\u00f3n online? Conv\u00e9ncete con el vicerrector de la UOC"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/b13231ce954d76e9ebc3b5771df738ae","name":"Sonia Ribo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c116e1b60ede2c2b744d95ca29d9b6ff80170b1bec985210e0034e72c293c74?s=96&r=g","caption":"Sonia Ribo"},"description":"Soy periodista. He trabajado 12 a\u00f1os en la radio: en Radio Nacional y la Cadena SER. Ahora me dedico a la comunicaci\u00f3n digital y redacci\u00f3n de contenidos en Emagister. Presento un programa de radio de baloncesto de formaci\u00f3n en Badalona que se llama Fem B\u00e0squet.","sameAs":["https:\/\/www.facebook.com\/sonia.ribo.9","https:\/\/x.com\/soniaribo"],"url":"https:\/\/www.emagister.com\/blog\/author\/sonia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/12413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=12413"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/12413\/revisions"}],"predecessor-version":[{"id":130057,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/12413\/revisions\/130057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/24058"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=12413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=12413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=12413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}