{"id":127679,"date":"2021-05-14T10:19:34","date_gmt":"2021-05-14T08:19:34","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=127679"},"modified":"2021-05-25T13:17:57","modified_gmt":"2021-05-25T11:17:57","slug":"tipos-de-cocina-cuales-son","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/","title":{"rendered":"Tipos de cocina: \u00bfCu\u00e1les son?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La gastronom\u00eda es un mundo lleno de posibilidades que se encuentra en una constante evoluci\u00f3n. D\u00eda a d\u00eda, van surgiendo nuevas formas, m\u00e9todos y procesos para innovar en la manera de cocinar. No obstante, existen varios tipos de cocina que son la base de todo el arte gastron\u00f3mico.<\/p>\n\n\n<p><!--more--><\/p>\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que, si te apasiona la cocina y quieres conocer m\u00e1s acerca de todas las posibilidades que existen a la hora de crear nuevos platos, est\u00e1s en el lugar indicado. En el art\u00edculo de hoy te contaremos cu\u00e1les son algunos de los estilos culinarios m\u00e1s populares y en qu\u00e9 consiste cada uno de ellos. No olvides que la <strong>Escuela Ergon<\/strong> pone a tu disposici\u00f3n el nuevo curso en Ayudante de Cocina (Pinche), un programa de calidad superior que te formar\u00e1 profesionalmente en el mundo de la gastronom\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tipos de cocina<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda, la cocina se divide principalmente en tres estilos. A continuaci\u00f3n, te contaremos cu\u00e1les son y de qu\u00e9 se trata cada uno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cocina tradicional<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se habla de cocina tradicional se refiere a un tipo de gastronom\u00eda en la cual cada plato es una referencia de una localizaci\u00f3n geogr\u00e1fica concreta. Este estilo de cocina es uno de los m\u00e1s amplios, pues la variedad de sabores es enorme, principalmente debido a que en cada regi\u00f3n puede cocinarse un mismo producto de manera diferente.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.emagister.com\/escuela-origen-international-education-cursos-1152223-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"147\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/12\/Escuela-Ergon.png\" alt=\"\" class=\"wp-image-110744\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/12\/Escuela-Ergon.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/12\/Escuela-Ergon-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La cocina tradicional es una cocina sociocultural. Es decir, en ella, se reflejan los productos aut\u00f3ctonos de una zona. Las tradiciones van de generaci\u00f3n en generaci\u00f3n y revelan la historia y la cultura popular en cada plato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es una cocina de base en la que se utilizan productos cl\u00e1sicos, econ\u00f3micos y f\u00e1ciles de conseguir. El ejemplo m\u00e1s b\u00e1sico, un guiso o el uso de fuego lento.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Alta cocina<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Del franc\u00e9s \u201c<em>La haure Cuisine<\/em>\u201d, la alta cocina se refiere a la gastronom\u00eda que se encuentra principalmente en los hoteles y restaurantes m\u00e1s importantes del mundo occidental. En la actualidad, este tipo de cocina suele ser moderna y creativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este estilo se aplican diversas t\u00e9cnicas culinarias en la elaboraci\u00f3n de cada plato. La atenci\u00f3n al detalle es fundamental, y el conocimiento por cada producto es muy espec\u00edfico, lo que hace posible desarrollar platos con sabores exquisitos en los que se resalta la calidad de los ingredientes y el estatus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo general este tipo de platos son muy elaborados y en ellos se destaca su presentaci\u00f3n, limpia y elegante, casi como una obra de arte en donde la <strong>composici\u00f3n de colores y texturas<\/strong> hacen que el plato en s\u00ed mismo tenga una personalidad.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Cocina de vanguardia<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">El concepto de cocina de vanguardia se refiere principalmente a la innovaci\u00f3n. Este tipo de cocina permite reinventarse a partir de una cocina tradicional y probar nuevos m\u00e9todos, t\u00e9cnicas y procesos para lograr creaciones de otro nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los ejemplos m\u00e1s oportunos es la <strong>cocina molecular,<\/strong> un estilo en el cual se aplican principios f\u00edsicos y qu\u00edmicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las porciones reducidas, la atenci\u00f3n al detalle en la presentaci\u00f3n y el cuidado en la est\u00e9tica, son las principales caracter\u00edsticas de la cocina de vanguardia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si quieres conocer<strong><a href=\"https:\/\/www.emagister.com\/escuela-origen-international-education-cursos-1152223-centrodetalles.htm\" target=\"_blank\" rel=\"noreferrer noopener\"> toda la oferta formativa<\/a><\/strong> que la <strong>Escuela Ergon<\/strong> tiene disponible para ti, no dudes en <a href=\"https:\/\/www.emagister.com\/contact\/center\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>contactar<\/strong><\/a> a uno de los profesionales de <strong>Emagister<\/strong> que con gusto te ayudar\u00e1 a encontrar el curso ideal para ti. O si ya formas parte del grupo de estudiantes de este centro, comparte tu experiencia con otros alumnos en este <a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>formulario<\/strong><\/a><strong>,<\/strong> y ay\u00fadalos a tomar su decisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gastronom\u00eda es un mundo lleno de posibilidades que se encuentra en una constante evoluci\u00f3n. D\u00eda a d\u00eda, van surgiendo &#8230; <a title=\"Tipos de cocina: \u00bfCu\u00e1les son?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/\" aria-label=\"M\u00e1s en Tipos de cocina: \u00bfCu\u00e1les son?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":127675,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[1469,2832,3265,10141,11027,12639,12961],"class_list":["post-127679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-cocina","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-noticiaselpais","tag-11027","tag-escuela-ergon","tag-ayudante-de-cocina","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"mostrar_faldon":"-1","texto_faldon":"Descubre la oferta formativa de la Escuela Ergon","link_faldon":"https:\/\/www.emagister.com\/escuela-origen-international-education-cursos-1152223-centrodetalles.htm","link_texto_faldon":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tipos de cocina: \u00bfCu\u00e1les son? - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de cocina: \u00bfCu\u00e1les son?\" \/>\n<meta property=\"og:description\" content=\"La gastronom\u00eda es un mundo lleno de posibilidades que se encuentra en una constante evoluci\u00f3n. D\u00eda a d\u00eda, van surgiendo ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T08:19:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-25T11:17:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2120\" \/>\n\t<meta property=\"og:image:height\" content=\"1415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Tipos de cocina: \u00bfCu\u00e1les son?\",\"datePublished\":\"2021-05-14T08:19:34+00:00\",\"dateModified\":\"2021-05-25T11:17:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/GettyImages-1200458828.jpg\",\"keywords\":[\"cocina\",\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"noticiasElPais\",\"99997192958079401036578245632064\",\"Escuela Ergon\",\"ayudante de cocina\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/\",\"name\":\"Tipos de cocina: \u00bfCu\u00e1les son? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/GettyImages-1200458828.jpg\",\"datePublished\":\"2021-05-14T08:19:34+00:00\",\"dateModified\":\"2021-05-25T11:17:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/GettyImages-1200458828.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/GettyImages-1200458828.jpg\",\"width\":2120,\"height\":1415,\"caption\":\"Chicken Pasta Spaghetti Primavera, homemade pasta dish with grilled chicken, vegetables tomato, broccoli, green pea, bell pepper and basil leaves, top view, copy space.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/tipos-de-cocina-cuales-son\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipos de cocina: \u00bfCu\u00e1les son?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tipos de cocina: \u00bfCu\u00e1les son? - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/","og_locale":"es_ES","og_type":"article","og_title":"Tipos de cocina: \u00bfCu\u00e1les son?","og_description":"La gastronom\u00eda es un mundo lleno de posibilidades que se encuentra en una constante evoluci\u00f3n. D\u00eda a d\u00eda, van surgiendo ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2021-05-14T08:19:34+00:00","article_modified_time":"2021-05-25T11:17:57+00:00","og_image":[{"width":2120,"height":1415,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Tipos de cocina: \u00bfCu\u00e1les son?","datePublished":"2021-05-14T08:19:34+00:00","dateModified":"2021-05-25T11:17:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg","keywords":["cocina","Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","noticiasElPais","99997192958079401036578245632064","Escuela Ergon","ayudante de cocina"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/","url":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/","name":"Tipos de cocina: \u00bfCu\u00e1les son? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg","datePublished":"2021-05-14T08:19:34+00:00","dateModified":"2021-05-25T11:17:57+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2021\/05\/GettyImages-1200458828.jpg","width":2120,"height":1415,"caption":"Chicken Pasta Spaghetti Primavera, homemade pasta dish with grilled chicken, vegetables tomato, broccoli, green pea, bell pepper and basil leaves, top view, copy space."},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/tipos-de-cocina-cuales-son\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Tipos de cocina: \u00bfCu\u00e1les son?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/127679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=127679"}],"version-history":[{"count":5,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/127679\/revisions"}],"predecessor-version":[{"id":127684,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/127679\/revisions\/127684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/127675"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=127679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=127679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=127679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}