{"id":139991,"date":"2022-01-27T08:42:00","date_gmt":"2022-01-27T07:42:00","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=139991"},"modified":"2022-01-25T17:09:05","modified_gmt":"2022-01-25T16:09:05","slug":"cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/","title":{"rendered":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La <strong>Formaci\u00f3n Profesional <\/strong>en modalidad<strong> a distancia<\/strong> est\u00e1 pensada para <strong>brindar flexibilidad <\/strong>al alumnado durante su aprendizaje. Al realizarse <strong>100 % online<\/strong>, el estudiante no tiene que desplazarse a ning\u00fan centro de estudios, por lo que <strong>puede compatibilizar la FP con otras tareas y obligaciones<\/strong>. Entonces, <strong>\u00bfC\u00f3mo se eval\u00faa al alumnado en la Formaci\u00f3n Profesional a distancia?<\/strong> En este art\u00edculo, resolveremos esta duda frecuente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta modalidad de Formaci\u00f3n Profesional es imprescindible que los estudiantes posean unos conocimientos b\u00e1sicos del uso de ordenador y dispongan de acceso a Internet, dado que ser\u00e1n las principales herramientas de aprendizaje. El alumno disfrutar\u00e1 de <strong>autonom\u00eda absoluta y de flexibilidad total <\/strong>durante el curso. No obstante, los centros que imparten la formaci\u00f3n a distancia coinciden en resaltar que el esfuerzo y el trabajo son similares a los de la f\u00f3rmula presencial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-alternancia-de-caracter-presencial-y-no-presencial\"><strong>Alternancia de car\u00e1cter presencial y no presencial<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de que se trata de FP a distancia, es conveniente que sepas que es una metodolog\u00eda de ense\u00f1anza que necesariamente <strong>incluye elementos de car\u00e1cter presencial <\/strong>con el objetivo de que, como alumno, puedas acreditar los conocimientos adquiridos. Esto significa que, dado que debes matricularte en un centro de Formaci\u00f3n Profesional, ser\u00e1 ah\u00ed donde debas dirigirte para <strong>realizar los ex\u00e1menes<\/strong> y la parte presencial de <strong>determinados m\u00f3dulos profesionales<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia es <strong>mixto<\/strong>. Por un lado, el alumno debe completar los <strong>ex\u00e1menes online y tareas a trav\u00e9s de la plataforma virtual<\/strong>, es decir, desde su propio ordenador personal. Por otro, para superar la FP con \u00e9xito, deber\u00e1 dirigirse al centro de estudios para efectuar el <strong>examen final <\/strong>de manera presencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No olvides que la legislaci\u00f3n vigente exige que toda formaci\u00f3n incluya <strong>al menos un examen de car\u00e1cter presencial.<\/strong> Superarlo es requisito innegociable para la obtenci\u00f3n del t\u00edtulo. En el caso de que un centro de estudios te ofrezca la posibilidad de cursar un ciclo formativo sin un examen presencial final, entonces, es muy probable que se trate de una <strong>instituci\u00f3n no oficial<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-donde-estudiar-una-fp-a-distancia-oficial\"><strong>D\u00f3nde estudiar una FP a distancia oficial<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A la vista de esto \u00faltimo que te hemos contado, quiz<strong>\u00e1s necesites algo de orientaci\u00f3n acerca de <\/strong>centros oficiales de Formaci\u00f3n Profesional. Ser\u00eda una l\u00e1stima invertir tanto tiempo en un curso que despu\u00e9s no va a servirte para nada. Por ello, desde Emagister queremos hablarte de algunos de los <a href=\"https:\/\/www.emagister.com\/rankings\/ranking-centros-formacion-profesional-online-mejor-valoracion-ranktonline-7161.htm\"><strong>centros de Formaci\u00f3n Profesional online con mejor valoraci\u00f3n<\/strong><\/a> para que estudies con todas las garant\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las escuelas m\u00e1s reputadas es <strong><a href=\"https:\/\/www.emagister.com\/esneca-business-school-cursos-123469-centrodetalles.htm\">ESNECA Business School<\/a><\/strong>, una innovadora escuela de negocios que imparte su formaci\u00f3n 100 % online. <strong><a href=\"https:\/\/www.emagister.com\/eleinternacional-cursos-180247-centrodetalles.htm\">ELEInternacional <\/a><\/strong>es, por su parte, un centro de capacitaci\u00f3n profesional dise\u00f1ado para quienes desean <strong>formarse como profesores de espa\u00f1ol<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de <strong><a href=\"https:\/\/www.emagister.com\/tecniqas-cursos-154675-centrodetalles.htm\">Formaci\u00f3n Activa Profesional<\/a><\/strong>, se presenta como un centro l\u00edder en Formaci\u00f3n Profesional. <strong><a href=\"https:\/\/www.emagister.com\/academyformacion-cursos-192433-centrodetalles.htm\">AcademyFormaci\u00f3n<\/a><\/strong> es pionera en la<strong> ense\u00f1anza virtual <\/strong>gracias a sus cursos en PDF, mientras que <strong><a href=\"https:\/\/www.emagister.com\/nueva-vision-cursos-55777-centrodetalles.htm\">Nueva Visi\u00f3n<\/a><\/strong> es la mejor escuela para formarte en el \u00e1mbito de la <strong>est\u00e9tica profesional<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan apunta el Ministerio de Educaci\u00f3n y Formaci\u00f3n Profesional, los ciclos formativos tanto de Grado Medio como de Grado Superior tienen una duraci\u00f3n de <strong>2000 horas<\/strong>. Por supuesto, es una duraci\u00f3n orientativa, pues <strong>ir\u00e1 en funci\u00f3n de la dedicaci\u00f3n del alumno<\/strong>. En la FP a distancia es muy importante la automotivaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya conoces las caracter\u00edsticas y la metodolog\u00eda de evaluaci\u00f3n de la Formaci\u00f3n Profesional a distancia, as\u00ed que \u00a1solo te falta escoger el ciclo que m\u00e1s te guste! Sum\u00e9rgete en el <strong><a href=\"https:\/\/www.emagister.com\/formacion-profesional\/online-segim-8-3.htm\">cat\u00e1logo de Emagister<\/a> <\/strong>en busca de inspiraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Formaci\u00f3n Profesional en modalidad a distancia est\u00e1 pensada para brindar flexibilidad al alumnado durante su aprendizaje. Al realizarse 100 &#8230; <a title=\"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/\" aria-label=\"M\u00e1s en \u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":139994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8339,8433],"tags":[96,607,832,1795],"class_list":["post-139991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fp","category-estudiar-fp-a-distancia","tag-formacion-profesional","tag-fp","tag-estudiar-fp-2","tag-formacion-a-distancia","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Descubre toda la oferta de Formaci\u00f3n Profesional a distancia","link_faldon":"https:\/\/www.emagister.com\/formacion-profesional\/online-segim-8-3.htm","link_texto_faldon":"Ver cursos","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia? - Blog Emagister<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-27T07:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?\",\"datePublished\":\"2022-01-27T07:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/\"},\"wordCount\":661,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1138947362.jpg\",\"keywords\":[\"formaci\u00f3n profesional\",\"fp\",\"estudiar fp\",\"Formaci\u00f3n a distancia\"],\"articleSection\":[\"Formaci\u00f3n profesional\",\"Estudiar FP a distancia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/\",\"name\":\"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1138947362.jpg\",\"datePublished\":\"2022-01-27T07:42:00+00:00\",\"description\":\"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1138947362.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/GettyImages-1138947362.jpg\",\"width\":2121,\"height\":1414},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema educativo y titulaciones\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formaci\u00f3n profesional\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/fp\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Estudiar FP a distancia\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/fp\\\/estudiar-fp-a-distancia\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia? - Blog Emagister","description":"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?","og_description":"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.","og_url":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2022-01-27T07:42:00+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?","datePublished":"2022-01-27T07:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/"},"wordCount":661,"commentCount":2,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg","keywords":["formaci\u00f3n profesional","fp","estudiar fp","Formaci\u00f3n a distancia"],"articleSection":["Formaci\u00f3n profesional","Estudiar FP a distancia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/","url":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/","name":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg","datePublished":"2022-01-27T07:42:00+00:00","description":"\u00bfQuieres saber que m\u00e9todo de evaluaci\u00f3n se sigue en la Formaci\u00f3n Profesional a distancia? En este nuevo post te lo explicamos con detalle.","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2022\/01\/GettyImages-1138947362.jpg","width":2121,"height":1414},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/cual-es-el-metodo-de-evaluacion-en-la-formacion-profesional-a-distancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sistema educativo y titulaciones","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/"},{"@type":"ListItem","position":3,"name":"Formaci\u00f3n profesional","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/fp\/"},{"@type":"ListItem","position":4,"name":"Estudiar FP a distancia","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/fp\/estudiar-fp-a-distancia\/"},{"@type":"ListItem","position":5,"name":"\u00bfCu\u00e1l es el m\u00e9todo de evaluaci\u00f3n en la Formaci\u00f3n Profesional a distancia?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/139991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=139991"}],"version-history":[{"count":3,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/139991\/revisions"}],"predecessor-version":[{"id":139998,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/139991\/revisions\/139998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/139994"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=139991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=139991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=139991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}