{"id":16252,"date":"2014-10-14T09:03:34","date_gmt":"2014-10-14T07:03:34","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=16252"},"modified":"2021-12-01T15:39:38","modified_gmt":"2021-12-01T14:39:38","slug":"como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/","title":{"rendered":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?"},"content":{"rendered":"<p>La implantaci\u00f3n de la LOMCE este curso implica una modificaci\u00f3n del consejo escolar, uno de los principales \u00f3rganos de representaci\u00f3n de las familias en la escuela, que ha generado un<a href=\"https:\/\/www.emagister.com\/blog\/lomce-argumentos-favor-y-en-contra\/\"> intenso debate en la comunidad educativa<\/a>. A tenor de estos cambios, entre otros factores, la Fundaci\u00f3 Bofill presento el pasado mes de mayo el <em>Llibre blanc sobre la participaci\u00f3 de les fam\u00edlies a l&#8217;escola<\/em> [<em>Libro blanco sobre la participaci\u00f3n de las familias en la escuela<\/em>]. Dicho estudio se enmarca en el provecto Fam\u00edlies amb veu [Familias con voz] y recoge datos a partir de diferentes encuestas a 1.228 asociaciones de padres de escuelas p\u00fablicas catalanas, a equipos directivos de 1.500 centros de Catalu\u00f1a y a 1.500 familias con escolares de la misma comunidad de entre 0 y16 a\u00f1os.<\/p>\n<p>Si tienes un hijo en edad escolar te pueden interesar el contenido este trabajo. Veamos cu\u00e1les son las tendencias.<\/p>\n<p><!--more--><\/p>\n<p><strong>Sobre los h\u00e1bitos familiares en relaci\u00f3n a la escuela, el estudio indica los siguientes datos optimistas:<\/strong><\/p>\n<ul>\n<li>El 95 % de los padres han asistido a la reuni\u00f3n de inicio de curso.<\/li>\n<li>El 89 % se ha reunido con el tutor a lo largo del curso.<\/li>\n<li>El 74 % ayuda a sus hijos con cierta asiduidad a hacer los deberes.<\/li>\n<\/ul>\n<p>Las cifras var\u00edan cuando se trata de valorar la implicaci\u00f3n de los padres en la escuela:<\/p>\n<p><strong>El 97 % de las escuelas tienen una Asociaci\u00f3n de Madres y Padres de Alumnos<\/strong> (AMPA) y el 87 % de los padres est\u00e1n asociados a esas AMPAS. Sin embargo, <strong>solo el 29 % de los padres dice participar de forma activa en la organizaci\u00f3n de la escuela<\/strong>, ya sea a trav\u00e9s de la AMPA o de las comisiones de trabajo. En este sentido, <strong>el 47 % de los padres que no participan de forma activa en la gobernaci\u00f3n de la escuela manifiestan no estar satisfechos con su implicaci\u00f3n en la vida escolar<\/strong>.<br \/>\nLos principales factores que se\u00f1ala el estudio sobre la falta de participaci\u00f3n de las familias son:<\/p>\n<ul>\n<li>El nivel de estudios de los padres (a m\u00e1s formaci\u00f3n, m\u00e1s participaci\u00f3n en la escuela).<\/li>\n<li>La situaci\u00f3n econ\u00f3mica (las familias m\u00e1s pobres son las que menos se implican en la escuela).<\/li>\n<li>La monoparentalidad (dificulta la posibilidad de dedicar horas a la vida escolar).<\/li>\n<li>El origen geogr\u00e1fico de los padres (las familias extranjeras con menos recursos de todo tipo son las que tienen m\u00e1s dificultades para participar en la vida escolar).<\/li>\n<\/ul>\n<p>Sobre la participaci\u00f3n de familias extranjeras, el Libro Blanco indica que, en igualdad de condiciones socioecon\u00f3micas con las familias nacionales, las padres de origen extranjero acaban implic\u00e1ndose en la escuela al cabo de seis a\u00f1os de estancia en nuestro pa\u00eds.<\/p>\n<p><strong>Para remarcar la importancia sobre las AMPA en la vida escolar, el libro blanco destaca los siguientes indicadores:<\/strong><\/p>\n<ul>\n<li>En el 97 % de los casos, las AMPA cubren servicios esenciales vinculados a la conciliaci\u00f3n familiar (comedor, transporte escolar, etc.)<\/li>\n<li>El 18 % del presupuesto de las AMPA se destina a la compra de bienes para el colegio y el 5 % va para la adquisici\u00f3n de material escolar.<\/li>\n<li>El 70 % de las AMPA manifiestan su voluntad de participar en la programaci\u00f3n del centro y el 60 % en la elecci\u00f3n del director.<\/li>\n<li>M\u00e1s del 60 % de las AMPA participan tambi\u00e9n en iniciativas de car\u00e1cter social fuera de la escuela.<\/li>\n<\/ul>\n<p>El estudio destaca el valor de las AMPA como puente para fluidificar la relaci\u00f3n entre maestros y familias. Seg\u00fan este trabajo, m\u00e1s de la mitad de las AMPA se re\u00fane de forma peri\u00f3dica con el equipo directivo del centro.<\/p>\n<p><strong>El <em>Llibre blanc<\/em> se muestra cr\u00edtico con la situaci\u00f3n de los consejos escolares:<\/strong><\/p>\n<ul>\n<li>Creen que est\u00e1n demasiado burocratizados y cumplen solo son los m\u00ednimos exigidos.<\/li>\n<li>A pesar de que la participaci\u00f3n de los padres en las elecciones al consejo escolar es superior a la media de todos los sectores implicados (9 %) todav\u00eda es muy raqu\u00edtica: 34 %.<\/li>\n<li>Los consejos escolares que rebasan el \u00e1mbito estricto de la escuela (municipales, auton\u00f3micos, del Estado) han hecho una buena labor consultiva, pero con escasa trascendencia.<\/li>\n<\/ul>\n<p>En la din\u00e1mica negativa de los consejos escolares se\u00f1alan los siguientes factores:<\/p>\n<ul>\n<li>La desinformaci\u00f3n.<\/li>\n<li>La falta de paridad en la composici\u00f3n<\/li>\n<li>La poca autonom\u00eda de los centros<\/li>\n<li>El corporativismo<\/li>\n<li>La delicada situaci\u00f3n econ\u00f3mica por la que pasan muchas familias.<\/li>\n<\/ul>\n<p>En este sentido, <strong>el estudio es muy cr\u00edtico con los cambios que introduce la LOMCE en referencia al consejo escolar<\/strong>. Seg\u00fan el <em>Llibre blanc<\/em>:<\/p>\n<ul>\n<li>Recorta la participaci\u00f3n de la comunidad escolar en la administraci\u00f3n de los centros.<\/li>\n<li>Rebaja el papel de las familias en el consejo escolar<\/li>\n<li>Minimiza sus funciones hasta el punto de convertirlo en un \u00f3rgano irrelevante.<\/li>\n<\/ul>\n<p><strong>A partir de los datos del estudio, el <em>Llibre blanc<\/em> propone un dec\u00e1logo de la participaci\u00f3n de las familias en la vida escolar:<\/strong><\/p>\n<ol>\n<li>Hace falta incrementar el peso de las familias en la organizaci\u00f3n de los centros educativos (aumentar la frecuencia de reuniones tutor-padres, reformar el papel de las AMPA liber\u00e1ndolas de la mera prestaci\u00f3n de servicios y convirti\u00e9ndolas en protagonistas de las relaciones entre la escuela y las familias en cada centro).<\/li>\n<li>Los padres se deben involucrar en los contenidos educativos (participar en los debates sobre los curr\u00edculos escolares, colaborar en la programaci\u00f3n educativa del centro, etc.)<\/li>\n<li>Las familias son clave en el combate contra el fracaso escolar (se debe de asesorar a los padres en el acompa\u00f1amiento educativo, abrir un debate sobre el papel de los deberes, exigir subvenciones para programas de ayuda contra el fracaso escolar).<\/li>\n<li>Se debe de garantizar una buena oferta p\u00fablica de escuelas de calidad.<\/li>\n<li>Es necesario garantizar la conciliaci\u00f3n familiar tanto en los horarios escolares como en los laborales.<\/li>\n<li>Hay que mejorar la financiaci\u00f3n de la escuela p\u00fablica<\/li>\n<li>Se precisa instaurar, en nombre de la equidad y la calidad educativa, un sistema de becas que corrija las desigualdades econ\u00f3micas entre familias.<\/li>\n<li>Las administraciones p\u00fablicas han de reconocer el valor social de las AMPA.<\/li>\n<li>Hay que promulgar una nueva ley de educaci\u00f3n que supere los vaivenes de la pol\u00edtica y en la que se reconozca el papel decisorio de las familias en la vida escolar.<\/li>\n<li>Se debe de superar el contexto estricto de la escuela, es decir, las AMPA han de participar en otros \u00e1mbitos de la sociedad vinculados a la infancia y la adolescencia (Consejo del Audiovisual de Catalu\u00f1a, programas de prevenci\u00f3n de maltratos, de vida saludable, etc.)<\/li>\n<\/ol>\n<p>\u00bfY t\u00fa, que opinas?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La implantaci\u00f3n de la LOMCE este curso implica una modificaci\u00f3n del consejo escolar, uno de los principales \u00f3rganos de representaci\u00f3n &#8230; <a title=\"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/\" aria-label=\"M\u00e1s en \u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":92,"featured_media":16304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[429],"tags":[1255,1256,158],"class_list":["post-16252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-padres","tag-como-ser-padre","tag-relacion-escuela-padres","tag-educacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"","link_faldon":"","link_texto_faldon":"","hreflang":false,"estilo_titulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela? - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?\" \/>\n<meta property=\"og:description\" content=\"La implantaci\u00f3n de la LOMCE este curso implica una modificaci\u00f3n del consejo escolar, uno de los principales \u00f3rganos de representaci\u00f3n ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-14T07:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T14:39:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1238\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mart\u00ed Farr\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mart\u00ed Farr\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/\"},\"author\":{\"name\":\"Mart\u00ed Farr\u00e9\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/cee940959b59b525dc1baa04811b34af\"},\"headline\":\"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?\",\"datePublished\":\"2014-10-14T07:03:34+00:00\",\"dateModified\":\"2021-12-01T14:39:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/\"},\"wordCount\":1129,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/166671541.jpg\",\"keywords\":[\"c\u00f3mo ser padre\",\"relaci\u00f3n escuela -padres\",\"educaci\u00f3n\"],\"articleSection\":[\"Ser padres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/\",\"name\":\"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/166671541.jpg\",\"datePublished\":\"2014-10-14T07:03:34+00:00\",\"dateModified\":\"2021-12-01T14:39:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/166671541.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/166671541.jpg\",\"width\":1920,\"height\":1238},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema educativo y titulaciones\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Educaci\u00f3n primaria\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/educacion-primaria\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ser padres\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/educacion-primaria\\\/para-padres\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/cee940959b59b525dc1baa04811b34af\",\"name\":\"Mart\u00ed Farr\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g\",\"caption\":\"Mart\u00ed Farr\u00e9\"},\"description\":\"Barcelona, 1974. Ha trabajado como redactor, corrector, validador, indexador, cron\u00f3logo, dise\u00f1ador de colecciones, asistente de edici\u00f3n y un largo etc\u00e9tera en el sector editorial -para empresas como Planeta Actimedia, Ediciones B, RBA, Oc\u00e9ano, Edicions Riama o Angle Editorial- y tambi\u00e9n de periodista cultural -y de otros menesteres- en medios como Dominical de El Peri\u00f3dico de Catalunya, El Triangle, M\u00e9s Tarragona, Ja\u00e7, Scanner FM o la agencia Temas de Comunicaci\u00f3n.\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/marti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela? - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?","og_description":"La implantaci\u00f3n de la LOMCE este curso implica una modificaci\u00f3n del consejo escolar, uno de los principales \u00f3rganos de representaci\u00f3n ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2014-10-14T07:03:34+00:00","article_modified_time":"2021-12-01T14:39:38+00:00","og_image":[{"width":1920,"height":1238,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg","type":"image\/jpeg"}],"author":"Mart\u00ed Farr\u00e9","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Mart\u00ed Farr\u00e9","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/"},"author":{"name":"Mart\u00ed Farr\u00e9","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/cee940959b59b525dc1baa04811b34af"},"headline":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?","datePublished":"2014-10-14T07:03:34+00:00","dateModified":"2021-12-01T14:39:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/"},"wordCount":1129,"commentCount":2,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg","keywords":["c\u00f3mo ser padre","relaci\u00f3n escuela -padres","educaci\u00f3n"],"articleSection":["Ser padres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/","url":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/","name":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg","datePublished":"2014-10-14T07:03:34+00:00","dateModified":"2021-12-01T14:39:38+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2014\/10\/166671541.jpg","width":1920,"height":1238},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/como-debe-de-ser-la-relacion-entre-la-familia-y-la-escuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sistema educativo y titulaciones","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/"},{"@type":"ListItem","position":3,"name":"Educaci\u00f3n primaria","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/educacion-primaria\/"},{"@type":"ListItem","position":4,"name":"Ser padres","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/educacion-primaria\/para-padres\/"},{"@type":"ListItem","position":5,"name":"\u00bfC\u00f3mo debe de ser la relaci\u00f3n entre la familia y la escuela?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/cee940959b59b525dc1baa04811b34af","name":"Mart\u00ed Farr\u00e9","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0c3bfaa3fa412aa26879ba4f36a3fb99c3ef234b729166ce00c1e1c60927227?s=96&r=g","caption":"Mart\u00ed Farr\u00e9"},"description":"Barcelona, 1974. Ha trabajado como redactor, corrector, validador, indexador, cron\u00f3logo, dise\u00f1ador de colecciones, asistente de edici\u00f3n y un largo etc\u00e9tera en el sector editorial -para empresas como Planeta Actimedia, Ediciones B, RBA, Oc\u00e9ano, Edicions Riama o Angle Editorial- y tambi\u00e9n de periodista cultural -y de otros menesteres- en medios como Dominical de El Peri\u00f3dico de Catalunya, El Triangle, M\u00e9s Tarragona, Ja\u00e7, Scanner FM o la agencia Temas de Comunicaci\u00f3n.","url":"https:\/\/www.emagister.com\/blog\/author\/marti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/16252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=16252"}],"version-history":[{"count":1,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/16252\/revisions"}],"predecessor-version":[{"id":135884,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/16252\/revisions\/135884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/16304"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=16252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=16252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=16252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}