{"id":34479,"date":"2017-01-13T15:32:39","date_gmt":"2017-01-13T14:32:39","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=34479"},"modified":"2021-04-27T10:42:47","modified_gmt":"2021-04-27T08:42:47","slug":"la-formacion-continua-las-empresas-no-topico","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/","title":{"rendered":"La formaci\u00f3n continua en las empresas no como t\u00f3pico"},"content":{"rendered":"<p style=\"text-align: justify;\">Parece que la recuperaci\u00f3n econ\u00f3mica es un hecho, no, no estamos como antes de la recesi\u00f3n, pero hasta el Rey coment\u00f3 en enero en un foro de inversores extranjeros que la crisis \u201cha pasado ya\u201d en Espa\u00f1a, es decir, que de alguna forma es oficial.<!--more--><\/p>\n<p style=\"text-align: justify;\">Aunque los niveles de desempleo a\u00fan siguen siendo muy elevados, sobre todo si los comparamos con el resto de Europa, por ahora no hay sectores que sean motores r\u00e1pidos de la econom\u00eda hasta el punto de poder inflar burbujas, y las empresas parece que se van estabilizando.<\/p>\n<p style=\"text-align: justify;\">La recuperaci\u00f3n de las ventas y el consumo es paulatina, pero lo m\u00e1s importante es que la operativa empresarial no volver\u00e1 a ser igual que antes. Las empresas han aprendido el valor de la diversificaci\u00f3n de sus carteras, adaptaci\u00f3n a entornos cambiantes (a velocidad de v\u00e9rtigo), y sobre todo a valorar el desarrollo del talento interno, que repercute en procesos de creatividad e innovaci\u00f3n y son \u00e9stos los que han hecho que muchas empresas se reinventen y hayan buscado caminos para salir de una situaci\u00f3n que ha afectado a pr\u00e1cticamente todos los sectores empresariales, directa e indirectamente.<\/p>\n<p style=\"text-align: justify;\">Actualmente en los procesos de selecci\u00f3n ya no se valora como \u00fanico elemento los conocimientos t\u00e9cnicos y el expediente acad\u00e9mico, sino que se a\u00f1aden con mucha importancia las habilidades y competencias de las personas, en relaci\u00f3n con los equipos, las tomas de decisiones y la capacidad para\u00a0 evaluar situaciones y riesgos.<\/p>\n<p style=\"text-align: justify;\">La experiencia profesional de las personas se traduce en las horas dedicadas al trabajo, en las situaciones diferentes a las que se enfrentan y en la\u00a0 formaci\u00f3n que han ido adquiriendo y aplicando durante su carrera profesional.<\/p>\n<p style=\"text-align: justify;\">En los \u00faltimos 15 a\u00f1os se ha impulsado mucho la formaci\u00f3n continua de los trabajadores, pero ha sido en el \u00faltima d\u00e9cada donde se ha visto la necesidad de realizar formaci\u00f3n, tanto t\u00e9cnica como competencial, en cada uno de los empleados de las empresas. Esta labor que las personas por un lado <a href=\"https:\/\/www.emagister.com\/vision-valor-consulting-l-cursos-64039-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34484 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/visionyvalor_logo.jpg\" alt=\"visionyvalor_logo\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/visionyvalor_logo.jpg 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/visionyvalor_logo-80x53.jpg 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a>han asimilado, la prueba ha sido el incremento de matriculaciones en programas M\u00e1ster, y que, por otro lado las grandes empresas ven\u00edan ya aplicando para desarrollar programas formativos de alto rendimiento, es trasladable a las pymes, donde la formaci\u00f3n generalmente ha estado menos impulsada desde la Direcci\u00f3n, siendo m\u00e1s una iniciativa particular del empleado.<\/p>\n<p style=\"text-align: justify;\">Las pymes representan la mayor parte del tejido empresarial espa\u00f1ol, y van asimilando la importancia de la formaci\u00f3n como elemento estrat\u00e9gico importante para hacer frente a situaciones en las que se requiera que los trabajadores puedan aportar soluciones, entender la necesidad del cambio y afianzar el compromiso con los objetivos de la organizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La formaci\u00f3n continua no es un t\u00f3pico, es una realidad que se traduce en inversi\u00f3n con rentabilidad para las organizaciones, independientemente de su tama\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece que la recuperaci\u00f3n econ\u00f3mica es un hecho, no, no estamos como antes de la recesi\u00f3n, pero hasta el Rey &#8230; <a title=\"La formaci\u00f3n continua en las empresas no como t\u00f3pico\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/\" aria-label=\"M\u00e1s en La formaci\u00f3n continua en las empresas no como t\u00f3pico\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":233,"featured_media":34481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[759,785],"tags":[807,1214,2293,2832,3265,3590,4334,7161,10141],"class_list":["post-34479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-para-profesionales","category-nuestros-clientes","tag-experiencia-laboral","tag-formacion-continua","tag-pymes","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-3590","tag-formacion-para-trabajadores","tag-vision-y-valor-consulting-s-l","tag-noticiaselpais","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"estilo_titulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La formaci\u00f3n continua en las empresas no como t\u00f3pico - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La formaci\u00f3n continua en las empresas no como t\u00f3pico\" \/>\n<meta property=\"og:description\" content=\"Parece que la recuperaci\u00f3n econ\u00f3mica es un hecho, no, no estamos como antes de la recesi\u00f3n, pero hasta el Rey ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-13T14:32:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"633\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n Visi\u00f3n y Valor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Visi\u00f3n y Valor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Visi\u00f3n y Valor\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/e0f7c93b4de8f569cc6c7b0ce1f6e07a\"},\"headline\":\"La formaci\u00f3n continua en las empresas no como t\u00f3pico\",\"datePublished\":\"2017-01-13T14:32:39+00:00\",\"dateModified\":\"2021-04-27T08:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/1-1.png\",\"keywords\":[\"experiencia laboral\",\"formaci\u00f3n continua\",\"pymes\",\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"68670030082770495465676765514566\",\"formaci\u00f3n para trabajadores\",\"Vision y Valor Consulting S.L\",\"noticiasElPais\"],\"articleSection\":[\"Competencias profesionales\",\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/\",\"name\":\"La formaci\u00f3n continua en las empresas no como t\u00f3pico - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/1-1.png\",\"datePublished\":\"2017-01-13T14:32:39+00:00\",\"dateModified\":\"2021-04-27T08:42:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/1-1.png\",\"width\":1024,\"height\":633},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-formacion-continua-las-empresas-no-topico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La formaci\u00f3n continua en las empresas no como t\u00f3pico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/e0f7c93b4de8f569cc6c7b0ce1f6e07a\",\"name\":\"Redacci\u00f3n Visi\u00f3n y Valor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g\",\"caption\":\"Redacci\u00f3n Visi\u00f3n y Valor\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/redaccion-vision-y-valor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La formaci\u00f3n continua en las empresas no como t\u00f3pico - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/","og_locale":"es_ES","og_type":"article","og_title":"La formaci\u00f3n continua en las empresas no como t\u00f3pico","og_description":"Parece que la recuperaci\u00f3n econ\u00f3mica es un hecho, no, no estamos como antes de la recesi\u00f3n, pero hasta el Rey ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2017-01-13T14:32:39+00:00","article_modified_time":"2021-04-27T08:42:47+00:00","og_image":[{"width":1024,"height":633,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png","type":"image\/png"}],"author":"Redacci\u00f3n Visi\u00f3n y Valor","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Redacci\u00f3n Visi\u00f3n y Valor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/"},"author":{"name":"Redacci\u00f3n Visi\u00f3n y Valor","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/e0f7c93b4de8f569cc6c7b0ce1f6e07a"},"headline":"La formaci\u00f3n continua en las empresas no como t\u00f3pico","datePublished":"2017-01-13T14:32:39+00:00","dateModified":"2021-04-27T08:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png","keywords":["experiencia laboral","formaci\u00f3n continua","pymes","Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","68670030082770495465676765514566","formaci\u00f3n para trabajadores","Vision y Valor Consulting S.L","noticiasElPais"],"articleSection":["Competencias profesionales","Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/","url":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/","name":"La formaci\u00f3n continua en las empresas no como t\u00f3pico - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png","datePublished":"2017-01-13T14:32:39+00:00","dateModified":"2021-04-27T08:42:47+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/1-1.png","width":1024,"height":633},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/la-formacion-continua-las-empresas-no-topico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"La formaci\u00f3n continua en las empresas no como t\u00f3pico"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/e0f7c93b4de8f569cc6c7b0ce1f6e07a","name":"Redacci\u00f3n Visi\u00f3n y Valor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70a3a559c9af68d900f95b955572a5dec3d8a169346b1682472c0fa3ae96bb8f?s=96&r=g","caption":"Redacci\u00f3n Visi\u00f3n y Valor"},"url":"https:\/\/www.emagister.com\/blog\/author\/redaccion-vision-y-valor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/34479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/233"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=34479"}],"version-history":[{"count":1,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/34479\/revisions"}],"predecessor-version":[{"id":121470,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/34479\/revisions\/121470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/34481"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=34479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=34479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=34479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}