{"id":39573,"date":"2017-05-24T12:50:59","date_gmt":"2017-05-24T10:50:59","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=39573"},"modified":"2018-07-03T09:53:28","modified_gmt":"2018-07-03T07:53:28","slug":"las-intolerancias-alimenticias-mas-frecuentes","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/","title":{"rendered":"Las intolerancias alimenticias m\u00e1s frecuentes"},"content":{"rendered":"<p style=\"text-align: justify\">Una media hora despu\u00e9s de haber comido empiezas a experimentar dolores de est\u00f3mago o te tienes que ir pitando al ba\u00f1o. Te sientes tan mal que ni te atreves a irte de casa. \u00bfTe suena? Entonces puede que est\u00e9s sufriendo de intolerancias alimentarias. En el Instituto NEWMIND te explican las m\u00e1s comunes, sus s\u00edntomas y qu\u00e9 comidas deber\u00edas vigilar. Porque a veces los alimentos saludables tambi\u00e9n te pueden afectar.<!--more--><\/p>\n<h4 style=\"text-align: justify\"><strong>Intolerancia vs. alergia<\/strong><\/h4>\n<p style=\"text-align: justify\">No confundas las intolerancias con las alergias. Las alergias son reacciones hipersensitivas, lo que significa que el cuerpo reacciona de forma anormal a un alimento en particular, al polen o a algunos animales. El cuerpo considera que la sustancia es un peligro, as\u00ed que produce anticuerpos. Esto puede llevarte a tener s\u00edntomas como rinitis, sarpullidos o asma, pero tambi\u00e9n otros que puede poner en riesgo tu vida, como la anafilaxia.<\/p>\n<p style=\"text-align: justify\">Una intolerancia alimentaria, por otro lado, se produce cuando el cuerpo no puede digerir bien un alimento en particular. No hay una respuesta defensiva por parte del sistema inmunol\u00f3gico. El s\u00edntoma m\u00e1s frecuente es el malestar grastrointestinal.<\/p>\n<p style=\"text-align: justify\"><strong>1. Lactosa<\/strong><\/p>\n<p style=\"text-align: justify\">La intolerancia a la lactosa se produce cuando el cuerpo no puede digerir la lactosa (el az\u00facar de la leche). La lactosa es un az\u00facar disac\u00e1rido compuesto de glucosa y galactosa. Normalmente, la lactosa es descompuesta en estos az\u00facares simples por la enzima lactasa as\u00ed que se puede absorber a trav\u00e9s de los intestinos en la sangre. Pero si eres intolerante a la lactosa, te falta esta enzima o no la produces en cantidades suficientes. Esto significa que la lactosa no se puede digerir bien y como resultado se producen gases, dolores estomacales, n\u00e1useas y diarrea.<\/p>\n<p style=\"text-align: justify\">Como indica el t\u00e9rmino az\u00facar de la leche, la lactosa se encuentra en todos los productos l\u00e1cteos (leche, yogur, quesos). Tambi\u00e9n se a\u00f1ade frecuentemente a alimentos procesados o incluso a suplementos de prote\u00edna. Cuanto m\u00e1s l\u00edquido es un producto l\u00e1cteo, m\u00e1s lactosa contiene. As\u00ed que la leche es una aut\u00e9ntica bomba de lactosa (4,5 g por cada 100 g), mientras que un queso curado contiene s\u00f3lo meras trazas\u00a0(&lt; 1 g por cada 100 g).<\/p>\n<p style=\"text-align: justify\">Si te han\u00a0diagnosticado intolerancia a la lactosa, deber\u00edas reducir el consumo de productos l\u00e1cteos o cambiar a los que no contienen lactosa o a los veganos. En muchos casos, lo que cuenta es la cantidad (esto tambi\u00e9n aplica a la intolerancia a la fructosa y a la histamina). Por ejemplo, puede que seas capaz de tolerar un poco de leche en el caf\u00e9, pero no un vaso entero de leche con miel. Una vez se haya diagnosticado tu caso, te puede ayudar el eliminar por completo todos los alimentos que contengan lactosa antes de reincorporarlos a tu dieta. Tambi\u00e9n puedes llevar un diario de comidas y s\u00edntomas, as\u00ed sabr\u00e1s qu\u00e9 alimentos\u00a0te van mejor.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s, tambi\u00e9n puedes adquirir lactasa en la farmacia. Deber\u00edas tenerla siempre a mano, para cuando vayas a comer fuera y tengas potenciales problemas de est\u00f3mago.<\/p>\n<p style=\"text-align: justify\"><em>Est\u00e1 bien saberlo:\u00a0<\/em>Igual que la leche de vaca, la leche de cabra o la de oveja tambi\u00e9n contienen lactosa. La lactosa de la leche sin lactosa ya est\u00e1 descompuesta en az\u00facares simples, por eso es m\u00e1s f\u00e1cil de digerir. Sabe algo m\u00e1s dulce que la leche normal. Las leches de origen vegetal como la de soja, almendras o avena no contienen az\u00facares de la leche.<\/p>\n<p style=\"text-align: justify\"><strong>2. Fructosa<\/strong><\/p>\n<p style=\"text-align: justify\">En el caso de la intolerancia a la fructosa o malabsorci\u00f3n de la fructosa, el az\u00facar de la fructosa no se absorbe adecuadamente. Esto lleva a los mismos problemas gastrointestinales que con la intolerancia a la lactosa. La gente que sufre de esta malabsorci\u00f3n tiene un defecto en el GLUT5, parte del sistema\u00a0de transporte en los intestinos. Por esto la cantidad de fructosa que se absorbe en la sangre es deficiente, as\u00ed que termina en el intestino grueso donde es fermentada por las bacterias. Esto lleva a los s\u00edntomas caracter\u00edsticos de la malabsorci\u00f3n de la fructosa.<\/p>\n<p style=\"text-align: justify\">La fructosa se encuentra en los siguientes alimentos:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fruta (sobre todo en la seca, manzanas, peras, uvas, ciruelas y cerezas)<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Zumos de frutas<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dulces<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Miel, sirope de arce y sirope de agave<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Adem\u00e1s, tambi\u00e9n algunas verduras son dif\u00edciles de digerir, como el repollo, el br\u00e9col o los puerros. Los sustitutos del az\u00facar sorbitol y xylitol pueden llevarte a tener desajustes grastrointestinales. Estos se suelen encontrar en bebidas diet\u00e9ticas, chicles sin az\u00facar y dulces. Si sufres de malabsorci\u00f3n de la fructosa, es muy importante que mires los ingredientes de\u00a0la comida que compras.<\/p>\n<p style=\"text-align: justify\">\u00bfTe han diagnosticado malabsorci\u00f3n de fructosa? Evita alimentos que contengan fructosa al principio e intenta volverlos a introducir lentamente en tu dieta en peque\u00f1as cantidades. De esta forma podr\u00e1s identificar qu\u00e9 alimentos te sientan peor.<\/p>\n<p style=\"text-align: justify\"><strong>3. Histamina<\/strong><\/p>\n<p style=\"text-align: justify\">La histamina es una amina biog\u00e9nica presente en el tejido humano. Muchos alimentos contienen histamina. Normalmente, tomar histamina no es un problema. La histamina que se digiere se descompone r\u00e1pidamente por la enzima diamino oxidasa y se metaboliza. En el caso de la intolerancia a la histamina, sin embargo, la histamina no se descompone lo suficientemente r\u00e1pido y la amina biog\u00e9nica se almacena en el cuerpo. Los niveles altos de histamina en sangre pueden llevar a producir s\u00edntomas al\u00e9rgicos. Por eso la intolerancia a la histamina se considera una seudoalergia. Los s\u00edntomas son dolor de cabeza, rinitis, dificultad para respirar, sarpullidos y problemas gastrointestinales.<\/p>\n<p style=\"text-align: justify\">Algunos alimentos que contienen histamina:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 queso curado<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 pescado enlatado<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 alcohol<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 chucrut<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 embutido curado<\/li>\n<\/ul>\n<p style=\"text-align: justify\">B\u00e1sicamente todos los alimentos a\u00f1ejos contienen altos niveles de histamina. Adem\u00e1s, hay liberadores de histamina que liberan m\u00e1s histamina en el cuerpo y pueden darte problemas:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 chocolate<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 fresas<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 tomates<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 c\u00edtricos<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 aguacates<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 mariscos<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\u00bfQu\u00e9 puedes hacer si has tienes intolerancia a la histamina? Interrumpir el consumo de alimentos que la contengan. Seguramente puedas tolerar peque\u00f1as cantidades, pero tendr\u00e1s que averiguar cu\u00e1nto con el sistema de prueba y error. Adem\u00e1s habr\u00e1 veces en que la forma en que toleras un alimento dependa de c\u00f3mo te sientas ese d\u00eda.<\/p>\n<p style=\"text-align: justify\"><strong>4. Gluten<\/strong><\/p>\n<p style=\"text-align: justify\">La celiaqu\u00eda es una intolerancia alimentaria gen\u00e9tica al gluten (que no se debe confundir con alergia al trigo). Si no se trata puede llegar a producir da\u00f1os en la membrana mucosa del intestino delgado. El gluten es una prote\u00edna que se encuentra en los siguientes cereales:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 centeno<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 escanda<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 escanda verde<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 cebada<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 avena<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 farro<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 trigo khorasan<\/li>\n<\/ul>\n<p style=\"text-align: justify\">* La avena no suele contener gluten, pero a menudo se contamina al ser procesada. Si quieres estar seguro, busca informaci\u00f3n espec\u00edfica en el envase.<\/p>\n<p style=\"text-align: justify\">Los alimentos que contienen gluten inician una reacci\u00f3n autoinmune en los cel\u00edacos. Las c\u00e9lulas inmunes del cuerpo producen anticuerpos que atacan a las c\u00e9lulas del intestino delgado. Este proceso destruye la membrana mucosa y pone en peligro la habilidad del intestino delgado de absorber nutrientes (malabsorci\u00f3n). Los s\u00edntomas m\u00e1s comunes de la celiaqu\u00eda son la diarrea, el dolor de est\u00f3mago, gases y fatiga. Los ni\u00f1os tambi\u00e9n pueden sufrir des\u00f3rdenes en el crecimiento.<\/p>\n<p style=\"text-align: justify\">La \u00fanica \u201ccura\u201d para la celiaqu\u00eda es ce\u00f1irse a una dieta sin gluten. Todos los tipos de cereales que contengan gluten se deben evitar. Los alimentos procesados y envasados suelen ser problem\u00e1ticos porque pueden contener gluten. Unas meras trazas de esta prote\u00edna pueden desencadenar los s\u00edntomas que hemos mencionado. El etiquetado de los alimentos te puede ayudar a identificar qu\u00e9 alimentos est\u00e1n libres de gluten.<\/p>\n<p style=\"text-align: justify\">Algunas guarniciones que no contienen gluten son:<\/p>\n<ul style=\"text-align: justify\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 arroz<a href=\"https:\/\/www.emagister.com\/instituto-newmind-cursos-1115397-centrodetalles.htm?sid=21&amp;pfichas=12168\" target=\"_blank\" rel=\"attachment wp-att-39575 noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-39575 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/newmind.jpg\" alt=\"newmind\" width=\"226\" height=\"76\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/newmind.jpg 226w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/newmind-80x27.jpg 80w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/a><\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 quinoa<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 amaranto<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 ma\u00edz<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 trigo sarraceno<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 sorgo<\/li>\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 boniatos<\/li>\n<\/ul>\n<p style=\"text-align: justify\">S\u00f3lo el 1% de la poblaci\u00f3n mundial es cel\u00edaca. Pero hay mucha gente que sufre de sensibilidad al gluten, una enfermedad relativamente nueva de la que no se conoce mucho por el momento. Los s\u00edntomas son similares a los de la celiaqu\u00eda, pero la comida no da\u00f1a la membrana mucosa. Puedes evitar los s\u00edntomas haciendo una dieta sin gluten.<\/p>\n<p style=\"text-align: justify\">\u00bfCrees que padeces alguna de las intolerancias alimentarias que hemos mencionado? Antes de modificar tu dieta debes consultar a un m\u00e9dico para que te haga las pruebas correspondientes. \u00a1Los tests caseros no suelen ser fiables y adem\u00e1s son caros!<\/p>\n<p style=\"text-align: justify\">Si el diagn\u00f3stico es positivo, entonces te recomendamos que consultes a un dietista.<\/p>\n<p style=\"text-align: justify\">Si quieres formarte en el \u00e1mbito de la nutrici\u00f3n, y poder as\u00ed llegar a ser un profesional del sector, estos cursos te pueden ayudar a conseguirlo:<\/p>\n<ul>\n<li class=\"premium-title\">Curso Superior de nutrici\u00f3n avanzada<\/li>\n<li>Curso Experto en trastornos de conducta alimentaria<\/li>\n<\/ul>\n<div class=\"courses\"><div class=\"course\"><div class=\"inside\"><a href=\"https:\/\/www.emagister.com\/curso-experto-pnl-cursos-3458503.htm\" class=\"course_name directory\">Curso experto en PNL<\/a><div class=\"course_center\">INSTITUTO NEWMIND<\/div><div class=\"course_rating\"><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><\/div><div class=\"course_price\">95 \u20ac<\/div><a href=\"https:\/\/www.emagister.com\/curso-experto-pnl-cursos-3458503.htm\" class=\"course_button directory\">Ver m\u00e1s<\/a><\/div><\/div><div class=\"course\"><div class=\"inside\"><a href=\"https:\/\/www.emagister.com\/curso-experto-mindfulness-cursos-3396866.htm\" class=\"course_name directory\">Curso experto en mindfulness<\/a><div class=\"course_center\">INSTITUTO NEWMIND<\/div><div class=\"course_rating\"><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><\/div><div class=\"course_price\">75 \u20ac<\/div><a href=\"https:\/\/www.emagister.com\/curso-experto-mindfulness-cursos-3396866.htm\" class=\"course_button directory\">Ver m\u00e1s<\/a><\/div><\/div><div class=\"courses_more_wpr\"><span class=\"courses_more directory ofuscado\" onclick=\"window.location.href='https:\/\/www.emagister.com\/web\/search?q=INSTITUTO%20NEWMIND&#038;token=668d173c-ff0d-4d4f-bd13-3db820a3b96a&#038;segment=1&#038;sort=purePPL&#038;idCentro=99997192958079401036578245595238';\">Ver todos los cursos<svg height=\"20\" viewBox=\"0 0 20 20\" width=\"20\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m12.77 10.332-4.602 4.531c-.184.184-.48.184-.664 0l-.277-.277c-.184-.184-.184-.48 0-.664l3.996-3.922-3.993-3.922c-.183-.183-.183-.48 0-.664l.278-.277c.183-.184.48-.184.664 0l4.601 4.531c.18.184.18.48-.003.664z\" fill=\"#4cb7ac\" fill-rule=\"evenodd\"\/><\/svg><\/span><\/div><\/div>\n<h4 style=\"text-align: justify\">Fuente: Blog Instituto NEWMIND<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Una media hora despu\u00e9s de haber comido empiezas a experimentar dolores de est\u00f3mago o te tienes que ir pitando al &#8230; <a title=\"Las intolerancias alimenticias m\u00e1s frecuentes\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/\" aria-label=\"M\u00e1s en Las intolerancias alimenticias m\u00e1s frecuentes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":160,"featured_media":39588,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[818,1366,2832,3265,4671,5933,8306,8307,10141],"class_list":["post-39573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-alimentacion","tag-nutricion","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-tipos-de-alimentos","tag-intolerancias-alimenticias","tag-8306","tag-instituto-newmind","tag-noticiaselpais","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"","link_faldon":"","link_texto_faldon":"","estilo_titulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las intolerancias alimenticias m\u00e1s frecuentes - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las intolerancias alimenticias m\u00e1s frecuentes\" \/>\n<meta property=\"og:description\" content=\"Una media hora despu\u00e9s de haber comido empiezas a experimentar dolores de est\u00f3mago o te tienes que ir pitando al ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-24T10:50:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-03T07:53:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Gonz\u00e1lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Gonz\u00e1lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/\"},\"author\":{\"name\":\"Carlos Gonz\u00e1lez\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/9ce79b5f872bb07f9a9b2049231a2dd3\"},\"headline\":\"Las intolerancias alimenticias m\u00e1s frecuentes\",\"datePublished\":\"2017-05-24T10:50:59+00:00\",\"dateModified\":\"2018-07-03T07:53:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/\"},\"wordCount\":1512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/7-1.png\",\"keywords\":[\"alimentaci\u00f3n\",\"Nutrici\u00f3n\",\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"tipos de alimentos\",\"intolerancias alimenticias\",\"99997192958079401036578245595238\",\"INSTITUTO NEWMIND\",\"noticiasElPais\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/\",\"name\":\"Las intolerancias alimenticias m\u00e1s frecuentes - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/7-1.png\",\"datePublished\":\"2017-05-24T10:50:59+00:00\",\"dateModified\":\"2018-07-03T07:53:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/7-1.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/7-1.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/las-intolerancias-alimenticias-mas-frecuentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las intolerancias alimenticias m\u00e1s frecuentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/9ce79b5f872bb07f9a9b2049231a2dd3\",\"name\":\"Carlos Gonz\u00e1lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"caption\":\"Carlos Gonz\u00e1lez\"},\"sameAs\":[\"https:\\\/\\\/www.emagister.com\"],\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/cgonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las intolerancias alimenticias m\u00e1s frecuentes - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/","og_locale":"es_ES","og_type":"article","og_title":"Las intolerancias alimenticias m\u00e1s frecuentes","og_description":"Una media hora despu\u00e9s de haber comido empiezas a experimentar dolores de est\u00f3mago o te tienes que ir pitando al ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2017-05-24T10:50:59+00:00","article_modified_time":"2018-07-03T07:53:28+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png","type":"image\/png"}],"author":"Carlos Gonz\u00e1lez","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Carlos Gonz\u00e1lez","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/"},"author":{"name":"Carlos Gonz\u00e1lez","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/9ce79b5f872bb07f9a9b2049231a2dd3"},"headline":"Las intolerancias alimenticias m\u00e1s frecuentes","datePublished":"2017-05-24T10:50:59+00:00","dateModified":"2018-07-03T07:53:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/"},"wordCount":1512,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png","keywords":["alimentaci\u00f3n","Nutrici\u00f3n","Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","tipos de alimentos","intolerancias alimenticias","99997192958079401036578245595238","INSTITUTO NEWMIND","noticiasElPais"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/","url":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/","name":"Las intolerancias alimenticias m\u00e1s frecuentes - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png","datePublished":"2017-05-24T10:50:59+00:00","dateModified":"2018-07-03T07:53:28+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/05\/7-1.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/las-intolerancias-alimenticias-mas-frecuentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Las intolerancias alimenticias m\u00e1s frecuentes"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/9ce79b5f872bb07f9a9b2049231a2dd3","name":"Carlos Gonz\u00e1lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","caption":"Carlos Gonz\u00e1lez"},"sameAs":["https:\/\/www.emagister.com"],"url":"https:\/\/www.emagister.com\/blog\/author\/cgonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/39573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=39573"}],"version-history":[{"count":0,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/39573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/39588"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=39573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=39573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=39573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}