{"id":40128,"date":"2017-06-02T17:54:40","date_gmt":"2017-06-02T15:54:40","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=40128"},"modified":"2017-07-20T15:56:25","modified_gmt":"2017-07-20T13:56:25","slug":"la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/","title":{"rendered":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua"},"content":{"rendered":"<p style=\"text-align: justify;\">El inter\u00e9s en el aprendizaje de la lengua francesa se ha ido incrementando durante los \u00faltimos a\u00f1os en los diversos lugares del mundo, hasta el punto de convertirse en la cuarta lengua m\u00e1s hablada del mundo y la \u00fanica, junto con el ingl\u00e9s, que se habla en los cinco continentes.<!--more--><\/p>\n<p style=\"text-align: justify;\">A diferencia de lo que muchos piensan, el franc\u00e9s sigue siendo hoy d\u00eda un idioma influyente en ambientes de negocio internacional y exportaci\u00f3n, a pesar de la presencia cada vez mayor del ingl\u00e9s en continentes como el africano y el asi\u00e1tico. De hecho, el n\u00famero de personas que habla franc\u00e9s se ha triplicado en los \u00faltimos 60 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">El franc\u00e9s es lengua oficial en 32 pa\u00edses y es la lengua materna de 80 millones de personas. Se estima que lo hablan m\u00e1s de 220 millones de personas en todo el mundo. Francia, Canad\u00e1, B\u00e9lgica, Suiza, Luxemburgo, Andorra, M\u00f3naco, L\u00edbano, Vietnam, Marruecos, T\u00fanez y Camer\u00fan son algunos pa\u00edses en los que se utiliza de manera cotidiana el franc\u00e9s.<\/p>\n<p style=\"text-align: justify;\">En el \u00e1mbito de los negocios el franc\u00e9s es la tercera lengua m\u00e1s utilizada, mientras que en Internet es la cuarta. Adem\u00e1s, un 15% de la econom\u00eda mundial y un 12% del comercio internacional est\u00e1n representados por el espacio franc\u00f3fono. Es el idioma oficial de las instituciones internacionales.<a href=\"https:\/\/www.emagister.com\/sprachcaffe-language-plus-cursos-81126-centrodetalles.htm?sid=21&amp;pfichas=12168\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34879 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/Sin-t\u00edtulo-1.jpg\" alt=\"sprach\" width=\"250\" height=\"88\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/Sin-t\u00edtulo-1.jpg 250w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/01\/Sin-t\u00edtulo-1-80x28.jpg 80w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En buena parte del mundo es, adem\u00e1s, la segunda lengua que se estudia en el colegio, junto al ingl\u00e9s, la \u00fanica que se puede aprender en cualquier parte del mundo, considerando que en el mundo se hablan unas 5.000 lenguas.<\/p>\n<p style=\"text-align: justify;\">Estudiar franc\u00e9s te ayudar\u00e1 a potenciar y mejorar tus oportunidades laborales, son miles las empresas que exigen este idioma como requisito para incorporar a sus empleados. Para los hispanohablantes es una lengua asequible y familiar gracias al origen latino com\u00fan. Y, para los espa\u00f1oles en concreto, un idioma muy \u00fatil y f\u00e1cil de practicar.<\/p>\n<p style=\"text-align: justify;\">Si miramos al futuro, \u00c1frica es ya en la actualidad vista como un lugar importante para la comunidad franc\u00f3fona, continente con un gran potencial de desarrollo, se calcula que en el 2050 alcanzar\u00e1 los 850 millones de personas que lo hablar\u00e1n con mayor o menor nivel.<\/p>\n<p style=\"text-align: justify;\">De hecho, en los destinos que <a href=\"https:\/\/www.emagister.com\/sprachcaffe-language-plus-cursos-81126-centrodetalles.htm?sid=21&amp;pfichas=12168\" target=\"_blank\">Sprachcaffe Languages Plus<\/a> posee para aprender franc\u00e9s (Par\u00eds, Niza, Montrel y Rabat) se ha incrementado la demanda de los cursos est\u00e1ndar, intensivos y los campamentos de verano en el \u00faltimo lustro. Esto demuestra que todav\u00eda es buen momento para seguir mejorando los conocimientos de la lengua de Jean-Paul Sartre.<\/p>\n<h4 style=\"text-align: justify;\"><\/h4>\n<h4 style=\"text-align: justify;\">Fuente:\u00a0<span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Sprachcaffe Language Plus&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:8403841,&quot;3&quot;:[null,0],&quot;10&quot;:2,&quot;11&quot;:0,&quot;12&quot;:0,&quot;14&quot;:[null,2,0],&quot;15&quot;:&quot;Calibri, sans-serif&quot;,&quot;16&quot;:11,&quot;26&quot;:400}\"><a href=\"https:\/\/www.emagister.com\/sprachcaffe-language-plus-cursos-81126-centrodetalles.htm?sid=21&amp;pfichas=12168\" target=\"_blank\">Sprachcaffe Language Plus<\/a><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>El inter\u00e9s en el aprendizaje de la lengua francesa se ha ido incrementando durante los \u00faltimos a\u00f1os en los diversos &#8230; <a title=\"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/\" aria-label=\"M\u00e1s en La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":160,"featured_media":42771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[8454,8550,10141,931,2832,3265,7286,7287],"class_list":["post-40128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-aprender-frances","tag-idiomas","tag-noticiaselpais","tag-frances","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-7286","tag-sprachcaffe-language-plus","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"estilo_titulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua\" \/>\n<meta property=\"og:description\" content=\"El inter\u00e9s en el aprendizaje de la lengua francesa se ha ido incrementando durante los \u00faltimos a\u00f1os en los diversos ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-02T15:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-20T13:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"218\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Gonz\u00e1lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Gonz\u00e1lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/\"},\"author\":{\"name\":\"Carlos Gonz\u00e1lez\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/9ce79b5f872bb07f9a9b2049231a2dd3\"},\"headline\":\"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua\",\"datePublished\":\"2017-06-02T15:54:40+00:00\",\"dateModified\":\"2017-07-20T13:56:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/\"},\"wordCount\":466,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/4-20.jpg\",\"keywords\":[\"aprender franc\u00e9s\",\"Aprender idiomas\",\"noticiasElPais\",\"franc\u00e9s\",\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"53397020101267505467686667484569\",\"Sprachcaffe Language Plus\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/\",\"name\":\"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/4-20.jpg\",\"datePublished\":\"2017-06-02T15:54:40+00:00\",\"dateModified\":\"2017-07-20T13:56:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/4-20.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/4-20.jpg\",\"width\":580,\"height\":218},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/9ce79b5f872bb07f9a9b2049231a2dd3\",\"name\":\"Carlos Gonz\u00e1lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g\",\"caption\":\"Carlos Gonz\u00e1lez\"},\"sameAs\":[\"https:\\\/\\\/www.emagister.com\"],\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/cgonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/","og_locale":"es_ES","og_type":"article","og_title":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua","og_description":"El inter\u00e9s en el aprendizaje de la lengua francesa se ha ido incrementando durante los \u00faltimos a\u00f1os en los diversos ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2017-06-02T15:54:40+00:00","article_modified_time":"2017-07-20T13:56:25+00:00","og_image":[{"width":580,"height":218,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg","type":"image\/jpeg"}],"author":"Carlos Gonz\u00e1lez","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Carlos Gonz\u00e1lez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/"},"author":{"name":"Carlos Gonz\u00e1lez","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/9ce79b5f872bb07f9a9b2049231a2dd3"},"headline":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua","datePublished":"2017-06-02T15:54:40+00:00","dateModified":"2017-07-20T13:56:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/"},"wordCount":466,"commentCount":5,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg","keywords":["aprender franc\u00e9s","Aprender idiomas","noticiasElPais","franc\u00e9s","Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","53397020101267505467686667484569","Sprachcaffe Language Plus"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/","url":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/","name":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg","datePublished":"2017-06-02T15:54:40+00:00","dateModified":"2017-07-20T13:56:25+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/06\/4-20.jpg","width":580,"height":218},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/la-importancia-del-idioma-frances-sigue-creciendo-numero-personas-la-hablan-segunda-tercera-lengua-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"La importancia del idioma franc\u00e9s sigue creciendo en n\u00famero de personas que la hablan como segunda o tercera lengua"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/9ce79b5f872bb07f9a9b2049231a2dd3","name":"Carlos Gonz\u00e1lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c871c929d17d4969e1ce19e7f4e6f90f185d2976651045a8a8cd5eb86c1d5ef?s=96&r=g","caption":"Carlos Gonz\u00e1lez"},"sameAs":["https:\/\/www.emagister.com"],"url":"https:\/\/www.emagister.com\/blog\/author\/cgonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/40128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=40128"}],"version-history":[{"count":0,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/40128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/42771"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=40128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=40128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=40128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}