{"id":54529,"date":"2017-12-12T12:14:13","date_gmt":"2017-12-12T11:14:13","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=54529"},"modified":"2017-12-20T09:31:25","modified_gmt":"2017-12-20T08:31:25","slug":"aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/","title":{"rendered":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses"},"content":{"rendered":"<p style=\"text-align: justify;\">Las <strong>aulas de acogida<\/strong> son un recurso del sistema educativo catal\u00e1n dirigido a alumnos reci\u00e9n llegados de otro pa\u00eds. Concretamente, este espacio procura que los alumnos que desconocen la<a href=\"https:\/\/www.emagister.com\/cursos-catalan-tematica-161.htm\"><strong> lengua catalana<\/strong><\/a> adquieran el idioma y se integren con sus compa\u00f1eros en <strong>igualdad de oportunidades<\/strong>. Las aulas pueden tener diferentes tipos de usuario. Por ejemplo, alumnos latinoamericanos que hablan espa\u00f1ol y que, por lo tanto, conocen otra lengua rom\u00e1nica o alumnos que tienen como lengua nativa un idioma mucho m\u00e1s lejano. Sin embargo, las semejanzas entre lenguas no siempre son garant\u00eda de aprender antes un idioma. Tambi\u00e9n entran en juego la facilidad para comunicarse, la capacidad de retener informaci\u00f3n o la predisposici\u00f3n acad\u00e9mica. Sea como sea, el objetivo es que el estudiante se incorpore a las clases ordinarias con un<strong> buen dominio escrito y oral<\/strong>.<!--more--><\/p>\n<p style=\"text-align: justify;\">De todas formas, para que los alumnos est\u00e9n en contacto con sus compa\u00f1eros este sistema combina las <strong>sesiones ordinarias<\/strong> con las sesiones en el aula de acogida. Es decir, los alumnos pasan una parte de las horas con toda la clase y otra parte con alumnos que, al igual que ellos, acaban de emigrar. As\u00ed pues, se alterna la <strong>asistencia m\u00e1s personalizada<\/strong> con la integraci\u00f3n en el grupo-clase. Este programa de acogida ha dado resultados muy positivos en Catalu\u00f1a, un territorio que tradicionalmente recibe personas de lugares muy diversos. La idea es que el estudiante se sienta arropado desde el primer d\u00eda y, progresivamente, vaya abandonado las sesiones hasta participar solamente en el aula ordinaria.<\/p>\n<p style=\"text-align: justify;\">\u00bfTe gustar\u00eda contribuir a la integraci\u00f3n de personas que han emigrado? \u00bfTienes facilidad para ense\u00f1ar lenguas? Pues quiz\u00e1 puedes combinar estas dos capacidades en un\u00a0<strong>aula de acogida<\/strong>. Te explicamos qu\u00e9 conocimientos necesitas y en qu\u00e9 niveles podr\u00edas impartir clase.<\/p>\n<h3 style=\"text-align: justify;\"><strong>\u00bfQu\u00e9 se necesita para trabajar en una aula de acogida?<\/strong><\/h3>\n<p style=\"text-align: justify;\">En primer lugar, hay que tener claro que las aulas de acogida existen en<strong> diferentes niveles<\/strong> del sistema educativo. Es decir, se ofrecen tanto a los alumnos de <strong>Primaria<\/strong> como a los de <strong>Secundaria<\/strong>. As\u00ed pues, el perfil profesional del profesor puede variar sustancialmente. Desde un <a href=\"https:\/\/www.emagister.com\/universidades\/grado-maestro-educacion-primaria-tit-264.htm\"><strong>maestro de\u00a0Educaci\u00f3n Primaria<\/strong><\/a>, hasta un<a href=\"https:\/\/www.emagister.com\/universidades\/licenciatura-psicopedagogia-tit-160.htm\"><strong> psicopedagogo<\/strong><\/a> o un <a href=\"https:\/\/www.emagister.com\/blog\/se-dedica-filologo\/\"><strong>fil\u00f3logo<\/strong><\/a>. Adem\u00e1s, el nivel inicial no siempre es el mismo. Por ejemplo, algunas personas necesitar\u00e1n empezar de cero y aprender el vocabulario m\u00e1s b\u00e1sico, mientras que otras deber\u00e1n llegar a un nivel m\u00e1s elevado para superar el curr\u00edculum de la ESO y del Bachillerato. As\u00ed pues, \u00bfqu\u00e9 formaci\u00f3n debemos tener para trabajar en una aula de acogida?<\/p>\n<ul style=\"text-align: justify;\">\n<li>Los profesionales que acogen a alumnos emigrados en los <strong>centros de primaria<\/strong> necesitan conocimientos transversales. Por una parte, hay que ayudar al alumno a que gestione sus emociones; por otra, hay que tener un buen dominio escrito y oral de la lengua catalana. As\u00ed pues, tanto un psicopedagogo como un maestro pueden encajar en el perfil.<\/li>\n<li>En los <a href=\"https:\/\/www.emagister.com\/master-oficial\/master-oficial-ensenanza-secundaria-tematica-783.htm\"><strong>centros de Secundaria<\/strong><\/a> son los profesores de lengua y literatura (normalmente fil\u00f3logos) los que asumen este rol. En este sentido, es recomendable que la persona tenga conocimientos como profesor de <strong><a href=\"https:\/\/www.emagister.com\/cursos-catalan-para-extranjeros-kwes-1000004407.htm\">lengua extranjera<\/a><\/strong> y que trabaje codo a codo con otras figuras del centro: por ejemplo, el tutor de cada alumno o el orientador formativo y profesional.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Hay que tener en cuenta que, normalmente, el aula de acogida<strong> es una parte m\u00e1s<\/strong> del trabajo de un maestro\/profesor. As\u00ed pues, es probable que esta persona tenga su propia tutor\u00eda o imparta clase a otros grupos. \u00bfTe gustar\u00eda trabajar con alumnos reci\u00e9n llegados a Catalu\u00f1a? En Emagister tenemos los cursos necesarios para que ejerzas con garant\u00edas. \u00a1Ponte en contacto con los centros e inf\u00f3rmate!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las aulas de acogida son un recurso del sistema educativo catal\u00e1n dirigido a alumnos reci\u00e9n llegados de otro pa\u00eds. Concretamente, &#8230; <a title=\"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/\" aria-label=\"M\u00e1s en Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":255,"featured_media":54531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8329],"tags":[799,1001,1793,7242,8692,9465],"class_list":["post-54529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-titulaciones","tag-aprender-catalan","tag-catalan","tag-cataluna","tag-inmersion-linguistica","tag-formacion-cataluna","tag-aulas-de-acogida","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"estilo_titulo":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses - Blog Emagister<\/title>\n<meta name=\"description\" content=\"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses\" \/>\n<meta property=\"og:description\" content=\"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-12T11:14:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-20T08:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"521\" \/>\n\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Gonz\u00e0lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Gonz\u00e0lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/\"},\"author\":{\"name\":\"Laura Gonz\u00e0lez\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/141b37b56d8029c99a901d83b24ec28f\"},\"headline\":\"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses\",\"datePublished\":\"2017-12-12T11:14:13+00:00\",\"dateModified\":\"2017-12-20T08:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/\"},\"wordCount\":644,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ThinkstockPhotos-506135132.jpg\",\"keywords\":[\"aprender catal\u00e1n\",\"catal\u00e1n\",\"Catalu\u00f1a\",\"inmersi\u00f3n ling\u00fc\u00edstica\",\"formaci\u00f3n catalu\u00f1a\",\"aulas de acogida\"],\"articleSection\":[\"Sistema educativo y titulaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/\",\"name\":\"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ThinkstockPhotos-506135132.jpg\",\"datePublished\":\"2017-12-12T11:14:13+00:00\",\"dateModified\":\"2017-12-20T08:31:25+00:00\",\"description\":\"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ThinkstockPhotos-506135132.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/ThinkstockPhotos-506135132.jpg\",\"width\":521,\"height\":331},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema educativo y titulaciones\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/titulaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/141b37b56d8029c99a901d83b24ec28f\",\"name\":\"Laura Gonz\u00e0lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g\",\"caption\":\"Laura Gonz\u00e0lez\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/laura-gonzalez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses - Blog Emagister","description":"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/","og_locale":"es_ES","og_type":"article","og_title":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses","og_description":"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.","og_url":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2017-12-12T11:14:13+00:00","article_modified_time":"2017-12-20T08:31:25+00:00","og_image":[{"width":521,"height":331,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg","type":"image\/jpeg"}],"author":"Laura Gonz\u00e0lez","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Laura Gonz\u00e0lez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/"},"author":{"name":"Laura Gonz\u00e0lez","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/141b37b56d8029c99a901d83b24ec28f"},"headline":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses","datePublished":"2017-12-12T11:14:13+00:00","dateModified":"2017-12-20T08:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/"},"wordCount":644,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg","keywords":["aprender catal\u00e1n","catal\u00e1n","Catalu\u00f1a","inmersi\u00f3n ling\u00fc\u00edstica","formaci\u00f3n catalu\u00f1a","aulas de acogida"],"articleSection":["Sistema educativo y titulaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/","url":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/","name":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg","datePublished":"2017-12-12T11:14:13+00:00","dateModified":"2017-12-20T08:31:25+00:00","description":"\u00bfVives en Catalu\u00f1a y te gustar\u00eda ayudar a alumnos reci\u00e9n llegados de otro lugar del mundo? Las aulas de acogida son un espacio de integraci\u00f3n y aprendizaje.","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/12\/ThinkstockPhotos-506135132.jpg","width":521,"height":331},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/aulas-de-acogida-el-reto-de-trabajar-con-alumnos-de-otros-paises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sistema educativo y titulaciones","item":"https:\/\/www.emagister.com\/blog\/titulaciones\/"},{"@type":"ListItem","position":3,"name":"Aulas de acogida: el reto de trabajar con alumnos de otros pa\u00edses"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/141b37b56d8029c99a901d83b24ec28f","name":"Laura Gonz\u00e0lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9efac18419d3b71d38e95cbb8122c1560396cf37c42a8e40dd590bdbdcdd8ffd?s=96&r=g","caption":"Laura Gonz\u00e0lez"},"url":"https:\/\/www.emagister.com\/blog\/author\/laura-gonzalez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/54529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/255"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=54529"}],"version-history":[{"count":0,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/54529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/54531"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=54529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=54529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=54529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}