{"id":93247,"date":"2019-09-30T15:22:36","date_gmt":"2019-09-30T13:22:36","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=93247"},"modified":"2021-04-27T10:19:37","modified_gmt":"2021-04-27T08:19:37","slug":"que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/","title":{"rendered":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>El ultrasonido focalizado de alta intensidad (HIFU)<\/strong> es un tratamiento relativamente nuevo para el estiramiento de la piel que algunos consideran un reemplazo no invasivo para los estiramientos faciales. Utiliza energ\u00eda de ultrasonido para fomentar la producci\u00f3n de col\u00e1geno, lo que da como resultado una piel m\u00e1s firme.<!--more--><\/p>\n<h3 style=\"text-align: justify;\"><strong>\u00bfQui\u00e9n puede trabajarlo y como hacerlo con seguridad y efectividad?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Los ultrasonidos focalizados se incorporaron al mercado espa\u00f1ol en el campo de la medicina est\u00e9tica. Los doctores disponen de las competencias profesionales y conocimientos adecuados para su uso correcto.<\/p>\n<h3 style=\"text-align: justify;\"><strong>\u00bfPuede usarlo una t\u00e9cnico superior en est\u00e9tica, o una enfermera?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Si podr\u00edan pero cumpliendo una serie de requisitos:<\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong>\u00a0En una cl\u00ednica supervisada por un m\u00e9dico<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong>\u00a0En un centro de est\u00e9tica (sin supervisi\u00f3n m\u00e9dica).<\/p>\n<p><strong>3)<\/strong>\u00a0En una cl\u00ednica supervisada por un m\u00e9dico.<\/p>\n<p style=\"text-align: justify;\">Un profesional con formaci\u00f3n en est\u00e9tica superior o un profesional de la rama sanitaria\u00a0<strong>podr\u00eda trabajarlo en un centro m\u00e9dico est\u00e9tico supervisado por un doctor<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La supervisi\u00f3n supone la recepci\u00f3n por parte del doctor del paciente, diagn\u00f3stico y comunicaci\u00f3n de las pautas a seguir por el t\u00e9cnico y finalizaci\u00f3n de la consulta por parte del doctor.<\/p>\n<p style=\"text-align: justify;\">La realidad es que en pocas ocasiones se da la supervisi\u00f3n correcta y esto conlleva una serie de riesgos para el consumidor y responsabilidades para el t\u00e9cnico y para el mismo doctor o gerente del centro.<\/p>\n<h3 style=\"text-align: justify;\"><strong>\u00bfPodr\u00edan trabajarlo sin supervisi\u00f3n m\u00e9dica?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Si dicha supervisi\u00f3n no se realiza correctamente, el profesional t\u00e9cnico <strong>solo podr\u00eda si<\/strong> <strong>dispone de una cualificaci\u00f3n profesional espec\u00edfica<\/strong>\u00a0ya que podr\u00eda incurrir en responsabilidades administrativas, civiles e incluso penales en caso de producir cualquier da\u00f1o de un \u00f3rgano ( por ejemplo, la piel) al paciente\u00a0 durante o por el tratamiento.<\/p>\n<h4><strong style=\"text-align: justify;\"><u>En un centro de est\u00e9tica (sin supervisi\u00f3n m\u00e9dica):<\/u><\/strong><\/h4>\n<p style=\"text-align: justify;\">Un profesional con formaci\u00f3n en est\u00e9tica superior o un profesional de la rama sanitaria\u00a0<strong>solo <\/strong>podr\u00eda trabajarlo en un centro est\u00e9tico o m\u00e9dico-est\u00e9tico sin supervisi\u00f3n m\u00e9dica si se\u00a0<strong>especializa con una cualificaci\u00f3n profesional espec\u00edfica.\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\">Los tratamientos de aparatolog\u00eda electro-est\u00e9tica y muchos otros est\u00e1n proliferando y siendo utilizados en centros de est\u00e9tica no sanitarios.<\/p>\n<p style=\"text-align: justify;\">Todo ello provoca que se produzcan <strong>vac\u00edos legales<\/strong> en el sector, aumentando peligrosamente el grado de intrusismo profesional.<\/p>\n<p style=\"text-align: justify;\">El uso de estos equipos electro-est\u00e9ticos por personal no cualificado est\u00e1 comenzando a derivar en pacientes y por lo tanto afectando a la salud y a la posici\u00f3n indefensa de los consumidores, lo que est\u00e1 conllevando un mayor control por parte de las asociaciones m\u00e9dicas y por parte de la administraci\u00f3n y autoridad laboral.<\/p>\n<p style=\"text-align: justify;\">Los ultrasonidos de baja frecuencia para fines est\u00e9ticos, como la cavitaci\u00f3n, pueden ser trabajados por un profesional con FP Superior en est\u00e9tica, ya que est\u00e1n contemplados dentro de la cualificaci\u00f3n profesional de eq<\/p>\n<p><span style=\"text-align: justify;\">uipos electro-est\u00e9ticos desarrollada en la formaci\u00f3n profesional superior en est\u00e9tica (Real Decreto 790\/2007, de 15 de junio).<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>El problema<\/strong>\u00a0es que esta variante de ultrasonido focalizado HIFU no exist\u00eda y por lo tanto no est\u00e1 incluida dentro de los contenidos formativos y las competencias profesionales de dicha formaci\u00f3n profesional. Lo que conlleva un <strong>vac\u00edo legal<\/strong>.\u00a0<a href=\"https:\/\/www.emagister.com\/ivab-instituto-valenciano-antienvejecimiento-bienestar-cursos-1154196-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-87599 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/06\/IVAB-LOGO-e1560246599940.png\" alt=\"\" width=\"222\" height=\"96\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/06\/IVAB-LOGO-e1560246599940.png 222w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/06\/IVAB-LOGO-e1560246599940-80x35.png 80w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/06\/IVAB-LOGO-e1560246599940-220x96.png 220w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/a><\/p>\n<h3><strong>\u00bfQu\u00e9 ocurre si el profesional de la est\u00e9tica realiza un tratamiento que no est\u00e1 regulado (vac\u00edo legal)?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Los seguros de responsabilidad civil no cubren ante actividades profesionales en vac\u00edo legal (no reguladas).<\/p>\n<p style=\"text-align: justify;\">Ello conlleva una posici\u00f3n indefensa del consumidor ante cualquier problema y por supuesto un gran riesgo econ\u00f3mico y legal para el profesional ante cualquier problema que se pueda derivar.<\/p>\n<h3><strong>\u00bfC\u00f3mo y d\u00f3nde se pueden formar los profesionales que quieran trabajar los ultrasonidos focalizados HIFU con seguridad y siendo cubiertos por seguro de responsabilidad civil en Espa\u00f1a?<\/strong><\/h3>\n<p style=\"text-align: justify;\">Actualmente gran parte de estas nuevas t\u00e9cnicas se cubren con cualificaciones profesionales europeas desarrolladas por la Uni\u00f3n Europea bajo el Tratado de Lisboa <em>firmado por Espa\u00f1a el 13 de diciembre de 2007<\/em> y la Ley para el empleo y la movilidad <em>art\u00edculo 13 Directiva 2005\/36\/CE<\/em>. La Uni\u00f3n europea dispone de capacidad de complementar la educaci\u00f3n de los pa\u00edses miembros de la Uni\u00f3n Europea con el objetivo principal de velar por la seguridad del consumidor y fomentar la movilidad.<\/p>\n<p style=\"text-align: justify;\">El perfil que puede acceder a formarse de una manera directa, son profesionales que dispongan de FP superior en Est\u00e9tica o profesionales de la rama sanitaria, como por ejemplo, enfermer\u00eda, fisioterapia, farmacia\u2026<\/p>\n<h3 style=\"text-align: justify;\"><strong>\u00bfLos profesionales de la est\u00e9tica se pueden formar en cualquier sitio?<\/strong><\/h3>\n<p style=\"text-align: justify;\"><strong>NO.<\/strong><\/p>\n<p style=\"text-align: justify;\">Las formaciones realizadas por entidades privadas como por ejemplo fabricantes, laboratorios, distribuidores, sin un criterio unificado, sin una regulaci\u00f3n espec\u00edfica y sin un organismo oficial que respalde la calidad y objetividad de la formaci\u00f3n y examinaci\u00f3n\u00a0<strong>no capacitan a los profesionales para el ejercicio de la est\u00e9tica profesional.<\/strong><\/p>\n<h4 style=\"text-align: center;\"><strong>ES FUNDAMENTAL QUE LA FORMACI\u00d3N SEA REGULADA<\/strong><\/h4>\n<h3><strong>\u00bfD\u00f3nde formarse en cualificaciones profesionales europeas oficiales de la rama de est\u00e9tica avanzada profesional?<\/strong><\/h3>\n<p style=\"text-align: justify;\">El <strong>IVAB<\/strong> (<strong>Instituto Valenciano de Antienvejecimiento y Bienestar<\/strong>) es el \u00fanico centro de formaci\u00f3n en Espa\u00f1a que imparte y prepara a los alumnos para superar en Espa\u00f1a los ex\u00e1menes oficiales que otorgan dichas cualificaciones europeas.<\/p>\n<p style=\"text-align: justify;\">Est\u00e1 abierto el plazo de inscripci\u00f3n para la \u00fanica formaci\u00f3n oficial de ultrasonidos en la que se incluye Hifu (Ultrasonido focalizado) en Espa\u00f1a.<\/p>\n<p><strong>SOLICITA INFORMACI\u00d3N<\/strong><\/p>\n<p style=\"text-align: justify;\">El objetivo principal es la capacitaci\u00f3n para la aplicaci\u00f3n profesional de los equipos de ultrasonidos en todas sus variantes. Proporcionando las \u00faltimas t\u00e9cnicas en todas sus posibilidades de presentaci\u00f3n hasta ultrasonido focalizado (HIFU), seg\u00fan los objetivos est\u00e9ticos de tratamiento.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Las ventajas principales de esta cualificaci\u00f3n profesional:<\/strong><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Con la cualificaci\u00f3n profesional se accede a la cobertura de responsabilidad civil espec\u00edfica en Espa\u00f1a.<\/li>\n<li>Al d\u00eda siguiente de finalizar, el profesional est\u00e1 preparado para trabajar con seguridad y eficacia.<\/li>\n<li>Ense\u00f1anza de m\u00e1xima calidad con un contenido m\u00e1s completo y unificado a nivel europeo. <strong>Es la formaci\u00f3n con mayor respaldo internacional existente en la actualidad, v\u00e1lida en Espa\u00f1a, Europa y m\u00e1s de 50 paises a nivel mundial<\/strong> (<em>pa\u00edses de la Commonwealth, por ej. Australia, Nueva Zelanda, Canada, etc\u2026<\/em>)<\/li>\n<li>M\u00e1s del 50% de pr\u00e1ctica real con clientes.<\/li>\n<li>Impartida por docentes de prestigio. Anatom\u00eda, fisiolog\u00eda y patolog\u00edas impartida por doctores especializados y pr\u00e1cticas impartidas por docentes t\u00e9cnicos especializados.<\/li>\n<li>Acceder a una bolsa de empleo para Espa\u00f1a y Reino Unido.<\/li>\n<li>Obtener un mayor reconocimiento laboral.<\/li>\n<li>Flexibilidad de horario y compatibilidad con la vida laboral y personal.<\/li>\n<li>Titulaciones consagradas en la Ley para el empleo y movilidad art\u00edculo 13 Directiva 2005\/36\/CE.<\/li>\n<li>Otorgan el Certificado Europass para la empleabilidad a trav\u00e9s de Europa.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>\u00a1INSCR\u00cdBETE YA, \u00daLTIMAS PLAZAS!<\/strong><\/p>\n<p>\u00bfQuieres descubrir toda la oferta formativa del centro IVAB Instituto Valenciano de Antienvejecimiento y Bienestar? P\u00f3nte en contacto con <a href=\"https:\/\/www.emagister.com\" target=\"_blank\" rel=\"noopener\"><strong>Emagister<\/strong> <\/a>y te ayudaremos a encontrar el curso perfecto para ti.<\/p>\n<p>Si eres ya un estudiante de este centro y deseas contarnos tu experiencia con Cursos IVAB Instituto Valenciano de Antienvejecimiento y Bienestar, \u00a1deja tu opini\u00f3n gracias a este <strong><a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\">formulario<\/a><\/strong> y ayuda otros estudiantes como tu a escoger mejor!<\/p>\n<div class=\"courses\"><div class=\"course\"><div class=\"inside\"><a href=\"https:\/\/www.emagister.com\/titulo-oficial-especialista-micropuncion-piel-cursos-3587426.htm\" class=\"course_name directory\">T\u00edtulo OFICIAL Especialista en Micropunci\u00f3n en piel<\/a><div class=\"course_center\">IVAB Instituto Valenciano de Antienvejecimiento y Bienestar<\/div><div class=\"course_rating\"><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><\/div><div class=\"course_price\"><div class=\"course_price_text\">Precio a consultar<\/div><\/div><a href=\"https:\/\/www.emagister.com\/titulo-oficial-especialista-micropuncion-piel-cursos-3587426.htm\" class=\"course_button directory\">Ver m\u00e1s<\/a><\/div><\/div><div class=\"course\"><div class=\"inside\"><a href=\"https:\/\/www.emagister.com\/titulo-oficial-experto-laser-luz-para-depilacion-cursos-3582099.htm\" class=\"course_name directory\">T\u00edtulo OFICIAL Experto en l\u00e1ser y luz para depilaci\u00f3n<\/a><div class=\"course_center\">IVAB Instituto Valenciano de Antienvejecimiento y Bienestar<\/div><div class=\"course_rating\"><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><svg fill=\"none\" height=\"13\" viewBox=\"0 0 13 13\" width=\"13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m5.79999.990059-1.58 3.220001-3.549999.52c-.6399996.09-.9.87-.43 1.32l2.559999 2.51-.6 3.53004c-.11.64.56 1.12 1.13.82l3.18-1.67v-10.680041c-.29 0-.56.14-.71.43z\" fill=\"#f5ba41\"\/><path d=\"m10.8 12.0901-.6-3.53004 2.57-2.5c.46-.45.21-1.23-.43-1.33l-3.56-.52-1.58-3.220001c-.15-.28-.42-.43-.7-.43v10.680041l3.18 1.67c.56.3 1.23-.18 1.12-.82z\" fill=\"#e5e5e5\"\/><\/svg><\/i><\/div><div class=\"course_price\"><div class=\"course_price_text\">Precio a consultar<\/div><\/div><a href=\"https:\/\/www.emagister.com\/titulo-oficial-experto-laser-luz-para-depilacion-cursos-3582099.htm\" class=\"course_button directory\">Ver m\u00e1s<\/a><\/div><\/div><div class=\"courses_more_wpr\"><span class=\"courses_more directory ofuscado\" onclick=\"window.location.href='https:\/\/www.emagister.com\/web\/search?q=IVAB%20Instituto%20Valenciano%20de%20Antienvejecimiento%20y%20Bienestar&#038;token=668d173c-ff0d-4d4f-bd13-3db820a3b96a&#038;segment=1&#038;sort=purePPL&#038;idCentro=99997192958079401036578245634037';\">Ver todos los cursos<svg height=\"20\" viewBox=\"0 0 20 20\" width=\"20\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"m12.77 10.332-4.602 4.531c-.184.184-.48.184-.664 0l-.277-.277c-.184-.184-.184-.48 0-.664l3.996-3.922-3.993-3.922c-.183-.183-.183-.48 0-.664l.278-.277c.183-.184.48-.184.664 0l4.601 4.531c.18.184.18.48-.003.664z\" fill=\"#4cb7ac\" fill-rule=\"evenodd\"\/><\/svg><\/span><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El ultrasonido focalizado de alta intensidad (HIFU) es un tratamiento relativamente nuevo para el estiramiento de la piel que algunos &#8230; <a title=\"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/\" aria-label=\"M\u00e1s en \u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":249,"featured_media":93258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[2832,3173,10840,10841],"class_list":["post-93247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-noticias-de-centros-de-formacion","tag-centro-de-formacion","tag-10840","tag-ivab-instituto-valenciano-de-antienvejecimiento-y-bienestar","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Consulta los cursos del IVAB","link_faldon":"https:\/\/www.emagister.com\/ivab-instituto-valenciano-antienvejecimiento-bienestar-cursos-1154196-centrodetalles.htm","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a? - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?\" \/>\n<meta property=\"og:description\" content=\"El ultrasonido focalizado de alta intensidad (HIFU) es un tratamiento relativamente nuevo para el estiramiento de la piel que algunos ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-30T13:22:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T08:19:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/\"},\"author\":{\"name\":\"Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/3300b7adf3ccc45da42dc883c2932c22\"},\"headline\":\"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?\",\"datePublished\":\"2019-09-30T13:22:36+00:00\",\"dateModified\":\"2021-04-27T08:19:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/\"},\"wordCount\":1286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/GettyImages-1014126288.jpg\",\"keywords\":[\"Noticias de centros de formaci\u00f3n\",\"centro de formaci\u00f3n\",\"99997192958079401036578245634037\",\"IVAB Instituto Valenciano de Antienvejecimiento y Bienestar\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/\",\"name\":\"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/GettyImages-1014126288.jpg\",\"datePublished\":\"2019-09-30T13:22:36+00:00\",\"dateModified\":\"2021-04-27T08:19:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/GettyImages-1014126288.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/GettyImages-1014126288.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Close-up of young beautiful woman smiling during cosmetic procedure - special massage for face in spa salon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/3300b7adf3ccc45da42dc883c2932c22\",\"name\":\"Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g\",\"caption\":\"Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a? - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?","og_description":"El ultrasonido focalizado de alta intensidad (HIFU) es un tratamiento relativamente nuevo para el estiramiento de la piel que algunos ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2019-09-30T13:22:36+00:00","article_modified_time":"2021-04-27T08:19:37+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg","type":"image\/jpeg"}],"author":"Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Emagister","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/"},"author":{"name":"Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/3300b7adf3ccc45da42dc883c2932c22"},"headline":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?","datePublished":"2019-09-30T13:22:36+00:00","dateModified":"2021-04-27T08:19:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/"},"wordCount":1286,"commentCount":0,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg","keywords":["Noticias de centros de formaci\u00f3n","centro de formaci\u00f3n","99997192958079401036578245634037","IVAB Instituto Valenciano de Antienvejecimiento y Bienestar"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/","url":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/","name":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg","datePublished":"2019-09-30T13:22:36+00:00","dateModified":"2021-04-27T08:19:37+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/09\/GettyImages-1014126288.jpg","width":1920,"height":1280,"caption":"Close-up of young beautiful woman smiling during cosmetic procedure - special massage for face in spa salon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/que-son-los-ultrasonidos-focalizados-hifu-y-quien-lo-puede-trabajar-con-seguridad-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 son los ultrasonidos focalizados HIFU y qui\u00e9n lo puede trabajar con seguridad en Espa\u00f1a?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/3300b7adf3ccc45da42dc883c2932c22","name":"Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74b3e8dfcd32a15800dd739d2be47f9fd51a1f64b8f301298a07de8260c02ff5?s=96&r=g","caption":"Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/93247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=93247"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/93247\/revisions"}],"predecessor-version":[{"id":109141,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/93247\/revisions\/109141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/93258"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=93247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=93247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=93247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}