{"id":99053,"date":"2020-01-23T17:01:41","date_gmt":"2020-01-23T16:01:41","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=99053"},"modified":"2024-04-17T13:01:59","modified_gmt":"2024-04-17T11:01:59","slug":"que-es-y-que-no-es-emagister","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/","title":{"rendered":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?"},"content":{"rendered":"<p>\u00bfQuieres estudiar pero no sabes qu\u00e9, d\u00f3nde, c\u00f3mo ni a qu\u00e9 precio? <strong>Bienvenido a <a href=\"https:\/\/www.emagister.com\">Emagister<\/a><\/strong>, donde la formaci\u00f3n se vuelve realidad. Desde el nacimiento de Emagister en el 2000 hemos querido trasmitir <strong>nuestros valores<\/strong> y la importancia de la educaci\u00f3n en todo el mundo, ayudando a los estudiantes a elegir la formaci\u00f3n que m\u00e1s se adecue a la situaci\u00f3n y gustos.<\/p>\n<p>Por todo ello, desde la compa\u00f1\u00eda tenemos una <strong>misi\u00f3n<\/strong> que refuerza sus ideales en ayudar a las personas a ser mejores a trav\u00e9s de la formaci\u00f3n. Y, adem\u00e1s, generamos la <strong>visi\u00f3n<\/strong> de nuestros clientes comparando entre la oferta formativa m\u00e1s relevante y consiguiendo el mejor precio y experiencia para que los alumnos puedan encontrar la mejor educaci\u00f3n enfocada a sus necesidades.<\/p>\n<p>Si no sabes c\u00f3mo funcionamos y estas interesado en nosotros, qu\u00e9date leyendo este <em>post<\/em> y tus dudas se disipar\u00e1n en un abrir y cerrar de ojos.<!--more--><\/p>\n<h1>\u00bfQu\u00e9 es Emagister?<\/h1>\n<p>Emagister es el <strong>buscador perfecto para encontrar la formaci\u00f3n<\/strong> que te mereces. En nuestra p\u00e1gina web puedes encontrar m\u00e1s de 1 mill\u00f3n de cursos y m\u00e1s de 100.000 centros de formaci\u00f3n que te ayudar\u00e1n a estudiar aquello que llevas tiempo deseando.<\/p>\n<p>Entra en <strong><a href=\"https:\/\/www.emagister.com\">Emagister<\/a><\/strong>, <span style=\"text-decoration: underline;\">busca<\/span> la tem\u00e1tica que quieres estudiar, <span style=\"text-decoration: underline;\">compara<\/span> los precios, comentarios, centros de formaci\u00f3n y <span style=\"text-decoration: underline;\">pide informaci\u00f3n<\/span> para solucionar todas tus dudas sobre el certificado, curso, formaci\u00f3n profesional, grado, m\u00e1ster, postgrado, doctorado u oposiciones que est\u00e9s buscando. En definitiva, <strong>somos el puente entre el alumno y el centro formativo donde estudiar\u00e1s.<\/strong><\/p>\n<p>Con todas nuestras herramientas para ayudarte, <strong>ponemos a tu alcance la formaci\u00f3n<\/strong> en distintos centros educativos. A trav\u00e9s de nuestro cat\u00e1logo puedes seleccionar los filtros que m\u00e1s te interesen para llegar m\u00e1s r\u00e1pido a tu b\u00fasqueda exacta.<\/p>\n<p>Nuestro objetivo es que aquellos interesados en estudiar puedan encontrar, a trav\u00e9s de nosotros, mediante nuestra ayuda, la formaci\u00f3n que m\u00e1s se adapte a sus necesidades.<\/p>\n<h1>\u00bfQu\u00e9 no es Emagister?<\/h1>\n<p>Muchos sois los que os pon\u00e9is en contacto con nosotros pens\u00e1ndoos que somos un centro de formaci\u00f3n, pero no. Hacemos la funci\u00f3n de <strong>intermediario<\/strong> entre vosotros y los centros educativos para conseguiros la mejor opci\u00f3n que se adapte a vuestras necesidades.<\/p>\n<p>As\u00ed pues, Emagister no es el encargado de impartir ning\u00fan tipo de curso, adem\u00e1s <strong>no cobra<\/strong> por prestar informaci\u00f3n ya que creemos que es una de las bases m\u00e1s importantes de nuestro negocio, el mantener bien informados a todos aquellos interesados en comenzar unos estudios. <strong>Tampoco somos educadores<\/strong> ni ofrecemos clases formativas propias, y <strong>no estamos vinculados con el centro \u201cmagister\u201d<\/strong>.<\/p>\n<h2>Recomendaciones para elegir un curso<\/h2>\n<p>Si est\u00e1s interesado en empezar a estudiar no dudes en averiguar qu\u00e9 <span style=\"text-decoration: underline;\"><strong>modalidades<\/strong><\/span> existen para tu b\u00fasqueda y qu\u00e9 diferencias podr\u00edas encontrar con cada una de ellas respecto a las otras. Es importante saber si tienen plataforma <em>online<\/em> y tutor a distancia aquellas que se imparten mediante estas modalidades; y en qu\u00e9 ciudad puedes encontrar las presenciales\/semipresenciales.<\/p>\n<p>Otro de los puntos relevantes son las <span style=\"text-decoration: underline;\"><strong>opiniones<\/strong><\/span> de antiguos alumnos, ya que a trav\u00e9s de ellas podr\u00e1s verificar la experiencia de antiguos alumnos y coger confianza a trav\u00e9s de los comentarios y puntuaciones en la parte baja de la p\u00e1gina.<\/p>\n<p>Ten siempre en cuenta el comparador de precios, la relaci\u00f3n <strong><span style=\"text-decoration: underline;\">calidad-precio<\/span><\/strong> es un punto fundamental.<\/p>\n<p>Nunca te quedes con ninguna duda acerca de tu b\u00fasqueda, aunque creas que alguna pregunta no pueda ser tan importante, siempre resu\u00e9lvela, llama al <strong><span style=\"text-decoration: underline;\">asesor<\/span><\/strong>, y te aconsejar\u00e1 lo mejor para ti de manera gratuita.<\/p>\n<h2>Asesor<\/h2>\n<p>Si has llegado a la p\u00e1gina que estabas buscando, comprobar\u00e1s que tienes mucha informaci\u00f3n a cerca de la formaci\u00f3n que hayas elegido pero si necesitas un poco m\u00e1s de contenido siempre puedes ponerte en contacto con el <strong>asesor educativo<\/strong> pidiendo m\u00e1s informaci\u00f3n y resolviendo todas las dudas que te hayan surgido.<\/p>\n<p>Cuando contactes con el asesor educativo no dudes en aprovechar la ocasi\u00f3n para resolver todo aquello que necesites saber ya que estar\u00e1 100% a tu disponibilidad. Siempre es importante saber <strong>preguntas claves<\/strong> como si el curso es homologado o no, qu\u00e9 modalidades existen para tal, si tiene validez en el extranjero o si te permite ejercer profesionalmente. Estas son algunas pistas que os dejamos para que no perd\u00e1is detalle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-161202 size-full aligncenter\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2024\/04\/imagen-logo-emagister.png\" alt=\"\" width=\"290\" height=\"90\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2024\/04\/imagen-logo-emagister.png 290w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2024\/04\/imagen-logo-emagister-80x25.png 80w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/p>\n<h2>Te formamos y te informamos<\/h2>\n<p>Adem\u00e1s de ofrecerte toda la formaci\u00f3n, tenemos un <strong><a href=\"https:\/\/www.emagister.com\/blog\/\">blog<\/a> <\/strong>en el que publicamos constantemente <em>posts<\/em> de gran utilidad, tanto nuestros como de los centros que trabajan con nosotros. En \u00e9l te contamos las \u00faltimas novedades dentro del mundo de la formaci\u00f3n, as\u00ed como de todo lo que necesitas saber antes de elegir un curso u otro: diferencias entre la educaci\u00f3n p\u00fablica y privada, informaci\u00f3n sobre plazos de admisi\u00f3n, precios de las universidades, calendarios acad\u00e9micos, cambios de legislaci\u00f3n, \u00a1y mucho m\u00e1s!<\/p>\n<p>Ahora que ya nos conoces, \u00bfa qu\u00e9 esperas para ser parte de nuestra comunidad? \u00a1Entra en Emagister y encuentra tu formaci\u00f3n ideal!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQuieres estudiar pero no sabes qu\u00e9, d\u00f3nde, c\u00f3mo ni a qu\u00e9 precio? Bienvenido a Emagister, donde la formaci\u00f3n se vuelve &#8230; <a title=\"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/\" aria-label=\"M\u00e1s en \u00bfQu\u00e9 es y qu\u00e9 no es Emagister?\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":99055,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[8336],"tags":[],"class_list":["post-99053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"\u00a1Descubre toda nuestra oferta formativa!","link_faldon":"https:\/\/www.emagister.com\/pagina\/acerca-de","link_texto_faldon":"","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"publication","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"link_button_faldon":"","bannerid1":"","bannerid2":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfQu\u00e9 es y qu\u00e9 no es Emagister? - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres estudiar pero no sabes qu\u00e9, d\u00f3nde, c\u00f3mo ni a qu\u00e9 precio? Bienvenido a Emagister, donde la formaci\u00f3n se vuelve ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-23T16:01:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T11:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?\",\"datePublished\":\"2020-01-23T16:01:41+00:00\",\"dateModified\":\"2024-04-17T11:01:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/\"},\"wordCount\":880,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ciudad_libros_2-e1579795086974.jpg\",\"articleSection\":[\"Actualidad Emagister\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/\",\"name\":\"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister? - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ciudad_libros_2-e1579795086974.jpg\",\"datePublished\":\"2020-01-23T16:01:41+00:00\",\"dateModified\":\"2024-04-17T11:01:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ciudad_libros_2-e1579795086974.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ciudad_libros_2-e1579795086974.jpg\",\"width\":1200,\"height\":900,\"caption\":\"qu\u00e9 es y qu\u00e9 no es emagister\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-que-no-es-emagister\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualidad Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister? - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?","og_description":"\u00bfQuieres estudiar pero no sabes qu\u00e9, d\u00f3nde, c\u00f3mo ni a qu\u00e9 precio? Bienvenido a Emagister, donde la formaci\u00f3n se vuelve ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-01-23T16:01:41+00:00","article_modified_time":"2024-04-17T11:01:59+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg","type":"image\/jpeg"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?","datePublished":"2020-01-23T16:01:41+00:00","dateModified":"2024-04-17T11:01:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/"},"wordCount":880,"commentCount":4,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg","articleSection":["Actualidad Emagister"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/","url":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/","name":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister? - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg","datePublished":"2020-01-23T16:01:41+00:00","dateModified":"2024-04-17T11:01:59+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/01\/ciudad_libros_2-e1579795086974.jpg","width":1200,"height":900,"caption":"qu\u00e9 es y qu\u00e9 no es emagister"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-que-no-es-emagister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Actualidad Emagister","item":"https:\/\/www.emagister.com\/blog\/noticias\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 es y qu\u00e9 no es Emagister?"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=99053"}],"version-history":[{"count":4,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99053\/revisions"}],"predecessor-version":[{"id":161203,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99053\/revisions\/161203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/99055"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=99053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=99053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=99053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}