{"id":99923,"date":"2020-07-10T07:58:39","date_gmt":"2020-07-10T05:58:39","guid":{"rendered":"https:\/\/www.emagister.com\/blog\/?p=99923"},"modified":"2021-05-21T13:59:28","modified_gmt":"2021-05-21T11:59:28","slug":"que-es-y-como-actua-la-magnetoterapia","status":"publish","type":"post","link":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/","title":{"rendered":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La&nbsp;<\/span><strong>magnetoterapia&nbsp;<\/strong><span style=\"font-weight: 400;\">comprende pr\u00e1cticas tan sencillas como la utilizaci\u00f3n de pulseras magnetizadas o el uso de colchones magnetizados. Incluso esta terapia puede comprometer grandes m\u00e1quinas creadoras de campos magn\u00e9ticos. Hay distintas teor\u00edas sobre el efecto de los imanes, pero b\u00e1sicamente estos act\u00faan sobre las mol\u00e9culas y iones del cuerpo para mejorar ciertas patolog\u00edas. Sigue leyendo para saber m\u00e1s alrededor de este asunto.<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es la magnetoterapia?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Tambi\u00e9n se puede denominar&nbsp;<\/span><b>terapia de campo magn\u00e9tico<\/b><span style=\"font-weight: 400;\">&nbsp;y&nbsp;<\/span><b>terapia de bioenerg\u00eda<\/b><span style=\"font-weight: 400;\">. Se trata de una terapia alternativa que se suministra de imanes est\u00e1ticos (es decir, inm\u00f3viles) de distintos tama\u00f1os y fuerzas. Estos se colocan en el cuerpo para mitigar el dolor y tratar dolencias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los imanes met\u00e1licos delgados se enganchan al cuerpo solos o en grupos. Se pueden utilizar como pulseras o collares, unidos a parches adhesivos para mantenerlos en su sitio. Tambi\u00e9n se pueden colocar en bandas o cinturones para dejarlos alrededor de la mu\u00f1eca, el codo, la rodilla, el tobillo, el pie, la cintura o la espalda baja. Adem\u00e1s, est\u00e1n disponibles plantillas magn\u00e9ticas, mantas y almohadillas para dormir.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Estos imanes se pueden usar \u00fanicamente unos minutos o por semanas, dependiendo de la condici\u00f3n a tratar. Los campos magn\u00e9ticos generados desde el polo negativo del im\u00e1n tienen poderes sanatorios. Esto es debido a que estimulan el metabolismo, incrementan la cantidad de ox\u00edgeno disponible para las c\u00e9lulas y crean un ambiente menos \u00e1cido dentro del cuerpo.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 modelos de magnetoterapia existen?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se pueden diferenciar tres tipos de terapias; est\u00e1tica, electomagn\u00e9tica y con acupuntura:<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Terapia de campo magn\u00e9tico est\u00e1tico<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Se pone un im\u00e1n sobre la piel de alguna manera. Se puede utilizar una pulsera magn\u00e9tica u otras joyas magnetizadas. Puede ser una venda con un im\u00e1n o puede usar un im\u00e1n como plantilla de zapato. Tambi\u00e9n se puede dormir en un colch\u00f3n especial con un im\u00e1n.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Terapia magn\u00e9tica con carga el\u00e9ctrica (terapia electromagn\u00e9tica)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los imanes que se usan en estos tratamientos poseen una carga el\u00e9ctrica. El tratamiento con&nbsp;<\/span><b>terapia electromagn\u00e9tica<\/b><span style=\"font-weight: 400;\">&nbsp;generalmente viene mediante un pulso el\u00e9ctrico.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Terapia magn\u00e9tica con acupuntura<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los imanes van en las mismas secciones de la piel en las que un acupunturista probablemente se centrar\u00eda en una sesi\u00f3n de acupuntura. Es probable que se reconozcan estas \u00e1reas como v\u00edas o canales de energ\u00eda.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfC\u00f3mo funciona?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El cuerpo tiene, l\u00f3gicamente, campos magn\u00e9ticos y el\u00e9ctricos. Todas las mol\u00e9culas poseen una peque\u00f1a cantidad de energ\u00eda magn\u00e9tica en ellas. La<\/span><b>&nbsp;terapia de campo magn\u00e9tico&nbsp;<\/b><span style=\"font-weight: 400;\">afirma que algunos problemas ocurren porque los campos magn\u00e9ticos no est\u00e1n en armon\u00eda. Colocando un campo magn\u00e9tico cerca de un cuerpo de manera correcta, se puede hacer que vuelvan a la normalidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los iones como el calcio y el potasio ayudan a las c\u00e9lulas a enviar indicios. En las pruebas, los cient\u00edficos han comprobado c\u00f3mo los imanes cambian la manera en que act\u00faan estos iones. No obstante, hasta ahora, no hay certeza de que los imanes tengan el mismo efecto en las c\u00e9lulas que cuando se encuentran en el cuerpo.<a href=\"https:\/\/www.emagister.com\/instituto-dyn-cursos-176987-centrodetalles.htm\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-96726 size-full\" src=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/dyn.png\" alt=\"\" width=\"220\" height=\"147\" srcset=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/dyn.png 220w, https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2019\/11\/dyn-80x53.png 80w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 efecto genera?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los resultados principales y m\u00e1s importantes que genera esta terapia son: efectos curativos y analg\u00e9sicos. Los efectos de la&nbsp;<\/span><b>magnetoterapia&nbsp;<\/b><span style=\"font-weight: 400;\">se detectan r\u00e1pidamente y desde la tercera sesi\u00f3n la curaci\u00f3n est\u00e1 casi lista. No obstante, los resultados dependen del deterioro del \u00e1rea del cuerpo a causa de la edad o la disfunci\u00f3n padecida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A causa de la velocidad y efectividad de las sesiones de&nbsp;<\/span><b>magnetoterapia<\/b><span style=\"font-weight: 400;\">, muchos atletas se han decantado por este tipo de tratamiento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Por ejemplo, Valentino Rossi y Jorge Lorenzo han utilizado el biomagnetismo para acelerar sus recuperaciones, sobre todo despu\u00e9s de una ca\u00edda. Tambi\u00e9n, Rafa Nadal se ha decantado por la&nbsp;<\/span><b>magnetoterapia&nbsp;<\/b><span style=\"font-weight: 400;\">como uno de los sistemas para tratar las lesiones. Hay futbolistas como Roberto Soldado o David Villa que lo han usado y han regenerado tejidos y agilizado la recuperaci\u00f3n \u00f3sea con estos imanes m\u00e9dicos.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Beneficios y aplicaciones de la magnetoterapia<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Estos son los principales&nbsp;<\/span><b>beneficios de la magnetoterapia<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Act\u00faa como un mitigante para el dolor.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Agiliza el&nbsp;proceso de curaci\u00f3n en comparaci\u00f3n con otros m\u00e9todos m\u00e9dicos.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ayuda a renovar las c\u00e9lulas del cuerpo humano.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Reduce la inflamaci\u00f3n en los m\u00fasculos y en distintas partes del cuerpo.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Disminuye la artritis, ralentiza la dolencia.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Es un tratamiento poco agresivo para el cuerpo.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Es indoloro.<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ayuda a agilizar el proceso de curaci\u00f3n de fracturas \u00f3seas.<\/span><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfD\u00f3nde act\u00faa?<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Este m\u00e9todo m\u00e9dico act\u00faa en distintas partes del cuerpo como: huesos, m\u00fasculos, articulaciones y en el sistema nervioso y circulatorio.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfPara qu\u00e9 se usa la terapia magn\u00e9tica?<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La mayor\u00eda de los usos de esta terapia son para tratamientos con distintos tipos de dolor, como en los pies y la espalda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Los cient\u00edficos han estudiado concretamente su uso para: dolor de artritis, cicatrizaci\u00f3n de heridas, insomnio, dolores de cabeza, trastornos circulatorios, dolor de fibromialgia, etc.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Contraindicaciones y efectos desfavorables<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La&nbsp;<\/span><b>magnetoterapia&nbsp;<\/b><span style=\"font-weight: 400;\">no tiene ning\u00fan efecto secundario en el cuerpo del paciente. Esto es debido a que la energ\u00eda de los imanes es muy d\u00e9bil para da\u00f1ar los tejidos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En general, para la mayor\u00eda de las personas usar imanes est\u00e1ticos de baja intensidad es un m\u00e9todo seguro. No obstante, no es una buena idea recibir terapia de campo magn\u00e9tico en los siguientes casos: si se usa un marcapasos, si se est\u00e1 recibiendo quimioterapia, si se tiene una bomba de insulina o si se est\u00e1 embarazada. No se recomienda su uso combinado con la quimioterapia porque debilita en gran medida el cuerpo. Eso hace que no se puedan recobrar los tejidos da\u00f1ados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Las pulseras, collares u otros dispositivos magn\u00e9ticos deben separarse del cuerpo antes de hacerse una radiograf\u00eda o una resonancia magn\u00e9tica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Algunas personas que reciben<\/span><b>&nbsp;terapia de campo magn\u00e9tico<\/b><span style=\"font-weight: 400;\"> producen efectos secundarios como: dolores, nauseas o mareos. No obstante, estos efectos secundarios son muy excepcionales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El \u00fanico elemento no beneficioso para el cuerpo que puede encontrarse en este m\u00e9todo es la ausencia de resultados en algunos casos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En resumen, el logro de la influencia de la&nbsp;<\/span><b>magnetoterapia&nbsp;<\/b><span style=\"font-weight: 400;\">es muy diverso. La gran ventaja de este tipo de tratamiento es su intensidad. Esta facilita que las m\u00e1quinas utilizadas puedan contrarrestar las enfermedades sin da\u00f1ar de ninguna manera al organismo. Su aplicaci\u00f3n contribuye a la sanaci\u00f3n de un simple dolor en el dedo anular hasta problemas de asma, bronquitis o depresi\u00f3n, por lo que hay pocas dolencias que un entendido en en esta terapia no pueda tratar.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfTe has hecho la idea del <a href=\"https:\/\/www.emagister.com\/cursos-instituto-dyn-cen-176987.htm\" target=\"_blank\" rel=\"noopener\">cat\u00e1logo formativo<\/a> que ofrece el INSTITUTO DYN<\/span><span style=\"font-weight: 400;\">? Consulta en<\/span> <a href=\"https:\/\/www.emagister.com\/contact\/student\" target=\"_blank\" rel=\"noopener\"><b>Emagister<\/b><\/a><span style=\"font-weight: 400;\"> todo aquello que no tengas claro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00bfTe has formado en INSTITUTO DYN<\/span><span style=\"font-weight: 400;\">?<\/span><span style=\"font-weight: 400;\">, \u00a1deja tu opini\u00f3n en este&nbsp;<\/span><a href=\"https:\/\/www.emagister.com\/reviews\/add\" target=\"_blank\" rel=\"noopener\"><b>formulario<\/b><\/a><span style=\"font-weight: 400;\">!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;magnetoterapia&nbsp;comprende pr\u00e1cticas tan sencillas como la utilizaci\u00f3n de pulseras magnetizadas o el uso de colchones magnetizados. Incluso esta terapia puede &#8230; <a title=\"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia\" class=\"read-more\" href=\"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/\" aria-label=\"M\u00e1s en Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":285,"featured_media":99924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[785],"tags":[2832,3265,5849,5850,10142],"class_list":["post-99923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestros-clientes","tag-noticias-de-centros-de-formacion","tag-centros-de-formacion","tag-5849","tag-instituto-dyn","tag-noticiaslavanguardia","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-25"],"acf":{"mostrar_faldon":"-1","texto_faldon":"Toda la formaci\u00f3n sobre INSTITUTO DYN","link_faldon":"https:\/\/www.emagister.com\/instituto-dyn-cursos-176987-centrodetalles.htm","link_texto_faldon":"La magnetoterapia, caracter\u00edsticas y funciones","hreflang":[{"url":""}],"estilo_titulo":"","fecha":"no","noticiasElPais":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""},"noticiasLaVanguardia":{"custom_snippet_image":false,"custom_snippet_title":"","custom_snippet_description":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia - Blog Emagister<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia\" \/>\n<meta property=\"og:description\" content=\"La&nbsp;magnetoterapia&nbsp;comprende pr\u00e1cticas tan sencillas como la utilizaci\u00f3n de pulseras magnetizadas o el uso de colchones magnetizados. Incluso esta terapia puede ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Emagister\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Emagister\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T05:58:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T11:59:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1418\" \/>\n\t<meta property=\"og:image:height\" content=\"944\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Blog Emagister\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@emagister\" \/>\n<meta name=\"twitter:site\" content=\"@emagister\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Blog Emagister\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/\"},\"author\":{\"name\":\"Blog Emagister\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\"},\"headline\":\"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia\",\"datePublished\":\"2020-07-10T05:58:39+00:00\",\"dateModified\":\"2021-05-21T11:59:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/\"},\"wordCount\":1228,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Magnetoterapia.png\",\"keywords\":[\"Noticias de centros de formaci\u00f3n\",\"Centros de formaci\u00f3n\",\"99997192958079401036578245562648\",\"INSTITUTO DYN\",\"noticiasLaVanguardia\"],\"articleSection\":[\"Nuestros clientes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/\",\"name\":\"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia - Blog Emagister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Magnetoterapia.png\",\"datePublished\":\"2020-07-10T05:58:39+00:00\",\"dateModified\":\"2021-05-21T11:59:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Magnetoterapia.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Magnetoterapia.png\",\"width\":1418,\"height\":944},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/que-es-y-como-actua-la-magnetoterapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog Emagister\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestros clientes\",\"item\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/nuestros-clientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"name\":\"Blog Emagister\",\"description\":\"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#organization\",\"name\":\"Emagister\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"contentUrl\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/photo.png\",\"width\":120,\"height\":120,\"caption\":\"Emagister\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Emagister\\\/\",\"https:\\\/\\\/x.com\\\/emagister\",\"https:\\\/\\\/www.instagram.com\\\/emagister\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emagister-com\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/emagister\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/emagister\\\/\",\"https:\\\/\\\/es.wikipedia.org\\\/wiki\\\/Emagister\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/#\\\/schema\\\/person\\\/776af158d79a20bccf84defca072a501\",\"name\":\"Blog Emagister\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g\",\"caption\":\"Blog Emagister\"},\"url\":\"https:\\\/\\\/www.emagister.com\\\/blog\\\/author\\\/blog-emagister\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia - Blog Emagister","robots":{"index":"index","follow":"follow"},"canonical":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia","og_description":"La&nbsp;magnetoterapia&nbsp;comprende pr\u00e1cticas tan sencillas como la utilizaci\u00f3n de pulseras magnetizadas o el uso de colchones magnetizados. Incluso esta terapia puede ... Leer m\u00e1s","og_url":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/","og_site_name":"Blog Emagister","article_publisher":"https:\/\/www.facebook.com\/Emagister\/","article_published_time":"2020-07-10T05:58:39+00:00","article_modified_time":"2021-05-21T11:59:28+00:00","og_image":[{"width":1418,"height":944,"url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png","type":"image\/png"}],"author":"Blog Emagister","twitter_card":"summary_large_image","twitter_creator":"@emagister","twitter_site":"@emagister","twitter_misc":{"Escrito por":"Blog Emagister","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#article","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/"},"author":{"name":"Blog Emagister","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501"},"headline":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia","datePublished":"2020-07-10T05:58:39+00:00","dateModified":"2021-05-21T11:59:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/"},"wordCount":1228,"commentCount":1,"publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png","keywords":["Noticias de centros de formaci\u00f3n","Centros de formaci\u00f3n","99997192958079401036578245562648","INSTITUTO DYN","noticiasLaVanguardia"],"articleSection":["Nuestros clientes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/","url":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/","name":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia - Blog Emagister","isPartOf":{"@id":"https:\/\/www.emagister.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#primaryimage"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png","datePublished":"2020-07-10T05:58:39+00:00","dateModified":"2021-05-21T11:59:28+00:00","breadcrumb":{"@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#primaryimage","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2020\/02\/Magnetoterapia.png","width":1418,"height":944},{"@type":"BreadcrumbList","@id":"https:\/\/www.emagister.com\/blog\/que-es-y-como-actua-la-magnetoterapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog Emagister","item":"https:\/\/www.emagister.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuestros clientes","item":"https:\/\/www.emagister.com\/blog\/nuestros-clientes\/"},{"@type":"ListItem","position":3,"name":"Qu\u00e9 es y c\u00f3mo act\u00faa la magnetoterapia"}]},{"@type":"WebSite","@id":"https:\/\/www.emagister.com\/blog\/#website","url":"https:\/\/www.emagister.com\/blog\/","name":"Blog Emagister","description":"Gu\u00eda de orientaci\u00f3n sobre estudios y tendencias de formaci\u00f3n","publisher":{"@id":"https:\/\/www.emagister.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emagister.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.emagister.com\/blog\/#organization","name":"Emagister","url":"https:\/\/www.emagister.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","contentUrl":"https:\/\/www.emagister.com\/blog\/wp-content\/uploads\/2017\/02\/photo.png","width":120,"height":120,"caption":"Emagister"},"image":{"@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Emagister\/","https:\/\/x.com\/emagister","https:\/\/www.instagram.com\/emagister\/","https:\/\/www.linkedin.com\/company\/emagister-com\/","https:\/\/www.pinterest.es\/emagister\/","https:\/\/www.youtube.com\/user\/emagister\/","https:\/\/es.wikipedia.org\/wiki\/Emagister"]},{"@type":"Person","@id":"https:\/\/www.emagister.com\/blog\/#\/schema\/person\/776af158d79a20bccf84defca072a501","name":"Blog Emagister","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44dc9fc526e06eb47a16c88f9b66a081ab656cfa8d8ad442778aa78886bdaff1?s=96&r=g","caption":"Blog Emagister"},"url":"https:\/\/www.emagister.com\/blog\/author\/blog-emagister\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/users\/285"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/comments?post=99923"}],"version-history":[{"count":2,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99923\/revisions"}],"predecessor-version":[{"id":128469,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/posts\/99923\/revisions\/128469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media\/99924"}],"wp:attachment":[{"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/media?parent=99923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/categories?post=99923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emagister.com\/blog\/wp-json\/wp\/v2\/tags?post=99923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}